{"id":159077,"date":"2025-06-23T11:39:54","date_gmt":"2025-06-23T09:39:54","guid":{"rendered":"https:\/\/xometry.eu\/e-procurement-system\/"},"modified":"2026-02-04T15:03:43","modified_gmt":"2026-02-04T13:03:43","slug":"integracao-e-procurement","status":"publish","type":"page","link":"https:\/\/xometry.eu\/pt\/integracao-e-procurement\/","title":{"rendered":"Integra\u00e7\u00e3o e-procurement"},"content":{"rendered":"<section class=\"hero  light light-to-dark-gradient printing-3d-page\" >\r\n            <div class=\"hero__container section container\" style=\"padding-bottom: px;\">\r\n        <div class=\"hero__title-wrapper\">\r\n            <h1 class=\"title title--01\">Integre a Xometry Diretamente no Seu <strong>Sistema de E-Procurement<\/strong><\/h1>\r\n            <div><p>Torne o processo de compra de pe\u00e7as feitas \u00e0 medida mais r\u00e1pido e mais f\u00e1cil atrav\u00e9s de uma integra\u00e7\u00e3o completa no workflow de aprovisionamento da sua empresa. Esta integra\u00e7\u00e3o simplifica o processo de aquisi\u00e7\u00e3o ao permitir que a sua equipa realize todas as etapas diretamente na Xometry e depois transfira a encomenda de forma integrada para o seu sistema de e-procurement ou ERP. Isto sem necessidade de carregar ou voltar a introduzir dados entre plataformas, sem passos manuais nem processos duplicados.<\/p>\n<\/div>\r\n                        <div class=\"hero__advantages-list\">\r\n                                    <div class=\"hero__advantages-item\">\r\n                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/service.svg\" alt=\"Workflows de compra e fatura\u00e7\u00e3o automatizados com zero passos manuais\">\r\n                        <p>Workflows de compra e fatura\u00e7\u00e3o automatizados com zero passos manuais<\/p>\r\n                    <\/div>\r\n                                    <div class=\"hero__advantages-item\">\r\n                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/broken-link.svg\" alt=\"Integra\u00e7\u00e3o sem complica\u00e7\u00f5es com o SAP Ariba, Coupa, Microsoft Dynamics, etc.\">\r\n                        <p>Integra\u00e7\u00e3o sem complica\u00e7\u00f5es com o SAP Ariba, Coupa, Microsoft Dynamics, etc.<\/p>\r\n                    <\/div>\r\n                                    <div class=\"hero__advantages-item\">\r\n                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/timer.svg\" alt=\"Fa\u00e7a a integra\u00e7\u00e3o em dias com total suporte inform\u00e1tico e de aprovisionamento\">\r\n                        <p>Fa\u00e7a a integra\u00e7\u00e3o em dias com total suporte inform\u00e1tico e de aprovisionamento<\/p>\r\n                    <\/div>\r\n                            <\/div>\r\n                    <\/div>\r\n        <div class=\"hero__cards-list\">\r\n              \r\n    <a href=\"https:\/\/calendly.com\/xometryeu\/demo-e-procurement-integration\" class=\"hero__cards-item card \">\r\n        <h3 class=\"title title--03\">Entre em Contacto Para Saber Mais<\/h3>\r\n        <div class=\"hero__cards-item-text \"><p>Discuta os detalhes e os requisitos do projeto de integra\u00e7\u00e3o com os nossos gestores de conta e equipa de integra\u00e7\u00e3o de produto.<\/p>\n<\/div>\r\n        <span class=\"btn btn--primary btn_wide\">Agende uma Chamada com a Nossa Equipa<\/span>\r\n            <\/a>\r\n        <\/div>\r\n            <\/div>\r\n<\/section>\n\n<section class=\"brands-slider  light blue-10\">\r\n    <div class=\"container\">\r\n        <div class=\"hero__brands-slider-wrapper\">\r\n            <p>Temos a Confian\u00e7a de Mais de 85.000 Profissionais de Aprovisionamento e Engenheiros em Todo o Mundo<\/p>\r\n            <div class=\"hero__brands-slider slider-mode\">\r\n                <div class=\"swiper-wrapper\">\r\n                                                                                        <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/bosch-logo-monochrome.svg\" alt=\"Bosch\" style='height:38px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2022\/01\/bosch-logo.svg\" alt=\"Bosch\" style='height:38px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <a class=\"swiper-slide brands-slider__item\" href=\"https:\/\/xometry.eu\/en\/case-studies\/hybrid-marine-engines\/\" target=\"_blank\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/hybrid-marine-logo-monochrome.png\" alt=\"Hybrid Marine\" style='height:38px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/hybrid-marine-logo.png\" alt=\"Hybrid Marine\" style='height:38px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                            <div class=\"brands-slider__item-tooltip-wrapper\">\r\n                                            <button type=\"button\" aria-label=\"Open brand tooltip\" class=\"brands-slider__item-tooltip-opener\">\r\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"24\" viewBox=\"0 0 25 24\" fill=\"none\">\r\n                                                <path d=\"M12.6001 1.5C6.80166 1.5 2.1001 6.20156 2.1001 12C2.1001 17.7984 6.80166 22.5 12.6001 22.5C18.3985 22.5 23.1001 17.7984 23.1001 12C23.1001 6.20156 18.3985 1.5 12.6001 1.5ZM12.6001 20.7188C7.78604 20.7188 3.88135 16.8141 3.88135 12C3.88135 7.18594 7.78604 3.28125 12.6001 3.28125C17.4142 3.28125 21.3188 7.18594 21.3188 12C21.3188 16.8141 17.4142 20.7188 12.6001 20.7188Z\"\/>\r\n                                                <path d=\"M11.4751 7.875C11.4751 8.17337 11.5936 8.45952 11.8046 8.6705C12.0156 8.88147 12.3017 9 12.6001 9C12.8985 9 13.1846 8.88147 13.3956 8.6705C13.6066 8.45952 13.7251 8.17337 13.7251 7.875C13.7251 7.57663 13.6066 7.29048 13.3956 7.0795C13.1846 6.86853 12.8985 6.75 12.6001 6.75C12.3017 6.75 12.0156 6.86853 11.8046 7.0795C11.5936 7.29048 11.4751 7.57663 11.4751 7.875ZM13.1626 10.5H12.0376C11.9345 10.5 11.8501 10.5844 11.8501 10.6875V17.0625C11.8501 17.1656 11.9345 17.25 12.0376 17.25H13.1626C13.2657 17.25 13.3501 17.1656 13.3501 17.0625V10.6875C13.3501 10.5844 13.2657 10.5 13.1626 10.5Z\"\/>\r\n                                            <\/svg>\r\n                                            <\/button>\r\n                            \r\n                                            <div class=\"brands-slider__item-tooltip\">\r\n                                                <p class=\"brands-slider__item-tooltip-text\">Hybrid Engines for the Marine Industry Produced Faster With on-demand Manufacturing<\/p>\r\n                                                                                                    <div class=\"btn btn--primary brands-slider__item-tooltip-btn\">\r\n                                                        Read Story                                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\">\r\n                                                        <path d=\"M11.8047 11.8047C11.5444 12.065 11.1227 12.0649 10.8624 11.8047C10.602 11.5444 10.602 11.1226 10.8624 10.8623L13.0577 8.66702L1.33305 8.66702C0.965021 8.66686 0.667052 8.3681 0.667038 8.00003C0.667038 7.63195 0.965014 7.3332 1.33305 7.33304L13.0577 7.33304L10.8624 5.13773C10.602 4.87737 10.602 4.45565 10.8624 4.19534C10.9924 4.06535 11.1626 4.00011 11.3331 4.00003C11.5037 4.00003 11.6746 4.06517 11.8047 4.19534L15.1377 7.52835C15.3981 7.78871 15.3981 8.2114 15.1377 8.47171L11.8047 11.8047Z\" fill=\"white\"\/>\r\n                                                        <\/svg>\r\n                                                    <\/div>\r\n                                                                                            <\/div>\r\n                                        <\/div>\r\n                                                                                                        <\/a>\r\n                                                                                                                                    <a class=\"swiper-slide brands-slider__item\" href=\"https:\/\/xometry.eu\/en\/case-studies\/pembleton-cycle-cars\/\" target=\"_blank\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/10\/pembleton-logo-monochrome.png\" alt=\"Pembleton\" style='height:44px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/10\/pembleton-logo.png\" alt=\"Pembleton\" style='height:44px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                            <div class=\"brands-slider__item-tooltip-wrapper\">\r\n                                            <button type=\"button\" aria-label=\"Open brand tooltip\" class=\"brands-slider__item-tooltip-opener\">\r\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"24\" viewBox=\"0 0 25 24\" fill=\"none\">\r\n                                                <path d=\"M12.6001 1.5C6.80166 1.5 2.1001 6.20156 2.1001 12C2.1001 17.7984 6.80166 22.5 12.6001 22.5C18.3985 22.5 23.1001 17.7984 23.1001 12C23.1001 6.20156 18.3985 1.5 12.6001 1.5ZM12.6001 20.7188C7.78604 20.7188 3.88135 16.8141 3.88135 12C3.88135 7.18594 7.78604 3.28125 12.6001 3.28125C17.4142 3.28125 21.3188 7.18594 21.3188 12C21.3188 16.8141 17.4142 20.7188 12.6001 20.7188Z\"\/>\r\n                                                <path d=\"M11.4751 7.875C11.4751 8.17337 11.5936 8.45952 11.8046 8.6705C12.0156 8.88147 12.3017 9 12.6001 9C12.8985 9 13.1846 8.88147 13.3956 8.6705C13.6066 8.45952 13.7251 8.17337 13.7251 7.875C13.7251 7.57663 13.6066 7.29048 13.3956 7.0795C13.1846 6.86853 12.8985 6.75 12.6001 6.75C12.3017 6.75 12.0156 6.86853 11.8046 7.0795C11.5936 7.29048 11.4751 7.57663 11.4751 7.875ZM13.1626 10.5H12.0376C11.9345 10.5 11.8501 10.5844 11.8501 10.6875V17.0625C11.8501 17.1656 11.9345 17.25 12.0376 17.25H13.1626C13.2657 17.25 13.3501 17.1656 13.3501 17.0625V10.6875C13.3501 10.5844 13.2657 10.5 13.1626 10.5Z\"\/>\r\n                                            <\/svg>\r\n                                            <\/button>\r\n                            \r\n                                            <div class=\"brands-slider__item-tooltip\">\r\n                                                <p class=\"brands-slider__item-tooltip-text\">Pembleton: Meticulously Engineered Cycle Cars Built With On-Demand Manufacturing<\/p>\r\n                                                                                                    <div class=\"btn btn--primary brands-slider__item-tooltip-btn\">\r\n                                                        Read Story                                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\">\r\n                                                        <path d=\"M11.8047 11.8047C11.5444 12.065 11.1227 12.0649 10.8624 11.8047C10.602 11.5444 10.602 11.1226 10.8624 10.8623L13.0577 8.66702L1.33305 8.66702C0.965021 8.66686 0.667052 8.3681 0.667038 8.00003C0.667038 7.63195 0.965014 7.3332 1.33305 7.33304L13.0577 7.33304L10.8624 5.13773C10.602 4.87737 10.602 4.45565 10.8624 4.19534C10.9924 4.06535 11.1626 4.00011 11.3331 4.00003C11.5037 4.00003 11.6746 4.06517 11.8047 4.19534L15.1377 7.52835C15.3981 7.78871 15.3981 8.2114 15.1377 8.47171L11.8047 11.8047Z\" fill=\"white\"\/>\r\n                                                        <\/svg>\r\n                                                    <\/div>\r\n                                                                                            <\/div>\r\n                                        <\/div>\r\n                                                                                                        <\/a>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/bmw-logo-monochrome.svg\" alt=\"BMW\"  class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/bmw-logo.svg\" alt=\"BMW\"   class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/10\/penlon-logo-monochrome.png\" alt=\"Penlon\" style='height:38px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/10\/penlon-logo.png\" alt=\"Penlon\" style='height:38px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/connectomx-logo-monochrome.png\" alt=\"ConnectomX\" style='height:44px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/connectomx-logo.png\" alt=\"ConnectomX\" style='height:44px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/dell-logo-monochrome.svg\" alt=\"Dell\"  class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/dell-logo.svg\" alt=\"Dell\"   class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/neocean-logo-monochrome.png\" alt=\"Neocean\" style='height:20px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/neocean-logo-1.png\" alt=\"Neocean\" style='height:20px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/ge-logo-monochrome.svg\" alt=\"General Electrics\"  class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/ge-logo.svg\" alt=\"General Electrics\"   class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/belassi-logo-monochrome.png\" alt=\"Belassi\" style='height:28px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/belassi-logo.png\" alt=\"Belassi\" style='height:28px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/10\/scewo-logo-monochrome.png\" alt=\"SCEWO\" style='height:28px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/10\/scewo-logo.png\" alt=\"SCEWO\" style='height:28px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/nasa-logo-monochrome.svg\" alt=\"Nasa\"  class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/nasa-logo.svg\" alt=\"Nasa\"   class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/08\/sncf-logo-monochrome.svg\" alt=\"SNCF\" style='height:38px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/08\/sncf-logo.svg\" alt=\"SNCF\" style='height:38px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                <\/a>\r\n            <\/div>\r\n        <\/div>\r\n            <\/div>\r\n<\/section>\n\n<section class=\"process-slider light blue-10\">\r\n  <div class=\"process-slider__container section container\">\r\n        <div class=\"section__title-wrapper\">\r\n                    <h2 class=\"title title--02\">D\u00ea In\u00edcio Com Apenas Alguns Passos Simples<\/h2>\r\n            <\/div>\r\n    <div class=\"process-slider__slider-wrapper\">\r\n                    <div class=\"process-slider__small-slider\">\r\n                                    <button class=\"process-slider__small-slider-item\">\r\n                        <span class=\"title title--03\">1.<\/span> \r\n                        <h3 class=\"title title--03\">Verifique o Setup Existente<\/h3>\r\n                    <\/button>\r\n                                    <button class=\"process-slider__small-slider-item\">\r\n                        <span class=\"title title--03\">2.<\/span> \r\n                        <h3 class=\"title title--03\">Ponha-nos em Contacto com os Principais Respons\u00e1veis<\/h3>\r\n                    <\/button>\r\n                                    <button class=\"process-slider__small-slider-item\">\r\n                        <span class=\"title title--03\">3.<\/span> \r\n                        <h3 class=\"title title--03\">Fa\u00e7a o Lan\u00e7amento em Dias<\/h3>\r\n                    <\/button>\r\n                \r\n                <div class=\"process-slider__progress\">\r\n                    <div class=\"process-slider__progress-bar\"><\/div>\r\n                <\/div>\r\n            <\/div>\r\n\r\n            <div class=\"process-slider__big-slider\">\r\n                                    <button class=\"process-slider__big-slider-mobile-btn\">\r\n                        <span class=\"title title--03\">1.<\/span> \r\n                        <h3 class=\"title title--03\">Verifique o Setup Existente<\/h3>\r\n                    <\/button>\r\n\r\n                    <div class=\"process-slider__big-slider-item\">\r\n                        <div class=\"process-slider__big-slider-main\">\r\n                            <h3 class=\"title title--04\">Verifique o Setup Existente<\/h3>\r\n                            <div class=\"process-slider__big-slider-text text-l\">\r\n                                <p>Verifique se a sua empresa j\u00e1 usa o PunchOut com outros fornecedores. Isto ajuda a acelerar a configura\u00e7\u00e3o e garante a compatibilidade com o seu sistema de aprovisionamento.<\/p>\n                            <\/div>\r\n                                                    <\/div>\r\n                                                    <div class=\"process-slider__big-slider-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/04\/settings-illustration.svg\" alt=\"Step Image\">\r\n                            <\/div>\r\n                                            <\/div>\r\n                                    <button class=\"process-slider__big-slider-mobile-btn\">\r\n                        <span class=\"title title--03\">2.<\/span> \r\n                        <h3 class=\"title title--03\">Ponha-nos em Contacto com os Principais Respons\u00e1veis<\/h3>\r\n                    <\/button>\r\n\r\n                    <div class=\"process-slider__big-slider-item\">\r\n                        <div class=\"process-slider__big-slider-main\">\r\n                            <h3 class=\"title title--04\">Ponha-nos em Contacto com os Principais Respons\u00e1veis<\/h3>\r\n                            <div class=\"process-slider__big-slider-text text-l\">\r\n                                <p>Apresente-nos ao seu contacto de IT ou aprovisionamento. Os nossos especialistas em integra\u00e7\u00e3o ficar\u00e3o respons\u00e1veis pela configura\u00e7\u00e3o e ir\u00e3o fazer a coordena\u00e7\u00e3o com as nossas equipas internas.<\/p>\n                            <\/div>\r\n                                                    <\/div>\r\n                                                    <div class=\"process-slider__big-slider-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/06\/Layer_1.png\" alt=\"Step Image\">\r\n                            <\/div>\r\n                                            <\/div>\r\n                                    <button class=\"process-slider__big-slider-mobile-btn\">\r\n                        <span class=\"title title--03\">3.<\/span> \r\n                        <h3 class=\"title title--03\">Fa\u00e7a o Lan\u00e7amento em Dias<\/h3>\r\n                    <\/button>\r\n\r\n                    <div class=\"process-slider__big-slider-item\">\r\n                        <div class=\"process-slider__big-slider-main\">\r\n                            <h3 class=\"title title--04\">Fa\u00e7a o Lan\u00e7amento em Dias<\/h3>\r\n                            <div class=\"process-slider__big-slider-text text-l\">\r\n                                <p>Fa\u00e7a o lan\u00e7amento rapidamente com suporte dedicado da nossa equipa. Assim que esteja conectado, as encomendas realizadas com a Xometry s\u00e3o dirigidas para o seu sistema interno para aprova\u00e7\u00e3o e processamento\u2014garantindo consist\u00eancia, reduzindo passos manuais e estando em alinhamento com os seus workflows existentes.<\/p>\n                            <\/div>\r\n                                                    <\/div>\r\n                                                    <div class=\"process-slider__big-slider-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/06\/Group-5512.png\" alt=\"Step Image\">\r\n                            <\/div>\r\n                                            <\/div>\r\n                            <\/div>\r\n            <\/div>\r\n\r\n      <\/div>\r\n<\/section>\n\n <section class=\"advantages light dark-to-light-gradient\">\r\n    <div class=\"advantages__container section container\">\r\n        <h2 class=\"title title--02\">\r\n            PunchOut: Uma Integra\u00e7\u00e3o R\u00e1pida e F\u00e1cil        <\/h2>\r\n        <div class=\"advantages__list\">\r\n                                <div class=\"advantages__item card\">\r\n                        <img decoding=\"async\" class=\"advantages__item-image\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2023\/03\/Home-Icons_02_Quote.svg\" alt=\"Aprovisionamento e Fatura\u00e7\u00e3o Automatizados\"\r\n                        \/>\r\n                        <h4 class=\"title title--04\">Aprovisionamento e Fatura\u00e7\u00e3o Automatizados<\/h4>\r\n                        <div>\r\n                            <p>Elimine processos manuais com ordens de compra totalmente eletr\u00f3nicas e gest\u00e3o de fatura\u00e7\u00e3o. Isto ajuda a tornar as aprova\u00e7\u00f5es mais r\u00e1pidas, a melhorar o rigor dos dados e a reduzir os custos administrativos.<\/p>\n                        <\/div>\r\n                                            <\/div>\r\n                                        <div class=\"advantages__item card\">\r\n                        <img decoding=\"async\" class=\"advantages__item-image\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/Vector-3.svg\" alt=\"Completa Integra\u00e7\u00e3o de Sistemas\"\r\n                        \/>\r\n                        <h4 class=\"title title--04\">Completa Integra\u00e7\u00e3o de Sistemas<\/h4>\r\n                        <div>\r\n                            <p>As equipas conseguem aceder \u00e0 Xometry a partir das ferramentas que j\u00e1 usam\u2014n\u00e3o \u00e9 necess\u00e1rio logins ou software extra. A experi\u00eancia fica completamente integrada no seu ambiente de aprovisionamento j\u00e1 existente.<\/p>\n                        <\/div>\r\n                                            <\/div>\r\n                                        <div class=\"advantages__item card\">\r\n                        <img decoding=\"async\" class=\"advantages__item-image\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/05\/support.svg\" alt=\"Configura\u00e7\u00e3o R\u00e1pida, Escal\u00e1vel Para Outras Equipas\"\r\n                        \/>\r\n                        <h4 class=\"title title--04\">Configura\u00e7\u00e3o R\u00e1pida, Escal\u00e1vel Para Outras Equipas<\/h4>\r\n                        <div>\r\n                            <p>A maioria das integra\u00e7\u00f5es fica funcional em poucos dias. A equipa da Xometry trabalha de perto com os seus respons\u00e1veis de IT e aprovisionamento para garantir uma implementa\u00e7\u00e3o segura, eficiente e f\u00e1cil.<\/p>\n                        <\/div>\r\n                                            <\/div>\r\n                            <\/div>\r\n            <\/div>\r\n<\/section>\n\n\r\n<section class=\"final-cta dark dark-blue-100\" >\r\n    <div class=\"final-cta__container section container\">\r\n        <h2 class=\"title title--02\">Envolva a Xometry no Seu Workflow<\/h2>\r\n        <div class=\"hero__cards-list\">\r\n              \r\n    <a href=\"https:\/\/calendly.com\/xometryeu\/demo-e-procurement-integration\" class=\"hero__cards-item card \">\r\n        <h3 class=\"title title--03\"><\/h3>\r\n        <div class=\"hero__cards-item-text \"><p>Fale com o seu gestor de conta ou contacte a nossa equipa para pedir uma demo e ver como a Xometry se integra com a sua plataforma.<\/p>\n<\/div>\r\n        <span class=\"btn btn--primary \">Agende uma Reuni\u00e3o para Saber Mais<\/span>\r\n            <\/a>\r\n        <\/div>\r\n        <div class=\"final-cta__footer-list\">\r\n                            <div class=\"final-cta__footer-item\">\r\n                    <h4 class=\"text-l\">Clientes<\/h4>\r\n                    <div class=\"title title--02 text--semi-bold\">85.000<\/div>\r\n                <\/div>\r\n                                        <div class=\"final-cta__footer-item\">\r\n                    <h4 class=\"text-l\">Pe\u00e7as Cotadas<\/h4>\r\n                    <div class=\"title title--02 text--semi-bold\">Mais de 1 Milh\u00e3o<\/div>\r\n                <\/div>\r\n                                        <div class=\"final-cta__footer-item trustpilot\">\r\n                   <div class=\"trustpilot-widget stat-item\" data-locale=\"pt\" data-template-id=\"53aa8807dec7e10d38f59f32\" data-businessunit-id=\"60b8c942cc8732000134c923\" data-style-height=\"100%\" data-style-width=\"145px\" data-theme=\"dark\"><a href=\"https:\/\/www.trustpilot.com\/review\/xometry.eu\" target=\"_blank\" rel=\"noopener\">Trustpilot<\/a><\/div>                <\/div>\r\n                    <\/div>\r\n    <\/div>\r\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":178893,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-new-style.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-159077","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.5 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Integre a Xometry Diretamente no Seu Sistema de E-Procurement | Xometry Europe<\/title>\n<meta name=\"description\" content=\"Acelere e simplifique a compra de pe\u00e7as feitas \u00e0 medida com uma integra\u00e7\u00e3o total no seu workflow de aprovisionamento.\" \/>\n<meta name=\"robots\" content=\"index, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xometry.eu\/pt\/integracao-e-procurement\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Integre a Xometry Diretamente no Seu Sistema de E-Procurement | Xometry Europe\" \/>\n<meta property=\"og:description\" content=\"Acelere e simplifique a compra de pe\u00e7as feitas \u00e0 medida com uma integra\u00e7\u00e3o total no seu workflow de aprovisionamento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xometry.eu\/pt\/integracao-e-procurement\/\" \/>\n<meta property=\"og:site_name\" content=\"Xometry Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T13:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Integra\u00e7\u00e3o e-procurement\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xometry.eu\\\/pt\\\/integracao-e-procurement\\\/\",\"url\":\"https:\\\/\\\/xometry.eu\\\/pt\\\/integracao-e-procurement\\\/\",\"name\":\"Integre a Xometry Diretamente no Seu Sistema de E-Procurement | Xometry Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xometry.eu\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xometry.eu\\\/pt\\\/integracao-e-procurement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xometry.eu\\\/pt\\\/integracao-e-procurement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xometry.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/EN-E-procurement-scaled.jpg\",\"datePublished\":\"2025-06-23T09:39:54+00:00\",\"dateModified\":\"2026-02-04T13:03:43+00:00\",\"description\":\"Acelere e simplifique a compra de pe\u00e7as feitas \u00e0 medida com uma integra\u00e7\u00e3o total no seu workflow de aprovisionamento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xometry.eu\\\/pt\\\/integracao-e-procurement\\\/#breadcrumb\"},\"inLanguage\":\"PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xometry.eu\\\/pt\\\/integracao-e-procurement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"PT\",\"@id\":\"https:\\\/\\\/xometry.eu\\\/pt\\\/integracao-e-procurement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xometry.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/EN-E-procurement-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/xometry.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/EN-E-procurement-scaled.jpg\",\"width\":2560,\"height\":1344},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xometry.eu\\\/pt\\\/integracao-e-procurement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/xometry.eu\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Integra\u00e7\u00e3o e-procurement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xometry.eu\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/xometry.eu\\\/pt\\\/\",\"name\":\"Xometry Europe\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/xometry.eu\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xometry.eu\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"PT\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Integre a Xometry Diretamente no Seu Sistema de E-Procurement | Xometry Europe","description":"Acelere e simplifique a compra de pe\u00e7as feitas \u00e0 medida com uma integra\u00e7\u00e3o total no seu workflow de aprovisionamento.","robots":{"index":"index","follow":"nofollow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xometry.eu\/pt\/integracao-e-procurement\/","og_locale":"pt_PT","og_type":"article","og_title":"Integre a Xometry Diretamente no Seu Sistema de E-Procurement | Xometry Europe","og_description":"Acelere e simplifique a compra de pe\u00e7as feitas \u00e0 medida com uma integra\u00e7\u00e3o total no seu workflow de aprovisionamento.","og_url":"https:\/\/xometry.eu\/pt\/integracao-e-procurement\/","og_site_name":"Xometry Europe","article_modified_time":"2026-02-04T13:03:43+00:00","twitter_card":"summary_large_image","twitter_title":"Integra\u00e7\u00e3o e-procurement","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xometry.eu\/pt\/integracao-e-procurement\/","url":"https:\/\/xometry.eu\/pt\/integracao-e-procurement\/","name":"Integre a Xometry Diretamente no Seu Sistema de E-Procurement | Xometry Europe","isPartOf":{"@id":"https:\/\/xometry.eu\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xometry.eu\/pt\/integracao-e-procurement\/#primaryimage"},"image":{"@id":"https:\/\/xometry.eu\/pt\/integracao-e-procurement\/#primaryimage"},"thumbnailUrl":"https:\/\/xometry.eu\/wp-content\/uploads\/2026\/06\/EN-E-procurement-scaled.jpg","datePublished":"2025-06-23T09:39:54+00:00","dateModified":"2026-02-04T13:03:43+00:00","description":"Acelere e simplifique a compra de pe\u00e7as feitas \u00e0 medida com uma integra\u00e7\u00e3o total no seu workflow de aprovisionamento.","breadcrumb":{"@id":"https:\/\/xometry.eu\/pt\/integracao-e-procurement\/#breadcrumb"},"inLanguage":"PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xometry.eu\/pt\/integracao-e-procurement\/"]}]},{"@type":"ImageObject","inLanguage":"PT","@id":"https:\/\/xometry.eu\/pt\/integracao-e-procurement\/#primaryimage","url":"https:\/\/xometry.eu\/wp-content\/uploads\/2026\/06\/EN-E-procurement-scaled.jpg","contentUrl":"https:\/\/xometry.eu\/wp-content\/uploads\/2026\/06\/EN-E-procurement-scaled.jpg","width":2560,"height":1344},{"@type":"BreadcrumbList","@id":"https:\/\/xometry.eu\/pt\/integracao-e-procurement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/xometry.eu\/pt\/"},{"@type":"ListItem","position":2,"name":"Integra\u00e7\u00e3o e-procurement"}]},{"@type":"WebSite","@id":"https:\/\/xometry.eu\/pt\/#website","url":"https:\/\/xometry.eu\/pt\/","name":"Xometry Europe","description":"","publisher":{"@id":"https:\/\/xometry.eu\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xometry.eu\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"PT"}]}},"_links":{"self":[{"href":"https:\/\/xometry.eu\/pt\/wp-json\/wp\/v2\/pages\/159077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xometry.eu\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xometry.eu\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xometry.eu\/pt\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/xometry.eu\/pt\/wp-json\/wp\/v2\/comments?post=159077"}],"version-history":[{"count":0,"href":"https:\/\/xometry.eu\/pt\/wp-json\/wp\/v2\/pages\/159077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xometry.eu\/pt\/wp-json\/wp\/v2\/media\/178893"}],"wp:attachment":[{"href":"https:\/\/xometry.eu\/pt\/wp-json\/wp\/v2\/media?parent=159077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}