{"id":155638,"date":"2025-03-06T16:24:19","date_gmt":"2025-03-06T14:24:19","guid":{"rendered":"https:\/\/xometry.eu\/injection-moulding\/"},"modified":"2026-07-27T20:03:52","modified_gmt":"2026-07-27T18:03:52","slug":"moulage-par-injection","status":"publish","type":"page","link":"https:\/\/xometry.eu\/fr\/moulage-par-injection\/","title":{"rendered":"Injection plastique"},"content":{"rendered":"<section class=\"hero  light light-to-dark-gradient printing-3d-page\" >\r\n        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/Frame-1321317199.png\" alt=\"Services de moulage par injection plastique\" class=\"hero__left-image\" \/>\r\n            <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/image-24.png\" alt=\"Services de moulage par injection plastique\" class=\"hero__right-image\" \/>\r\n        <div class=\"hero__container section container\" style=\"\">\r\n        <div class=\"hero__title-wrapper\">\r\n            <h1 class=\"title title--01\">Services de <strong>moulage par injection plastique<\/strong><\/h1>\r\n            <div><p>Services de moulage par injection plastique sur mesure, de moulage par insert et de surmoulage, avec une \u00e9valuation technique experte et un accompagnement en conception d\u00e9taill\u00e9. Nous proposons un service complet, de la fabrication du moule \u00e0 la production des pi\u00e8ces.<\/p>\n<\/div>\r\n                        <div class=\"hero__advantages-list\">\r\n                                    <div class=\"hero__advantages-item\">\r\n                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/Vector.svg\" alt=\"Id\u00e9al pour la production en s\u00e9rie\">\r\n                        <p>Id\u00e9al pour la production en s\u00e9rie<\/p>\r\n                    <\/div>\r\n                                    <div class=\"hero__advantages-item\">\r\n                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/discussion.svg\" alt=\"Accompagnement technique \u00e0 chaque \u00e9tape\">\r\n                        <p>Accompagnement technique \u00e0 chaque \u00e9tape<\/p>\r\n                    <\/div>\r\n                            <\/div>\r\n                    <\/div>\r\n        <div class=\"hero__cards-list\">\r\n              \r\n    <a href=\"https:\/\/get.xometry.eu\/?locale=fr\" class=\"hero__cards-item card hero__cards-item_mobile\">\r\n        <h3 class=\"title title--03\">Devis instantan\u00e9 assist\u00e9 par l\u2019IA<\/h3>\r\n        <div class=\"hero__cards-item-text \"><p>T\u00e9l\u00e9chargez vos fichiers CAO et votre dessin technique pour obtenir un devis instantan\u00e9<\/p>\n<p>STEP \u2022<span class=\"code char\">\u00a0<\/span>STP \u2022<span class=\"code char\">\u00a0<\/span>SLDPRT\u00a0\u2022 IPT \u2022 3DXML \u2022<span class=\"code char\">\u00a0<\/span>CATPART \u2022 PTC \u2022<span class=\"code char\">\u00a0<\/span>PRT \u2022<span class=\"code char\">\u00a0<\/span>SAT<\/p>\n<\/div>\r\n        <span class=\"btn btn--primary btn_wide\">Obtenir un devis instantan\u00e9<\/span>\r\n                    <div class=\"hero__cards-item-security\">\r\n                <svg width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n                <path d=\"M16.3613 7.86564C15.9447 7.44897 15.4061 7.33398 14.7487 7.33398H6.83203V5.33398C6.83203 4.50065 7.16536 3.83398 7.7487 3.25065C8.33203 2.66732 9.08203 2.41732 9.91536 2.41732H10.332C11.1654 2.41732 11.9154 2.75065 12.4987 3.25065C13.082 3.83398 13.4154 4.58398 13.4154 5.33398C13.4154 8.11083 13.4154 7.06261 13.4154 7.67921C13.4154 8.09588 14.9987 8.06459 14.9987 7.77941C14.9987 7.49423 14.9987 7.86564 14.9987 5.33398C14.9987 4.16732 14.4987 3.00065 13.6654 2.16732C12.832 1.33398 11.6654 0.833984 10.4154 0.833984H9.9987C8.7487 0.833984 7.58203 1.33398 6.7487 2.16732C5.91536 3.00065 5.41536 4.16732 5.41536 5.33398V7.33398C4.7487 7.41732 4.2487 7.58398 3.91536 7.91732C3.4987 8.33398 3.33203 8.83398 3.33203 9.41732V15.5007C3.33203 16.5007 3.7487 17.5007 4.4987 18.2507C5.2487 19.0007 6.2487 19.4173 7.2487 19.4173H12.9987C14.082 19.4173 14.9987 19.0007 15.7487 18.2507C16.4987 17.5007 16.9154 16.584 16.9154 15.5007V9.41732C16.9154 8.54938 16.778 8.28231 16.3613 7.86564ZM4.91536 9.41732C4.91536 9.25065 4.91536 9.11523 4.9987 9.00065C5.13542 8.83398 5.2487 8.83398 5.41536 8.83398H14.7487C15.0085 8.83398 15.0864 8.90156 15.207 9.00781C15.3148 9.10273 15.332 9.25065 15.332 9.41732V15.5007C15.332 16.084 15.082 16.6673 14.6654 17.1673C14.2487 17.584 13.582 17.834 12.9987 17.834H7.2487C6.58203 17.834 5.9987 17.584 5.58203 17.1673C5.16536 16.7507 4.91536 16.1673 4.91536 15.5007V9.41732Z\" fill=\"#476175\"\/>\r\n                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M11.002 13.3833C11.4415 13.1095 11.7339 12.622 11.7339 12.0662C11.7339 11.2098 11.0397 10.5156 10.1834 10.5156C9.32702 10.5156 8.63281 11.2098 8.63281 12.0662C8.63281 12.6095 8.91229 13.0876 9.33534 13.3645V15.3337C9.33534 15.5004 9.41867 15.7504 9.58534 15.917C9.752 16.0837 9.91867 16.167 10.1687 16.167C10.4187 16.167 10.5853 16.0837 10.752 15.917C10.9187 15.7504 11.002 15.5837 11.002 15.3337V13.3833Z\" fill=\"#476175\"\/>\r\n                <\/svg>\r\n                Tous les t\u00e9l\u00e9chargements sont s\u00e9curis\u00e9s et confidentiels            <\/div>\r\n            <\/a>\r\n  \r\n    <a href=\"https:\/\/get.xometry.eu\/high-volume-manufacturing\/?locale=fr\" class=\"hero__cards-item card hero__cards-item_mobile\">\r\n        <h3 class=\"title title--03\">Devis pour productions en moyennes et grandes s\u00e9ries<\/h3>\r\n        <div class=\"hero__cards-item-text \"><p>Vous souhaitez obtenir un devis personnalis\u00e9 pour un projet complexe ? Cr\u00e9ez votre compte, signez un accord de confidentialit\u00e9 (NDA) et \u00e9changez avec un responsable de compte (r\u00e9serv\u00e9 aux clients professionnels)<\/p>\n<\/div>\r\n        <span class=\"btn btn--primary btn_wide\">Cr\u00e9er un compte<\/span>\r\n            <\/a>\r\n        <\/div>\r\n        <div class=\"hero__certifications-list\">                    <div class=\"hero__certifications-item\">\r\n                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/12\/trusted.svg\" alt=\"Certifi\u00e9 ISO 9001:2015\" \/>\r\n                                                Certifi\u00e9 ISO 9001:2015                    <\/div>\r\n                <\/div>    <\/div>\r\n<\/section>\n\n<section class=\"brands-slider  light blue-10\">\r\n    <div class=\"container\">\r\n        <div class=\"hero__brands-slider-wrapper\">\r\n            <p>Plus de 85 000 ing\u00e9nieurs et acheteurs ont confiance<\/p>\r\n            <div class=\"hero__brands-slider slider-mode\">\r\n                <div class=\"swiper-wrapper\">\r\n                                                                                        <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/bosch-logo-monochrome.svg\" alt=\"Bosch\" style='height:38px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2022\/01\/bosch-logo.svg\" alt=\"Bosch\" style='height:38px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <a class=\"swiper-slide brands-slider__item\" href=\"https:\/\/xometry.eu\/en\/case-studies\/hybrid-marine-engines\/\" target=\"_blank\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/hybrid-marine-logo-monochrome.png\" alt=\"Hybrid Marine\" style='height:38px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/hybrid-marine-logo.png\" alt=\"Hybrid Marine\" style='height:38px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                            <div class=\"brands-slider__item-tooltip-wrapper\">\r\n                                            <button type=\"button\" aria-label=\"Open brand tooltip\" class=\"brands-slider__item-tooltip-opener\">\r\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"24\" viewBox=\"0 0 25 24\" fill=\"none\">\r\n                                                <path d=\"M12.6001 1.5C6.80166 1.5 2.1001 6.20156 2.1001 12C2.1001 17.7984 6.80166 22.5 12.6001 22.5C18.3985 22.5 23.1001 17.7984 23.1001 12C23.1001 6.20156 18.3985 1.5 12.6001 1.5ZM12.6001 20.7188C7.78604 20.7188 3.88135 16.8141 3.88135 12C3.88135 7.18594 7.78604 3.28125 12.6001 3.28125C17.4142 3.28125 21.3188 7.18594 21.3188 12C21.3188 16.8141 17.4142 20.7188 12.6001 20.7188Z\"\/>\r\n                                                <path d=\"M11.4751 7.875C11.4751 8.17337 11.5936 8.45952 11.8046 8.6705C12.0156 8.88147 12.3017 9 12.6001 9C12.8985 9 13.1846 8.88147 13.3956 8.6705C13.6066 8.45952 13.7251 8.17337 13.7251 7.875C13.7251 7.57663 13.6066 7.29048 13.3956 7.0795C13.1846 6.86853 12.8985 6.75 12.6001 6.75C12.3017 6.75 12.0156 6.86853 11.8046 7.0795C11.5936 7.29048 11.4751 7.57663 11.4751 7.875ZM13.1626 10.5H12.0376C11.9345 10.5 11.8501 10.5844 11.8501 10.6875V17.0625C11.8501 17.1656 11.9345 17.25 12.0376 17.25H13.1626C13.2657 17.25 13.3501 17.1656 13.3501 17.0625V10.6875C13.3501 10.5844 13.2657 10.5 13.1626 10.5Z\"\/>\r\n                                            <\/svg>\r\n                                            <\/button>\r\n                            \r\n                                            <div class=\"brands-slider__item-tooltip\">\r\n                                                <p class=\"brands-slider__item-tooltip-text\">Hybrid Engines for the Marine Industry Produced Faster With on-demand Manufacturing<\/p>\r\n                                                                                                    <div class=\"btn btn--primary brands-slider__item-tooltip-btn\">\r\n                                                        Lire l&rsquo;\u00e9tude de cas                                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\">\r\n                                                        <path d=\"M11.8047 11.8047C11.5444 12.065 11.1227 12.0649 10.8624 11.8047C10.602 11.5444 10.602 11.1226 10.8624 10.8623L13.0577 8.66702L1.33305 8.66702C0.965021 8.66686 0.667052 8.3681 0.667038 8.00003C0.667038 7.63195 0.965014 7.3332 1.33305 7.33304L13.0577 7.33304L10.8624 5.13773C10.602 4.87737 10.602 4.45565 10.8624 4.19534C10.9924 4.06535 11.1626 4.00011 11.3331 4.00003C11.5037 4.00003 11.6746 4.06517 11.8047 4.19534L15.1377 7.52835C15.3981 7.78871 15.3981 8.2114 15.1377 8.47171L11.8047 11.8047Z\" fill=\"white\"\/>\r\n                                                        <\/svg>\r\n                                                    <\/div>\r\n                                                                                            <\/div>\r\n                                        <\/div>\r\n                                                                                                        <\/a>\r\n                                                                                                                                    <a class=\"swiper-slide brands-slider__item\" href=\"https:\/\/xometry.eu\/en\/case-studies\/pembleton-cycle-cars\/\" target=\"_blank\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/10\/pembleton-logo-monochrome.png\" alt=\"Pembleton\" style='height:44px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/10\/pembleton-logo.png\" alt=\"Pembleton\" style='height:44px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                            <div class=\"brands-slider__item-tooltip-wrapper\">\r\n                                            <button type=\"button\" aria-label=\"Open brand tooltip\" class=\"brands-slider__item-tooltip-opener\">\r\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"24\" viewBox=\"0 0 25 24\" fill=\"none\">\r\n                                                <path d=\"M12.6001 1.5C6.80166 1.5 2.1001 6.20156 2.1001 12C2.1001 17.7984 6.80166 22.5 12.6001 22.5C18.3985 22.5 23.1001 17.7984 23.1001 12C23.1001 6.20156 18.3985 1.5 12.6001 1.5ZM12.6001 20.7188C7.78604 20.7188 3.88135 16.8141 3.88135 12C3.88135 7.18594 7.78604 3.28125 12.6001 3.28125C17.4142 3.28125 21.3188 7.18594 21.3188 12C21.3188 16.8141 17.4142 20.7188 12.6001 20.7188Z\"\/>\r\n                                                <path d=\"M11.4751 7.875C11.4751 8.17337 11.5936 8.45952 11.8046 8.6705C12.0156 8.88147 12.3017 9 12.6001 9C12.8985 9 13.1846 8.88147 13.3956 8.6705C13.6066 8.45952 13.7251 8.17337 13.7251 7.875C13.7251 7.57663 13.6066 7.29048 13.3956 7.0795C13.1846 6.86853 12.8985 6.75 12.6001 6.75C12.3017 6.75 12.0156 6.86853 11.8046 7.0795C11.5936 7.29048 11.4751 7.57663 11.4751 7.875ZM13.1626 10.5H12.0376C11.9345 10.5 11.8501 10.5844 11.8501 10.6875V17.0625C11.8501 17.1656 11.9345 17.25 12.0376 17.25H13.1626C13.2657 17.25 13.3501 17.1656 13.3501 17.0625V10.6875C13.3501 10.5844 13.2657 10.5 13.1626 10.5Z\"\/>\r\n                                            <\/svg>\r\n                                            <\/button>\r\n                            \r\n                                            <div class=\"brands-slider__item-tooltip\">\r\n                                                <p class=\"brands-slider__item-tooltip-text\">Pembleton: Meticulously Engineered Cycle Cars Built With On-Demand Manufacturing<\/p>\r\n                                                                                                    <div class=\"btn btn--primary brands-slider__item-tooltip-btn\">\r\n                                                        Lire l&rsquo;\u00e9tude de cas                                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\">\r\n                                                        <path d=\"M11.8047 11.8047C11.5444 12.065 11.1227 12.0649 10.8624 11.8047C10.602 11.5444 10.602 11.1226 10.8624 10.8623L13.0577 8.66702L1.33305 8.66702C0.965021 8.66686 0.667052 8.3681 0.667038 8.00003C0.667038 7.63195 0.965014 7.3332 1.33305 7.33304L13.0577 7.33304L10.8624 5.13773C10.602 4.87737 10.602 4.45565 10.8624 4.19534C10.9924 4.06535 11.1626 4.00011 11.3331 4.00003C11.5037 4.00003 11.6746 4.06517 11.8047 4.19534L15.1377 7.52835C15.3981 7.78871 15.3981 8.2114 15.1377 8.47171L11.8047 11.8047Z\" fill=\"white\"\/>\r\n                                                        <\/svg>\r\n                                                    <\/div>\r\n                                                                                            <\/div>\r\n                                        <\/div>\r\n                                                                                                        <\/a>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/bmw-logo-monochrome.svg\" alt=\"BMW\"  class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/bmw-logo.svg\" alt=\"BMW\"   class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/10\/penlon-logo-monochrome.png\" alt=\"Penlon\" style='height:38px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/10\/penlon-logo.png\" alt=\"Penlon\" style='height:38px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/connectomx-logo-monochrome.png\" alt=\"ConnectomX\" style='height:44px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/connectomx-logo.png\" alt=\"ConnectomX\" style='height:44px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/dell-logo-monochrome.svg\" alt=\"Dell\"  class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/dell-logo.svg\" alt=\"Dell\"   class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/neocean-logo-monochrome.png\" alt=\"Neocean\" style='height:20px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/neocean-logo-1.png\" alt=\"Neocean\" style='height:20px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/ge-logo-monochrome.svg\" alt=\"General Electrics\"  class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/ge-logo.svg\" alt=\"General Electrics\"   class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/belassi-logo-monochrome.png\" alt=\"Belassi\" style='height:28px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/belassi-logo.png\" alt=\"Belassi\" style='height:28px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/10\/scewo-logo-monochrome.png\" alt=\"SCEWO\" style='height:28px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/10\/scewo-logo.png\" alt=\"SCEWO\" style='height:28px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/nasa-logo-monochrome.svg\" alt=\"Nasa\"  class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/nasa-logo.svg\" alt=\"Nasa\"   class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                                                                    <div class=\"swiper-slide brands-slider__item\">\r\n                                                                    <div class=\"brands-slider__item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/08\/sncf-logo-monochrome.svg\" alt=\"SNCF\" style='height:38px;' class=\"svg-default\" \/>\r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/08\/sncf-logo.svg\" alt=\"SNCF\" style='height:38px;'  class=\"svg-color\">\r\n                                                                                \r\n                                    <\/div>\r\n                                                                                                        <\/div>\r\n                                                                                <\/a>\r\n            <\/div>\r\n        <\/div>\r\n            <\/div>\r\n<\/section>\n\n\r\n<section class=\"capability-cards\r\n  light \r\n  blue-10  \r\n\">\r\n    <div class=\"capability-cards__container section container\">\r\n            <div class=\"section__title-wrapper\">\r\n                    <h2 class=\"title title--02\">Nos capacit\u00e9s en injection plastique<\/h2>\r\n            <\/div>\r\n                    <div class=\"capability-cards__list\">\r\n                <div class=\"capability-cards__item\">\r\n            <a href=\"https:\/\/xometry.eu\/fr\/moulage-par-injection\/\" class=\"capability-cards__item-image\">\r\n            <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/Frame-481041.png\" alt=\"Selective Laser Sintering\">\r\n                    <div  class=\"capability-cards__item-link\">\r\n                En savoir plus                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\">\r\n                <path d=\"M1.33201 8.66665L13.0559 8.66665L10.8606 10.8619C10.6003 11.1222 10.6003 11.5444 10.8606 11.8047C11.1209 12.0651 11.5431 12.0651 11.8034 11.8047L15.1368 8.4714C15.3971 8.21109 15.3971 7.78896 15.1368 7.5286L11.8034 4.19527C11.6733 4.06509 11.5026 3.99998 11.332 3.99998C11.1614 3.99998 10.9908 4.06509 10.8606 4.19527C10.6003 4.45558 10.6003 4.87771 10.8606 5.13807L13.0559 7.33331L1.33201 7.33331C0.963833 7.33331 0.665344 7.6318 0.665344 7.99998C0.665344 8.36816 0.963833 8.66664 1.33201 8.66665Z\" fill=\"#092C47\"\/>\r\n                <\/svg>\r\n            <\/div>\r\n                    <\/a>\r\n        \r\n\r\n    <div class=\"capability-cards__item-main\">\r\n            <a href=\"https:\/\/xometry.eu\/fr\/moulage-par-injection\/\" class=\"capability-cards__item-info\">\r\n                <div class=\"capability-cards__item-titles\">\r\n                                    <h4 class=\"short-title title title--04\">\r\n                                            <\/h4>\r\n                                                    <h5 class=\"long-title title title--05\">\r\n                        Moulage par injection                    <\/h5>\r\n                            <\/div>\r\n                                <div class=\"capability-cards__item-descripion\">\r\n                        Production en s\u00e9rie de pi\u00e8ces plastiques complexes, \u00e0 haute pr\u00e9cision                    <\/div>\r\n                            <\/a>\r\n                        <a href=\"https:\/\/get.xometry.eu\/?locale=fr\" class=\"btn btn--primary\">Obtenir un devis instantan\u00e9<\/a>\r\n            <\/div>\r\n<\/div>\r\n                <div class=\"capability-cards__item\">\r\n            <div class=\"capability-cards__item-image\">\r\n            <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/Frame-481041-1.png\" alt=\"Selective Laser Sintering\">\r\n                    <\/div>\r\n        \r\n\r\n    <div class=\"capability-cards__item-main\">\r\n            <div class=\"capability-cards__item-info\">\r\n                <div class=\"capability-cards__item-titles\">\r\n                                    <h4 class=\"short-title title title--04\">\r\n                                            <\/h4>\r\n                                                    <h5 class=\"long-title title title--05\">\r\n                        Surmoulage d&rsquo;inserts                    <\/h5>\r\n                            <\/div>\r\n                                <div class=\"capability-cards__item-descripion\">\r\n                        Int\u00e9gration d\u2019\u00e9l\u00e9ments m\u00e9talliques ou techniques pendant le moulage                    <\/div>\r\n                            <\/div>\r\n                        <a href=\"https:\/\/get.xometry.eu\/?locale=fr\" class=\"btn btn--primary\">Obtenir un devis instantan\u00e9<\/a>\r\n            <\/div>\r\n<\/div>\r\n                <div class=\"capability-cards__item\">\r\n            <div class=\"capability-cards__item-image\">\r\n            <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/Frame-481041-2.png\" alt=\"Selective Laser Sintering\">\r\n                    <\/div>\r\n        \r\n\r\n    <div class=\"capability-cards__item-main\">\r\n            <div class=\"capability-cards__item-info\">\r\n                <div class=\"capability-cards__item-titles\">\r\n                                    <h4 class=\"short-title title title--04\">\r\n                                            <\/h4>\r\n                                                    <h5 class=\"long-title title title--05\">\r\n                        Surmoulage                    <\/h5>\r\n                            <\/div>\r\n                                <div class=\"capability-cards__item-descripion\">\r\n                        Assemblage de mat\u00e9riaux multiples pour am\u00e9liorer la fonctionnalit\u00e9 ou l\u2019esth\u00e9tique                    <\/div>\r\n                            <\/div>\r\n                        <a href=\"https:\/\/get.xometry.eu\/?locale=fr\" class=\"btn btn--primary\">Obtenir un devis instantan\u00e9<\/a>\r\n            <\/div>\r\n<\/div>\r\n                                            <\/div>\r\n        \r\n\r\n        <!-- <button type=\"button\" class=\"btn btn--secondary capability-cards__hide-btn\">\r\n           <php echo  __(\"Hide\", \"xometry\");?>\r\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"16\" viewBox=\"0 0 17 16\" fill=\"none\">\r\n                <path\r\n                    d=\"M2.6873 12L3.85918 12C3.93886 12 4.01386 11.9609 4.06074 11.8969L8.4998 5.77813L12.9389 11.8969C12.9857 11.9609 13.0607 12 13.1404 12H14.3123C14.4139 12 14.4732 11.8844 14.4139 11.8016L8.90449 4.20625C8.70449 3.93125 8.29511 3.93125 8.09668 4.20625L2.5873 11.8016C2.52636 11.8844 2.58574 12 2.6873 12Z\"\r\n                    fill=\"#0E6AED\" \/>\r\n            <\/svg>\r\n        <\/button> -->\r\n            <\/div>\r\n<\/section>\n\n\r\n <section class=\"capability-list light dark-to-light-gradient\">\r\n  <div class=\"capability-list__container section container\">\r\n        <div class=\"capability-list__list\">\r\n    \r\n            <div class=\"capability-list__item \">\r\n                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/3D-printer.svg\" alt=\"\" class=\"capability-list__item-icon\">\r\n                <div class=\"capability-list__item-main\">\r\n                    <h3 class=\"capability-list__item-title text-s\">Machines disponibles<\/h3>\r\n                    <div class=\"capability-list__item-text title title--05\">Moules \u00e0 cavit\u00e9 simple, \u00e0 cavit\u00e9s multiples et moules famille (multi-empreintes) ; presses de 50 \u00e0 plus de 1100 tonnes<\/div>\r\n                <\/div>\r\n            <\/div>\r\n\r\n        \r\n            <div class=\"capability-list__item \">\r\n                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/many.svg\" alt=\"\" class=\"capability-list__item-icon\">\r\n                <div class=\"capability-list__item-main\">\r\n                    <h3 class=\"capability-list__item-title text-s\">Quantit\u00e9<\/h3>\r\n                    <div class=\"capability-list__item-text title title--05\">De 50 \u00e0 1 000 000 de pi\u00e8ces<\/div>\r\n                <\/div>\r\n            <\/div>\r\n\r\n        \r\n            <div class=\"capability-list__item \">\r\n                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/attention.svg\" alt=\"\" class=\"capability-list__item-icon\">\r\n                <div class=\"capability-list__item-main\">\r\n                    <h3 class=\"capability-list__item-title text-s\">Tol\u00e9rance des pi\u00e8ces<\/h3>\r\n                    <div class=\"capability-list__item-text title title--05\">Tol\u00e9rances DIN 16742 ou tol\u00e9rances plus strictes selon vos dessins 2D<\/div>\r\n                <\/div>\r\n            <\/div>\r\n\r\n        \r\n            <div class=\"capability-list__item \">\r\n                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/samples.svg\" alt=\"\" class=\"capability-list__item-icon\">\r\n                <div class=\"capability-list__item-main\">\r\n                    <h3 class=\"capability-list__item-title text-s\">Finitions<\/h3>\r\n                    <div class=\"capability-list__item-text title title--05\">SPI\u00a0(A1, A2, A3, B1, B2, B3, C1, C2, C3, D1, D2, D3),\u00a0\r\nEDM STD\u00a0(VDI 12, 15, 18, 21, 24, 27, 30, 33, 36, 39, 42, 45), \r\nfinitions personnalis\u00e9es<\/div>\r\n                <\/div>\r\n            <\/div>\r\n\r\n        \r\n            <div class=\"capability-list__item \">\r\n                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/cube.png\" alt=\"\" class=\"capability-list__item-icon\">\r\n                <div class=\"capability-list__item-main\">\r\n                    <h3 class=\"capability-list__item-title text-s\">Mat\u00e9riaux<\/h3>\r\n                    <div class=\"capability-list__item-text title title--05\">Une large gamme de mat\u00e9riaux : plastiques rigides et flexibles couramment utilis\u00e9s, \u00e9lastom\u00e8res, caoutchoucs synth\u00e9tiques, ainsi que des options enti\u00e8rement personnalis\u00e9es selon vos besoins.<\/div>\r\n                <\/div>\r\n            <\/div>\r\n\r\n        \r\n            <div class=\"capability-list__item \">\r\n                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/ok.svg\" alt=\"\" class=\"capability-list__item-icon\">\r\n                <div class=\"capability-list__item-main\">\r\n                    <h3 class=\"capability-list__item-title text-s\">Types de moules disponibles<\/h3>\r\n                    <div class=\"capability-list__item-text title title--05\">Acier (acier \u00e0 outils, acier carbone) et aluminium ; classes de 105 (prototype) \u00e0 101 (production tr\u00e8s \u00e9lev\u00e9e)<\/div>\r\n                <\/div>\r\n            <\/div>\r\n\r\n        \r\n            <div class=\"capability-list__item border-none_desktop\">\r\n                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/broken-link.svg\" alt=\"\" class=\"capability-list__item-icon\">\r\n                <div class=\"capability-list__item-main\">\r\n                    <h3 class=\"capability-list__item-title text-s\">Tol\u00e9rances pour les \u00e9l\u00e9ments critiques<\/h3>\r\n                    <div class=\"capability-list__item-text title title--05\">Des tol\u00e9rances plus serr\u00e9es peuvent \u00eatre demand\u00e9es et peuvent augmenter le co\u00fbt de l&#039;outillage en raison d&#039;\u00e9chantillons et d&#039;ajustements suppl\u00e9mentaires. Xometry usinera les \u00e9l\u00e9ments critiques jusqu&#039;\u00e0 ce que l&#039;acier soit dans un \u00e9tat s\u00e9curis\u00e9.<\/div>\r\n                <\/div>\r\n            <\/div>\r\n\r\n        \r\n            <div class=\"capability-list__item border-none\">\r\n                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/solutions.svg\" alt=\"\" class=\"capability-list__item-icon\">\r\n                <div class=\"capability-list__item-main\">\r\n                    <h3 class=\"capability-list__item-title text-s\">Propri\u00e9t\u00e9 de l&#039;outil<\/h3>\r\n                    <div class=\"capability-list__item-text title title--05\">Appartient au client, comprend la maintenance du moule<\/div>\r\n                <\/div>\r\n            <\/div>\r\n\r\n        \r\n    <\/div>\r\n    \r\n            <div class=\"capability-list__table-wrapper\">\r\n        <table>\r\n                            <thead>\r\n                <tr>\r\n                    <th>Classe de moule<\/th><th>Cycles<\/th><th>Niveau de production<\/th><th>Base du moule<\/th><th>Duret\u00e9 minimale (BHN)<\/th><th>Description<\/th>   \r\n                <\/tr>\r\n                <\/thead>\r\n                        <tbody>\r\n                                    <tr>\r\n                        <td>101<\/td><td>&gt;1 million<\/td><td>\u00c9lev\u00e9<\/td><td>Acier inoxydable trait\u00e9 \u00e0 chaud<\/td><td>280<\/td><td>Temps de cycle rapides et taux de production tr\u00e8s \u00e9lev\u00e9<\/td>                    <\/tr>\r\n                                    <tr>\r\n                        <td>102<\/td><td>&lt;1 million<\/td><td>Moyen \u00e0 \u00e9lev\u00e9<\/td><td>Acier \u00e0 outils trait\u00e9 thermiquement<\/td><td>280<\/td><td>Id\u00e9al pour les pi\u00e8ces avec des mat\u00e9riaux abrasifs et des tol\u00e9rances serr\u00e9es<\/td>                    <\/tr>\r\n                                    <tr>\r\n                        <td>103<\/td><td>&lt;50,000<\/td><td>Moyen<\/td><td>Acier P20<\/td><td>165<\/td><td>Largement utilis\u00e9 pour les pi\u00e8ces de production faible \u00e0 moyenne<\/td>                    <\/tr>\r\n                                    <tr>\r\n                        <td>104<\/td><td>&lt;10,000<\/td><td>Faible<\/td><td>Acier, aluminium ou alliages<\/td><td>&lt;165<\/td><td>Bon pour les pi\u00e8ces \u00e0 production limit\u00e9e particuli\u00e8rement pour les mat\u00e9riaux non abrasifs<\/td>                    <\/tr>\r\n                                    <tr>\r\n                        <td>105<\/td><td>&lt;500<\/td><td>Tr\u00e8s faible<\/td><td>Aluminium, \u00e9poxy, mat\u00e9riaux de moulage<\/td><td>&lt;165<\/td><td>Principalement utilis\u00e9 pour la production de prototype<\/td>                    <\/tr>\r\n                            <\/tbody>\r\n        <\/table>\r\n        <\/div>\r\n        <div class=\"capability-list__btns-container\">\r\n            <div class=\"call-to-action\">\r\n                    <a href=\"https:\/\/get.xometry.eu\/?locale=fr\" class=\"btn btn--primary\" target=\"\">Obtenir un devis instantan\u00e9<\/a>\r\n                    <a href=\"https:\/\/get.xometry.eu\/high-volume-manufacturing\/?locale=fr\" class=\"btn btn--primary\" target=\"\">Cr\u00e9er un compte<\/a>\r\n            <\/div>\r\n                    <button type=\"button\" class=\"capability-list__table-switcher btn btn--secondary\" data-show-name=\"Afficher les classes de moule\" data-hide-name=\"Masquer les classes de moule\">\r\n                <span>Afficher les classes de moule<\/span>\r\n                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\">\r\n                <path d=\"M13.8127 4H12.6408C12.5611 4 12.4861 4.03906 12.4393 4.10313L8.0002 10.2219L3.56114 4.10313C3.51426 4.03906 3.43926 4 3.35957 4H2.1877C2.08614 4 2.02676 4.11563 2.08614 4.19844L7.59551 11.7937C7.79551 12.0687 8.20489 12.0687 8.40332 11.7937L13.9127 4.19844C13.9736 4.11563 13.9143 4 13.8127 4Z\" fill=\"#0E6AED\"\/>\r\n                <\/svg>\r\n            <\/button>\r\n            <\/div>\r\n  <\/div>\r\n<\/section>\n\n <section class=\"customer-review light light-to-dark-gradient\">\r\n    <div class=\"customer-review__container section container\">\r\n        <div class=\"customer-review__list card\">\r\n            <h2 class=\"visibility-hidden\">H\u0131z\u0131r Akbulut, Vivavis<\/h2>\r\n                            <div class=\"customer-review__card card\">\r\n                    <img decoding=\"async\" class=\"customer-review__card-image\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/vivavis-octopus-scaled.webp\" alt=\"H\u0131z\u0131r Akbulut, Vivavis\" \/>\r\n                <\/div>\r\n                        <div class=\"customer-review__card card\">\r\n                <svg\r\n                    class=\"customer-review__card-quotes\"\r\n                    xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\r\n                    width=\"80\"\r\n                    height=\"60\"\r\n                    viewBox=\"0 0 80 60\"\r\n                    fill=\"none\"\r\n                >\r\n                    <path\r\n                    d=\"M16.9911 58.7131C12.1927 58.7131 8.14159 57.1399 4.83776 53.9934C1.61259 50.9255 0 46.8744 0 41.84C0 35.7043 2.59587 28.8606 7.78761 21.309C13.058 13.836 20.059 7.1497 28.7906 1.25L32.4484 4.90782C29.0659 8.5263 26.3913 11.8695 24.4248 14.9373C22.5369 17.9265 21.5929 20.365 21.5929 22.253C21.5929 23.8262 22.2222 25.1241 23.4808 26.1468C23.8741 26.5401 24.9361 27.484 26.6667 28.9786C28.4759 30.4732 30.0492 32.2431 31.3864 34.2883C32.5664 36.1763 33.1563 38.6935 33.1563 41.84C33.1563 46.7957 31.6618 50.8469 28.6726 53.9934C25.5261 57.1399 21.6323 58.7131 16.9911 58.7131ZM63.8348 58.7131C58.8791 58.7131 54.8279 57.1399 51.6814 53.9934C48.5349 50.8469 46.9617 46.7957 46.9617 41.84C46.9617 35.547 49.5182 28.7033 54.6313 21.309C59.9017 13.836 66.9027 7.1497 75.6342 1.25L79.292 4.90782C75.9095 8.5263 73.235 11.8695 71.2684 14.9373C69.3805 17.9265 68.4366 20.365 68.4366 22.253C68.4366 23.8262 69.0659 25.1241 70.3245 26.1468C70.7178 26.5401 71.7797 27.484 73.5103 28.9786C75.3196 30.4732 76.8928 32.2431 78.2301 34.2883C79.41 36.1763 80 38.6935 80 41.84C80 46.7957 78.5054 50.8469 75.5162 53.9934C72.3697 57.1399 68.4759 58.7131 63.8348 58.7131Z\"\r\n                    \/>\r\n                <\/svg>\r\n                <div class=\"customer-review__card-text text-l\">\r\n                    <p>\u00ab L&rsquo;expertise de Xometry en mati\u00e8re de moulage par injection a garanti que le bo\u00eetier de notre appareil Octopus IoT r\u00e9pondait \u00e0 des normes strictes de durabilit\u00e9 et IP68, essentielles \u00e0 ses performances dans des environnements difficiles. \u00bb<\/p>\n                <\/div>\r\n                                    <div class=\"customer-review__card-footer\">\r\n                        <img decoding=\"async\" class=\"customer-review__card-logo-small\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/vivavis-logo.png\" alt=\"H\u0131z\u0131r Akbulut, Vivavis\" \/>\r\n                        <h3 class=\"title title--04\">H\u0131z\u0131r Akbulut, Vivavis<\/h3>\r\n                    <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n            <\/div>\r\n<\/section>\n\n <section class=\"advantages light blue-10\">\r\n    <div class=\"advantages__container section container\">\r\n        <h2 class=\"title title--02\">\r\n            Les avantages de notre plateforme de fabrication num\u00e9rique        <\/h2>\r\n        <div class=\"advantages__list\">\r\n                                <div class=\"advantages__item card\">\r\n                        <img decoding=\"async\" class=\"advantages__item-image\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/massive-network-capacity-dark.svg\" alt=\"Une immense capacit\u00e9 de r\u00e9seau\"\r\n                        \/>\r\n                        <h4 class=\"title title--04\">Une immense capacit\u00e9 de r\u00e9seau<\/h4>\r\n                        <div>\r\n                            <p>Acc\u00e9dez \u00e0 la capacit\u00e9 de production de plus de 5 000 fabricants qualifi\u00e9s dans le monde. Notre r\u00e9seau offre une large gamme de capacit\u00e9s de production et de certifications et permet de produire des pi\u00e8ces de tout niveau de complexit\u00e9, dans presque tous les mat\u00e9riaux, avec des tol\u00e9rances pr\u00e9cises et le post-traitement requis.<\/p>\n                        <\/div>\r\n                                            <\/div>\r\n                                        <div class=\"advantages__item card\">\r\n                        <img decoding=\"async\" class=\"advantages__item-image\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/intuitive-project-interface-dark.svg\" alt=\"Une interface de projet intuitive\"\r\n                        \/>\r\n                        <h4 class=\"title title--04\">Une interface de projet intuitive<\/h4>\r\n                        <div>\r\n                            <p>Commandez vos pi\u00e8ces facilement et quelle que soit l&rsquo;\u00e9chelle, gr\u00e2ce \u00e0 des devis instantan\u00e9s g\u00e9n\u00e9r\u00e9s par l&rsquo;IA, du prototypage \u00e0 la production en s\u00e9rie.<\/p>\n                        <\/div>\r\n                                            <\/div>\r\n                                        <div class=\"advantages__item card\">\r\n                        <img decoding=\"async\" class=\"advantages__item-image\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/endless-capabilities-dark.svg\" alt=\"Solutions d&rsquo;achat flexibles\"\r\n                        \/>\r\n                        <h4 class=\"title title--04\">Solutions d&rsquo;achat flexibles<\/h4>\r\n                        <div>\r\n                            <p>Xometry offre la possibilit\u00e9 de payer post-production pour les entreprises clientes, une vari\u00e9t\u00e9 de m\u00e9thodes de paiement pour r\u00e9pondre \u00e0 vos besoins, et la possibilit\u00e9 d&rsquo;\u00e9tablir des accords-cadres pour des prix et des quantit\u00e9s sp\u00e9cifiques, garantissant la pr\u00e9visibilit\u00e9 des co\u00fbts et la rationalisation des processus d&rsquo;approvisionnement.<\/p>\n                        <\/div>\r\n                                            <\/div>\r\n                                        <div class=\"advantages__item card\">\r\n                        <img decoding=\"async\" class=\"advantages__item-image\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/quality-assurance-dark.svg\" alt=\"Assurance qualit\u00e9\"\r\n                        \/>\r\n                        <h4 class=\"title title--04\">Assurance qualit\u00e9<\/h4>\r\n                        <div>\r\n                            <p>Certifi\u00e9 ISO 9001:2015, Xometry assure une qualit\u00e9 sup\u00e9rieure de chaque pi\u00e8ce exp\u00e9di\u00e9e gr\u00e2ce \u00e0 l&rsquo;int\u00e9gration harmonieuse de son r\u00e9seau de partenaires, de son \u00e9quipe d&rsquo;ing\u00e9nieurs en applications et de son laboratoire interne d&rsquo;assurance qualit\u00e9.<\/p>\n                        <\/div>\r\n                                                    <div class=\"advantages__item-footer\">\r\n                                <a href=\"https:\/\/youtu.be\/ievLnFE8uN4?si=6eWWcFOoIelEipOu\" class=\"advantages__item-link\" target=\"_blank\"\r\n                                    ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"28\" viewBox=\"0 0 28 28\" fill=\"none\">\r\n  <path d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\" fill=\"#0E6AED\"\/>\r\n  <path d=\"M19.6711 13.6479L11.5746 7.76893C11.5097 7.72133 11.4328 7.6927 11.3525 7.68622C11.2723 7.67975 11.1918 7.69568 11.1201 7.73226C11.0484 7.76883 10.9882 7.8246 10.9463 7.89336C10.9044 7.96212 10.8824 8.04115 10.8828 8.12167V19.8795C10.8828 20.2377 11.2875 20.4401 11.5746 20.2322L19.6711 14.3533C19.727 14.313 19.7725 14.2601 19.8039 14.1987C19.8353 14.1374 19.8517 14.0695 19.8517 14.0006C19.8517 13.9317 19.8353 13.8638 19.8039 13.8024C19.7725 13.7411 19.727 13.6881 19.6711 13.6479ZM12.6273 17.3119V10.6893L17.1856 14.0006L12.6273 17.3119Z\" fill=\"#0E6AED\"\/>\r\n<\/svg> Regardez la vid\u00e9o sur notre processus d&rsquo;assurance qualit\u00e9                                <\/a >\r\n                            <\/div>\r\n                                            <\/div>\r\n                                        <div class=\"advantages__item card\">\r\n                        <img decoding=\"async\" class=\"advantages__item-image\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/fast-delivery-across-europe-dark.svg\" alt=\"Livraison rapide dans toute l&rsquo;Europe\"\r\n                        \/>\r\n                        <h4 class=\"title title--04\">Livraison rapide dans toute l&rsquo;Europe<\/h4>\r\n                        <div>\r\n                            <p>Xometry livre des pi\u00e8ces dans tous les pays europ\u00e9ens, y compris au Royaume-Uni, en Norv\u00e8ge et en Suisse. Consultez d\u00e8s maintenant vos options de livraison pour des devis instantan\u00e9s ou planifiez vos exp\u00e9ditions personnalis\u00e9es pour des projets plus complexes.<\/p>\n                        <\/div>\r\n                                            <\/div>\r\n                                        <div class=\"advantages__item card\">\r\n                        <img decoding=\"async\" class=\"advantages__item-image\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/certifications-inspection-reports-dark.svg\" alt=\"Certifications et rapports d&rsquo;inspection\"\r\n                        \/>\r\n                        <h4 class=\"title title--04\">Certifications et rapports d&rsquo;inspection<\/h4>\r\n                        <div>\r\n                            <p>Xometry peut fournir divers certificats (conformit\u00e9 aux types de commande 2.1 et 2.2, certificats de mati\u00e8re premi\u00e8re pour les m\u00e9taux et plastiques, protocoles de traitement thermique, certificats RoHS, etc.) et des rapports d&rsquo;inspection (CMM, Rapport de contr\u00f4le des premiers articles &#8211; FAIR, rapports de mesure, etc.).<\/p>\n                        <\/div>\r\n                                            <\/div>\r\n                            <\/div>\r\n            <\/div>\r\n<\/section>\n\n<section class=\"process-slider light blue-10\">\r\n  <div class=\"process-slider__container section container\">\r\n        <div class=\"section__title-wrapper\">\r\n                    <h2 class=\"title title--02\">Le processus de moulage par injection avec Xometry<\/h2>\r\n                    <div class=\"section__description\">\r\n                <p>Cr\u00e9ez un devis en ligne sur Xometry, et notre \u00e9quipe d\u2019ing\u00e9nieurs vous guide \u00e0 chaque \u00e9tape : du chiffrage et de l\u2019analyse de fabricabilit\u00e9 (DFM) \u00e0 la fabrication de l\u2019outillage et \u00e0 la livraison des pi\u00e8ces.<\/p>\n            <\/div>\r\n            <\/div>\r\n    <div class=\"process-slider__slider-wrapper\">\r\n                    <div class=\"process-slider__small-slider\">\r\n                                    <button class=\"process-slider__small-slider-item\">\r\n                        <span class=\"title title--03\">1.<\/span> \r\n                        <h3 class=\"title title--03\">Soumettez votre demande de moulage par injection<\/h3>\r\n                    <\/button>\r\n                                    <button class=\"process-slider__small-slider-item\">\r\n                        <span class=\"title title--03\">2.<\/span> \r\n                        <h3 class=\"title title--03\">Examen et chiffrage<\/h3>\r\n                    <\/button>\r\n                                    <button class=\"process-slider__small-slider-item\">\r\n                        <span class=\"title title--03\">3.<\/span> \r\n                        <h3 class=\"title title--03\">Lancement du projet et DFM<\/h3>\r\n                    <\/button>\r\n                                    <button class=\"process-slider__small-slider-item\">\r\n                        <span class=\"title title--03\">4.<\/span> \r\n                        <h3 class=\"title title--03\">Fabrication du moule et production des \u00e9chantillons<\/h3>\r\n                    <\/button>\r\n                                    <button class=\"process-slider__small-slider-item\">\r\n                        <span class=\"title title--03\">5.<\/span> \r\n                        <h3 class=\"title title--03\">Production compl\u00e8te et livraison<\/h3>\r\n                    <\/button>\r\n                                    <button class=\"process-slider__small-slider-item\">\r\n                        <span class=\"title title--03\">6.<\/span> \r\n                        <h3 class=\"title title--03\">Propri\u00e9t\u00e9 du moule et r\u00e9approvisionnement<\/h3>\r\n                    <\/button>\r\n                \r\n                <div class=\"process-slider__progress\">\r\n                    <div class=\"process-slider__progress-bar\"><\/div>\r\n                <\/div>\r\n            <\/div>\r\n\r\n            <div class=\"process-slider__big-slider\">\r\n                                    <button class=\"process-slider__big-slider-mobile-btn\">\r\n                        <span class=\"title title--03\">1.<\/span> \r\n                        <h3 class=\"title title--03\">Soumettez votre demande de moulage par injection<\/h3>\r\n                    <\/button>\r\n\r\n                    <div class=\"process-slider__big-slider-item\">\r\n                        <div class=\"process-slider__big-slider-main\">\r\n                            <h3 class=\"title title--04\">Soumettez votre demande de moulage par injection<\/h3>\r\n                            <div class=\"process-slider__big-slider-text text-l\">\r\n                                <p>T\u00e9l\u00e9chargez vos fichiers, s\u00e9lectionnez la quantit\u00e9, le mat\u00e9riau, la finition de surface et les autres param\u00e8tres, puis soumettez votre demande de devis.<\/p>\n                            <\/div>\r\n                                                            <a href=\"https:\/\/get.xometry.eu\/?locale=fr\" class=\"btn\" target=\"_self\">\r\n                                    Obtenir un devis instantan\u00e9                                <\/a>\r\n                                                    <\/div>\r\n                                                    <div class=\"process-slider__big-slider-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/step-1.png\" alt=\"Step Image\">\r\n                            <\/div>\r\n                                            <\/div>\r\n                                    <button class=\"process-slider__big-slider-mobile-btn\">\r\n                        <span class=\"title title--03\">2.<\/span> \r\n                        <h3 class=\"title title--03\">Examen et chiffrage<\/h3>\r\n                    <\/button>\r\n\r\n                    <div class=\"process-slider__big-slider-item\">\r\n                        <div class=\"process-slider__big-slider-main\">\r\n                            <h3 class=\"title title--04\">Examen et chiffrage<\/h3>\r\n                            <div class=\"process-slider__big-slider-text text-l\">\r\n                                <p>Un ing\u00e9nieur Xometry examine votre demande sous 24 \u00e0 48 h afin de garantir que toutes les exigences sont prises en compte. Vous recevez un devis initial.<\/p>\n<p>Une fois votre validation obtenue, nos ing\u00e9nieurs attribuent votre projet au fabricant le plus adapt\u00e9 selon les comp\u00e9tences, la disponibilit\u00e9 et d\u2019autres crit\u00e8res. Nous vous transmettons ensuite le devis final.<\/p>\n                            <\/div>\r\n                                                    <\/div>\r\n                                                    <div class=\"process-slider__big-slider-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/step-3.png\" alt=\"Step Image\">\r\n                            <\/div>\r\n                                            <\/div>\r\n                                    <button class=\"process-slider__big-slider-mobile-btn\">\r\n                        <span class=\"title title--03\">3.<\/span> \r\n                        <h3 class=\"title title--03\">Lancement du projet et DFM<\/h3>\r\n                    <\/button>\r\n\r\n                    <div class=\"process-slider__big-slider-item\">\r\n                        <div class=\"process-slider__big-slider-main\">\r\n                            <h3 class=\"title title--04\">Lancement du projet et DFM<\/h3>\r\n                            <div class=\"process-slider__big-slider-text text-l\">\r\n                                <p>Une fois le devis final valid\u00e9, nous lan\u00e7ons le processus d\u2019analyse de fabricabilit\u00e9 (DFM). Xometry travaille avec vous pour finaliser tous les d\u00e9tails techniques avant de lancer la production.<\/p>\n                            <\/div>\r\n                                                    <\/div>\r\n                                                    <div class=\"process-slider__big-slider-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/step-2.png\" alt=\"Step Image\">\r\n                            <\/div>\r\n                                            <\/div>\r\n                                    <button class=\"process-slider__big-slider-mobile-btn\">\r\n                        <span class=\"title title--03\">4.<\/span> \r\n                        <h3 class=\"title title--03\">Fabrication du moule et production des \u00e9chantillons<\/h3>\r\n                    <\/button>\r\n\r\n                    <div class=\"process-slider__big-slider-item\">\r\n                        <div class=\"process-slider__big-slider-main\">\r\n                            <h3 class=\"title title--04\">Fabrication du moule et production des \u00e9chantillons<\/h3>\r\n                            <div class=\"process-slider__big-slider-text text-l\">\r\n                                <ul>\n<li>Apr\u00e8s validation du DFM, nous fixons les d\u00e9lais de fabrication du moule et de production du premier \u00e9chantillon (T1).<\/li>\n<li>Vous recevez une confirmation de commande et une facture correspondant \u00e0 50 % du co\u00fbt du moule.<\/li>\n<li>Un chef de projet d\u00e9di\u00e9 g\u00e8re la logistique et les \u00e9changes. Vous recevez les \u00e9chantillons T1 accompagn\u00e9s d\u2019un rapport dimensionnel et de certificats mati\u00e8re pour validation.<\/li>\n<li>Les retours sur les \u00e9chantillons T1 peuvent entra\u00eener des it\u00e9rations suppl\u00e9mentaires (T2, T3, etc.).<\/li>\n<\/ul>\n                            <\/div>\r\n                                                    <\/div>\r\n                                                    <div class=\"process-slider__big-slider-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/step-4.png\" alt=\"Step Image\">\r\n                            <\/div>\r\n                                            <\/div>\r\n                                    <button class=\"process-slider__big-slider-mobile-btn\">\r\n                        <span class=\"title title--03\">5.<\/span> \r\n                        <h3 class=\"title title--03\">Production compl\u00e8te et livraison<\/h3>\r\n                    <\/button>\r\n\r\n                    <div class=\"process-slider__big-slider-item\">\r\n                        <div class=\"process-slider__big-slider-main\">\r\n                            <h3 class=\"title title--04\">Production compl\u00e8te et livraison<\/h3>\r\n                            <div class=\"process-slider__big-slider-text text-l\">\r\n                                <p>Une fois les \u00e9chantillons valid\u00e9s, Xometry prend en charge la production en s\u00e9rie, le contr\u00f4le qualit\u00e9 et la livraison. Le moule est stock\u00e9 dans nos installations pendant deux ans. Aucun frais de stockage n\u2019est factur\u00e9 en cas de commande r\u00e9currente sur les m\u00eames pi\u00e8ces.<\/p>\n<p>Vous payez la production \u00e0 r\u00e9ception des pi\u00e8ces.<\/p>\n                            <\/div>\r\n                                                    <\/div>\r\n                                                    <div class=\"process-slider__big-slider-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/step-5.png\" alt=\"Step Image\">\r\n                            <\/div>\r\n                                            <\/div>\r\n                                    <button class=\"process-slider__big-slider-mobile-btn\">\r\n                        <span class=\"title title--03\">6.<\/span> \r\n                        <h3 class=\"title title--03\">Propri\u00e9t\u00e9 du moule et r\u00e9approvisionnement<\/h3>\r\n                    <\/button>\r\n\r\n                    <div class=\"process-slider__big-slider-item\">\r\n                        <div class=\"process-slider__big-slider-main\">\r\n                            <h3 class=\"title title--04\">Propri\u00e9t\u00e9 du moule et r\u00e9approvisionnement<\/h3>\r\n                            <div class=\"process-slider__big-slider-text text-l\">\r\n                                <p>La dur\u00e9e de vie du moule varie de 10 000 \u00e0 1 000 000 cycles. Le moule est votre propri\u00e9t\u00e9, et sa maintenance est assur\u00e9e par Xometry.<\/p>\n<p>Vous pouvez facilement repasser commande quand vous le souhaitez.<\/p>\n                            <\/div>\r\n                                                    <\/div>\r\n                                                    <div class=\"process-slider__big-slider-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/step-6.png\" alt=\"Step Image\">\r\n                            <\/div>\r\n                                            <\/div>\r\n                            <\/div>\r\n            <\/div>\r\n\r\n        <div class=\"call-to-action\">\r\n                    <a href=\"https:\/\/get.xometry.eu\/?locale=fr\" class=\"btn btn--primary\" target=\"\">Obtenir un devis instantan\u00e9<\/a>\r\n                    <a href=\"https:\/\/get.xometry.eu\/high-volume-manufacturing\/?locale=fr\" class=\"btn btn--primary\" target=\"\">Cr\u00e9er un compte<\/a>\r\n            <\/div>\r\n  <\/div>\r\n<\/section>\n\n <section class=\"customer-review light dark-to-light-gradient\">\r\n    <div class=\"customer-review__container section container\">\r\n        <div class=\"customer-review__list card\">\r\n            <h2 class=\"visibility-hidden\">Novag<\/h2>\r\n                            <div class=\"customer-review__card card\">\r\n                    <img decoding=\"async\" class=\"customer-review__card-image\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/Novag-photo.webp\" alt=\"Novag\" \/>\r\n                <\/div>\r\n                        <div class=\"customer-review__card card\">\r\n                <svg\r\n                    class=\"customer-review__card-quotes\"\r\n                    xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\r\n                    width=\"80\"\r\n                    height=\"60\"\r\n                    viewBox=\"0 0 80 60\"\r\n                    fill=\"none\"\r\n                >\r\n                    <path\r\n                    d=\"M16.9911 58.7131C12.1927 58.7131 8.14159 57.1399 4.83776 53.9934C1.61259 50.9255 0 46.8744 0 41.84C0 35.7043 2.59587 28.8606 7.78761 21.309C13.058 13.836 20.059 7.1497 28.7906 1.25L32.4484 4.90782C29.0659 8.5263 26.3913 11.8695 24.4248 14.9373C22.5369 17.9265 21.5929 20.365 21.5929 22.253C21.5929 23.8262 22.2222 25.1241 23.4808 26.1468C23.8741 26.5401 24.9361 27.484 26.6667 28.9786C28.4759 30.4732 30.0492 32.2431 31.3864 34.2883C32.5664 36.1763 33.1563 38.6935 33.1563 41.84C33.1563 46.7957 31.6618 50.8469 28.6726 53.9934C25.5261 57.1399 21.6323 58.7131 16.9911 58.7131ZM63.8348 58.7131C58.8791 58.7131 54.8279 57.1399 51.6814 53.9934C48.5349 50.8469 46.9617 46.7957 46.9617 41.84C46.9617 35.547 49.5182 28.7033 54.6313 21.309C59.9017 13.836 66.9027 7.1497 75.6342 1.25L79.292 4.90782C75.9095 8.5263 73.235 11.8695 71.2684 14.9373C69.3805 17.9265 68.4366 20.365 68.4366 22.253C68.4366 23.8262 69.0659 25.1241 70.3245 26.1468C70.7178 26.5401 71.7797 27.484 73.5103 28.9786C75.3196 30.4732 76.8928 32.2431 78.2301 34.2883C79.41 36.1763 80 38.6935 80 41.84C80 46.7957 78.5054 50.8469 75.5162 53.9934C72.3697 57.1399 68.4759 58.7131 63.8348 58.7131Z\"\r\n                    \/>\r\n                <\/svg>\r\n                <div class=\"customer-review__card-text text-l\">\r\n                    <p>\u00ab Le partenariat avec Xometry pour le moulage par injection a consid\u00e9rablement am\u00e9lior\u00e9 notre efficacit\u00e9 de production et la qualit\u00e9 de nos produits, consolidant notre position de leader dans le domaine de l&rsquo;agriculture de conservation. \u00bb<\/p>\n                <\/div>\r\n                                    <div class=\"customer-review__card-footer\">\r\n                        <img decoding=\"async\" class=\"customer-review__card-logo-small\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/novag-logo.png\" alt=\"Novag\" \/>\r\n                        <h3 class=\"title title--04\">Novag<\/h3>\r\n                    <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n            <\/div>\r\n<\/section>\n\n\r\n<section class=\"materials-accordion light light-to-dark-gradient\">\r\n    <div class=\"materials-accordion__container section container\">\r\n            <div class=\"section__title-wrapper\">\r\n                    <h2 class=\"title title--02\">Options de mat\u00e9riaux : choix illimit\u00e9<\/h2>\r\n                    <div class=\"section__description\">\r\n                <p>Le moulage par injection est compatible avec une large gamme de plastiques, ce qui le rend adapt\u00e9 \u00e0 presque tous les secteurs d\u2019activit\u00e9. Nous pouvons sourcer des milliers de mat\u00e9riaux sur demande pour r\u00e9pondre \u00e0 vos contraintes techniques. S\u00e9lectionnez simplement \u00ab\u202fMat\u00e9riau personnalis\u00e9\u202f\u00bb dans le formulaire et indiquez le nom du mat\u00e9riau souhait\u00e9.<\/p>\n            <\/div>\r\n            <\/div>\r\n\r\n        <div class=\"materials-accordion__list\">\r\n                            <div class=\"materials-accordion__column materials-accordion__column_desktop\">\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_11073_21476)\">\r\n    <path d=\"M20.0009 0C10.2833 0 2.41797 7.86312 2.41797 17.5808C2.41797 23.8785 5.75359 29.6398 11.1703 32.7863L11.1694 36.4756C11.1692 37.4156 11.5352 38.2994 12.1998 38.9641C14.4279 41.1923 18.208 39.5782 18.2074 36.4755L18.2071 35.1226C20.1904 35.2529 22.1938 35.056 24.1454 34.5066V36.4837C24.1454 38.4198 25.7208 39.9949 27.6571 39.9949C29.5934 39.9949 31.1688 38.4198 31.1688 36.4837V31.1592C35.1386 27.8877 37.5838 22.9888 37.5838 17.5808C37.584 7.86406 29.7195 0 20.0009 0ZM15.5196 37.3072C14.78 38.0467 13.5129 37.5166 13.5131 36.4762C13.5134 35.6727 13.5162 24.1547 13.5163 23.4357C14.2646 23.5883 15.0662 23.5977 15.8605 23.4357L15.8638 36.4761C15.8638 36.79 15.7416 37.0852 15.5196 37.3072ZM28.8252 36.4837C28.8252 37.1276 28.3012 37.6515 27.6572 37.6515C27.0132 37.6515 26.4892 37.1276 26.4892 36.4837V28.9065C26.4892 28.2594 25.9645 27.7348 25.3173 27.7348C25.0588 27.7348 24.8486 27.5245 24.8486 27.2661V16.9724C24.8486 14.5369 26.5491 12.491 28.8252 11.9591V36.4837ZM31.1689 27.952V10.653C31.1689 10.0059 30.6442 9.48125 29.997 9.48125C25.8658 9.48125 22.5048 12.8418 22.5048 16.9725V27.2661C22.5048 28.3988 23.1781 29.3772 24.1455 29.8223V32.0566C22.2453 32.6827 20.2364 32.927 18.2066 32.7734L18.2041 22.3777C19.624 21.3084 20.544 19.6092 20.544 17.6989V10.6236C20.544 9.97648 20.0193 9.45188 19.3721 9.45188C18.7249 9.45188 18.2002 9.97648 18.2002 10.6236V17.6989C18.2002 19.2257 17.2202 20.5273 15.8565 21.0098V10.6237C15.8565 9.97656 15.3318 9.45195 14.6846 9.45195C14.0374 9.45195 13.5127 9.97656 13.5127 10.6237V21.0072C12.153 20.5226 11.1768 19.2229 11.1768 17.699V10.6237C11.1768 9.97656 10.6521 9.45195 10.0049 9.45195C9.35773 9.45195 8.83305 9.97656 8.83305 10.6237V17.699C8.83305 19.6093 9.75305 21.3085 11.173 22.3778L11.1711 30.0029C7.17453 27.1654 4.7618 22.567 4.7618 17.5809C4.76172 9.17891 11.598 2.34344 20.0009 2.34344C28.4039 2.34344 35.2402 9.17891 35.2402 17.5808C35.2402 21.4895 33.7802 25.1539 31.1689 27.952Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_11073_21476\">\r\n      <rect width=\"40\" height=\"40\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Qualit\u00e9 alimentaire<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (POLYLAC\u00ae PA-757F)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 12<\/strong>\r\n                                            (Grilamid\u00ae L 16 nat)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (LEXAN\u2122 RESIN 124R)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PEEK glass-filled (30%)<\/strong>\r\n                                            (APEXTECH-HT\u00a0330GL30)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PMMA<\/strong>\r\n                                            (POLYCASA\u00ae ACRYL G 55)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PP<\/strong>\r\n                                            (TAIRIPRO\u00ae K1011)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M35.0137 18.2125C34.0265 18.2125 33.2262 19.0128 33.2262 20.0001C33.2262 20.9873 34.0265 21.7876 35.0137 21.7876C36.001 21.7876 36.8013 20.9873 36.8013 20.0001C36.8013 19.0128 36.001 18.2125 35.0137 18.2125ZM30.8262 20.0001C30.8262 17.6873 32.701 15.8125 35.0137 15.8125C37.3264 15.8125 39.2013 17.6873 39.2013 20.0001C39.2013 22.3128 37.3264 24.1876 35.0137 24.1876C32.701 24.1876 30.8262 22.3128 30.8262 20.0001Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M32.772 28.7438C30.5472 28.7438 28.7438 30.5472 28.7438 32.772C28.7438 34.9967 30.5472 36.8002 32.772 36.8002C34.9967 36.8002 36.8002 34.9967 36.8002 32.772C36.8002 30.5472 34.9967 28.7438 32.772 28.7438ZM26.3438 32.772C26.3438 29.2218 29.2218 26.3438 32.772 26.3438C36.3222 26.3438 39.2002 29.2218 39.2002 32.772C39.2002 36.3222 36.3222 39.2002 32.772 39.2002C29.2218 39.2002 26.3438 36.3222 26.3438 32.772Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6.48211 3.20078C4.66988 3.20078 3.20078 4.66988 3.20078 6.48211C3.20078 8.29434 4.66988 9.76344 6.48211 9.76344C8.29434 9.76344 9.76344 8.29434 9.76344 6.48211C9.76344 4.66988 8.29434 3.20078 6.48211 3.20078ZM0.800781 6.48211C0.800781 3.3444 3.3444 0.800781 6.48211 0.800781C9.61982 0.800781 12.1634 3.3444 12.1634 6.48211C12.1634 9.61982 9.61982 12.1634 6.48211 12.1634C3.3444 12.1634 0.800781 9.61982 0.800781 6.48211Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M4.24145 18.9605C3.6667 18.9605 3.20078 19.4265 3.20078 20.0012C3.20078 20.576 3.6667 21.0419 4.24145 21.0419C4.81619 21.0419 5.28211 20.576 5.28211 20.0012C5.28211 19.4265 4.81619 18.9605 4.24145 18.9605ZM0.800781 20.0012C0.800781 18.101 2.34122 16.5605 4.24145 16.5605C6.14167 16.5605 7.68211 18.101 7.68211 20.0012C7.68211 21.9014 6.14167 23.4419 4.24145 23.4419C2.34122 23.4419 0.800781 21.9014 0.800781 20.0012Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M5.28125 20.0008C5.28125 19.338 5.81851 18.8008 6.48125 18.8008H12.531C13.1938 18.8008 13.731 19.338 13.731 20.0008C13.731 20.6635 13.1938 21.2008 12.531 21.2008H6.48125C5.81851 21.2008 5.28125 20.6635 5.28125 20.0008Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M26.2695 20.0008C26.2695 19.338 26.8068 18.8008 27.4695 18.8008H32.0255C32.6883 18.8008 33.2255 19.338 33.2255 20.0008C33.2255 20.6635 32.6883 21.2008 32.0255 21.2008H27.4695C26.8068 21.2008 26.2695 20.6635 26.2695 20.0008Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M30.4563 3.20078C29.8815 3.20078 29.4156 3.6667 29.4156 4.24145C29.4156 4.81619 29.8815 5.28211 30.4563 5.28211C31.031 5.28211 31.497 4.81619 31.497 4.24145C31.497 3.6667 31.031 3.20078 30.4563 3.20078ZM27.0156 4.24145C27.0156 2.34122 28.5561 0.800781 30.4563 0.800781C32.3565 0.800781 33.897 2.34122 33.897 4.24145C33.897 6.14167 32.3565 7.68211 30.4563 7.68211C28.5561 7.68211 27.0156 6.14167 27.0156 4.24145Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M9.54418 34.7203C8.96944 34.7203 8.50352 35.1862 8.50352 35.761C8.50352 36.3357 8.96944 36.8016 9.54418 36.8016C10.1189 36.8016 10.5848 36.3357 10.5848 35.761C10.5848 35.1862 10.1189 34.7203 9.54418 34.7203ZM6.10352 35.761C6.10352 33.8608 7.64395 32.3203 9.54418 32.3203C11.4444 32.3203 12.9848 33.8608 12.9848 35.761C12.9848 37.6612 11.4444 39.2016 9.54418 39.2016C7.64395 39.2016 6.10352 37.6612 6.10352 35.761Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M20.0009 13.732C16.5387 13.732 13.732 16.5387 13.732 20.0009C13.732 23.4631 16.5387 26.2698 20.0009 26.2698C23.4631 26.2698 26.2698 23.4631 26.2698 20.0009C26.2698 16.5387 23.4631 13.732 20.0009 13.732ZM11.332 20.0009C11.332 15.2132 15.2132 11.332 20.0009 11.332C24.7886 11.332 28.6698 15.2132 28.6698 20.0009C28.6698 24.7886 24.7886 28.6698 20.0009 28.6698C15.2132 28.6698 11.332 24.7886 11.332 20.0009Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M24.4335 24.4335C24.9021 23.9649 25.6619 23.9649 26.1306 24.4335L29.9242 28.2272C30.3929 28.6958 30.3929 29.4556 29.9242 29.9242C29.4556 30.3929 28.6958 30.3929 28.2272 29.9242L24.4335 26.1306C23.9649 25.6619 23.9649 24.9021 24.4335 24.4335Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.8046 8.80264C9.27323 8.33401 10.033 8.33401 10.5017 8.80264L15.5703 13.8713C16.039 14.34 16.039 15.0998 15.5703 15.5684C15.1017 16.037 14.3419 16.037 13.8733 15.5684L8.8046 10.4997C8.33597 10.0311 8.33597 9.27127 8.8046 8.80264Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M29.8814 5.10842C30.4337 5.47484 30.5843 6.21955 30.2179 6.77179L25.1297 14.4403C24.7633 14.9925 24.0186 15.1432 23.4664 14.7768C22.9141 14.4104 22.7635 13.6656 23.1299 13.1134L28.2181 5.44488C28.5845 4.89264 29.3292 4.742 29.8814 5.10842Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.5337 25.2237C17.086 25.5901 17.2366 26.3348 16.8702 26.887L11.7821 34.5555C11.4157 35.1078 10.671 35.2584 10.1187 34.892C9.56647 34.5256 9.41583 33.7809 9.78224 33.2286L14.8703 25.5601C15.2368 25.0079 15.9815 24.8572 16.5337 25.2237Z\" fill=\"#476175\"\/>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Renforc\u00e9 fibres de verre<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>PA 6<\/strong>\r\n                                            (Kingfa PA6-G15 HSBK145)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 66<\/strong>\r\n                                            (Kingfa PA66-G35 AHBK003)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC glass-filled (10%)<\/strong>\r\n                                            (Makrolon\u00ae 9417)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC glass-filled (10%)<\/strong>\r\n                                            (LEXAN\u2122 FR Resin 500R)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC glass-filled (30%)<\/strong>\r\n                                            (Bayblend\u00ae T88 GF-30)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PEEK glass-filled (30%)<\/strong>\r\n                                            (APEXTECH-HT\u00a0330GL30)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_11073_21586)\">\r\n    <path d=\"M39.469 22.5952C38.9786 21.7446 38.1867 21.1362 37.2391 20.8819C36.2914 20.6277 35.3015 20.7578 34.4512 21.249L32.2824 22.5026C31.4667 20.9182 30.2856 19.5525 28.8122 18.5057C27.2377 17.3871 25.429 16.7085 23.5253 16.5104V13.7001C23.5253 11.9899 24.3927 10.3519 25.8453 9.31839L26.3219 8.97952C26.7581 9.38004 27.291 9.68562 27.9045 9.88291C28.4255 10.0504 28.986 10.1332 29.5731 10.1332C30.7707 10.1332 32.0794 9.78852 33.3907 9.1143C36.7028 7.41153 38.0738 2.48385 38.1305 2.27492C38.2892 1.69048 37.9765 1.08135 37.4091 0.869681C37.2063 0.794047 32.4071 -0.962405 29.0945 0.740838C27.495 1.5632 26.2964 2.66356 25.6283 3.923C25.0954 4.92749 24.9341 5.96878 25.1481 6.93796L24.4866 7.40833C23.1032 8.39266 22.0932 9.77016 21.575 11.3121C21.1307 10.9526 20.6186 10.6305 20.0449 10.3569L18.9133 9.8172C19.1194 8.85482 18.9571 7.82259 18.4285 6.8263C17.7604 5.56686 16.5618 4.4665 14.9623 3.64414C11.6496 1.94098 6.85047 3.69735 6.64772 3.77298C6.08023 3.98465 5.76754 4.59378 5.9263 5.17822C5.98311 5.38716 7.35412 10.3148 10.6661 12.0175C11.9775 12.6917 13.2861 13.0365 14.4838 13.0365C15.071 13.0365 15.6314 12.9536 16.1523 12.7861C16.7761 12.5856 17.3161 12.2726 17.7563 11.8624L19.0358 12.4727C20.3791 13.1134 21.1811 14.0553 21.1811 14.9924V16.5098C17.7509 16.8696 14.6761 18.7957 12.8503 21.7502H9.59891C8.87047 21.7502 8.14101 21.9311 7.48883 22.2736L7.08948 22.4837V21.1548C7.08948 20.5075 6.56474 19.9827 5.91747 19.9827H1.21107C0.56381 19.9827 0.0390625 20.5075 0.0390625 21.1548V38.828C0.0390625 39.4752 0.56381 40 1.21107 40H5.91747C6.56474 40 7.08948 39.4752 7.08948 38.828V37.5199L12.0669 36.0247C12.3948 35.9262 12.7346 35.8762 13.0769 35.8762H22.8477C23.9169 35.8762 24.9656 35.5834 25.8806 35.0294L38.1356 27.6087C39.2619 26.9522 39.9609 25.7352 39.9609 24.4293C39.9609 23.7874 39.7908 23.1532 39.469 22.5952ZM30.1664 2.82545C30.855 2.47143 31.7058 2.34266 32.5701 2.34266C33.6157 2.34266 34.6809 2.5312 35.5009 2.7374C34.9335 4.17616 33.8419 6.24679 32.3191 7.02969C30.9423 7.73743 29.595 7.96417 28.6221 7.65132C28.1315 7.49357 27.7794 7.21205 27.5754 6.81451C26.9507 5.59609 28.0404 3.91847 30.1664 2.82545ZM15.435 10.5545C14.4622 10.8672 13.1148 10.6407 11.7379 9.93291C10.2152 9.15001 9.12347 7.07938 8.55606 5.64062C10.054 5.26417 12.3688 4.94632 13.8906 5.72876C16.0165 6.82185 17.1061 8.49939 16.4814 9.71781C16.2777 10.1153 15.9255 10.3968 15.435 10.5545ZM22.3534 18.7921C25.7079 18.7921 28.7685 20.7202 30.2498 23.6775L26.4516 25.9499C25.9056 26.2771 25.2823 26.4495 24.6467 26.4495C24.6346 26.4495 24.6224 26.4494 24.6103 26.4493C24.6057 26.4493 24.6013 26.4493 24.5967 26.4493L22.1841 26.4522C22.3141 26.0848 22.3855 25.6899 22.3855 25.2785C22.3855 23.3329 20.8041 21.7501 18.8603 21.7501H15.7614C17.4159 19.8898 19.7991 18.7921 22.3534 18.7921ZM4.74546 37.656H2.38308V22.3268H4.74546V37.656ZM36.9514 25.5859C36.9446 25.5899 36.9378 25.5939 36.931 25.598L24.6664 33.0244C24.1178 33.3566 23.4888 33.5323 22.8477 33.5323H13.0769C12.506 33.5323 11.9393 33.6156 11.3926 33.7798L7.08948 35.0725V25.1323L8.57958 24.3482C8.89618 24.1819 9.24864 24.094 9.59891 24.094H18.8601C19.5115 24.094 20.0413 24.6253 20.0413 25.2784C20.0413 25.8894 19.5775 26.3936 18.9844 26.4561L13.5639 26.4629C12.9166 26.4636 12.3926 26.989 12.3934 27.6364C12.3942 28.2832 12.9188 28.807 13.5654 28.8069H13.5669L24.5927 28.7932C25.6703 28.8037 26.7306 28.5152 27.6564 27.9605L35.6239 23.2784C35.9312 23.101 36.2889 23.0539 36.6315 23.1457C36.9743 23.2376 37.2608 23.4579 37.4384 23.7659C37.5551 23.9684 37.6168 24.1978 37.6168 24.4292C37.6169 24.9053 37.3619 25.3484 36.9514 25.5859Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_11073_21586\">\r\n      <rect width=\"40\" height=\"40\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Biod\u00e9gradable<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>PLA<\/strong>\r\n                                            (Anbio BG4400)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PLA<\/strong>\r\n                                            (GS Pla\u00ae AD92W)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_12178_12382)\">\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-0.0625 31.0625C-0.0625 31.6148 0.385215 32.0625 0.9375 32.0625H31.0573C31.6095 32.0625 32.0573 31.6148 32.0573 31.0625V26.4513C32.0573 25.899 31.6095 25.4513 31.0573 25.4513H0.9375C0.385215 25.4513 -0.0625 25.899 -0.0625 26.4513V31.0625ZM1.9375 30.0625V27.4513H30.0573V30.0625H1.9375Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.3095 31.9842C7.81866 31.7702 8.058 31.184 7.84406 30.6749L5.90656 26.0636C5.69263 25.5545 5.10644 25.3151 4.59727 25.5291C4.0881 25.743 3.84877 26.3292 4.06271 26.8384L6.00021 31.4496C6.21414 31.9588 6.80033 32.1981 7.3095 31.9842Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.3329 31.9842C12.8421 31.7702 13.0814 31.184 12.8675 30.6749L10.93 26.0636C10.7161 25.5545 10.1299 25.3151 9.62071 25.5291C9.11154 25.743 8.87221 26.3292 9.08615 26.8384L11.0236 31.4496C11.2376 31.9588 11.8238 32.1981 12.3329 31.9842Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M17.3486 31.9842C17.8577 31.7702 18.0971 31.184 17.8831 30.6749L15.9456 26.0636C15.7317 25.5545 15.1455 25.3151 14.6363 25.5291C14.1272 25.743 13.8878 26.3292 14.1018 26.8384L16.0393 31.4496C16.2532 31.9588 16.8394 32.1981 17.3486 31.9842Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M22.372 31.9842C22.8812 31.7702 23.1205 31.184 22.9066 30.6749L20.9691 26.0636C20.7551 25.5545 20.1689 25.3151 19.6598 25.5291C19.1506 25.743 18.9113 26.3292 19.1252 26.8384L21.0627 31.4496C21.2766 31.9588 21.8628 32.1981 22.372 31.9842Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M27.3876 31.9842C27.8968 31.7702 28.1361 31.184 27.9222 30.6749L25.9847 26.0636C25.7708 25.5545 25.1846 25.3151 24.6754 25.5291C24.1662 25.743 23.9269 26.3292 24.1408 26.8384L26.0783 31.4496C26.2923 31.9588 26.8785 32.1981 27.3876 31.9842Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.0147 27.4512C16.2799 27.4512 16.5343 27.3458 16.7218 27.1583L23.771 20.109C24.0519 19.8282 24.1399 19.4079 23.9954 19.038C23.8508 18.6681 23.5011 18.4188 23.1043 18.4027L20.0568 18.2796C19.505 18.2573 19.0395 18.6866 19.0173 19.2384C18.995 19.7903 19.4242 20.2557 19.9761 20.278L20.7427 20.309L16.0147 25.037L10.2774 19.2997C9.8869 18.9092 9.25373 18.9092 8.86321 19.2997C8.47268 19.6902 8.47268 20.3234 8.86321 20.7139L15.3076 27.1583C15.4951 27.3458 15.7495 27.4512 16.0147 27.4512Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M23.0625 23.2109C23.6148 23.2109 24.0625 22.7632 24.0625 22.2109V19.4019C24.0625 18.8497 23.6148 18.4019 23.0625 18.4019C22.5102 18.4019 22.0625 18.8497 22.0625 19.4019V22.2109C22.0625 22.7632 22.5102 23.2109 23.0625 23.2109Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M9.06633 15.3555C9.45685 15.7461 10.09 15.7461 10.4805 15.3555L13.3059 12.5302C13.6964 12.1396 13.6964 11.5065 13.3059 11.116C12.9154 10.7254 12.2822 10.7254 11.8917 11.116L9.06633 13.9413C8.67581 14.3319 8.67581 14.965 9.06633 15.3555Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M10.2812 8.49744C10.2812 11.722 12.8953 14.3359 16.1197 14.3359C19.3443 14.3359 21.9583 11.722 21.9583 8.49744C21.9583 5.2729 19.3443 2.65888 16.1197 2.65888C12.8953 2.65888 10.2812 5.27291 10.2812 8.49744ZM16.1197 12.3359C13.9998 12.3359 12.2812 10.6174 12.2812 8.49744C12.2812 6.37746 13.9999 4.65888 16.1197 4.65888C18.2397 4.65888 19.9583 6.37747 19.9583 8.49744C19.9583 10.6174 18.2397 12.3359 16.1197 12.3359Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.1094 17.0234C16.6617 17.0234 17.1094 16.5757 17.1094 16.0234V13.3353C17.1094 12.783 16.6617 12.3352 16.1094 12.3352C15.5571 12.3352 15.1094 12.783 15.1094 13.3353V16.0234C15.1094 16.5757 15.5571 17.0234 16.1094 17.0234Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18.9335 5.88679C19.324 6.27732 19.9572 6.27732 20.3477 5.88679L23.1569 3.07767C23.5474 2.68715 23.5474 2.05398 23.1569 1.66346C22.7663 1.27293 22.1332 1.27293 21.7426 1.66346L18.9335 4.47258C18.543 4.8631 18.543 5.49627 18.9335 5.88679Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.1094 4.66211C16.6617 4.66211 17.1094 4.21439 17.1094 3.66211V1.00092C17.1094 0.448637 16.6617 0.000922203 16.1094 0.000922203C15.5571 0.000922203 15.1094 0.448637 15.1094 1.00092V3.66211C15.1094 4.21439 15.5571 4.66211 16.1094 4.66211Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M13.2963 5.89461C13.6868 5.50408 13.6868 4.87092 13.2963 4.48039L10.4805 1.66464C10.09 1.27412 9.45685 1.27412 9.06633 1.66464C8.67581 2.05517 8.67581 2.68833 9.06633 3.07886L11.8821 5.89461C12.2726 6.28513 12.9058 6.28513 13.2963 5.89461Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M23.1575 15.3555C23.548 14.965 23.548 14.3319 23.1575 13.9413L20.3321 11.116C19.9416 10.7254 19.3084 10.7254 18.9179 11.116C18.5274 11.5065 18.5274 12.1396 18.9179 12.5302L21.7433 15.3555C22.1338 15.7461 22.767 15.7461 23.1575 15.3555Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.1875 8.49805C7.1875 9.05033 7.63522 9.49805 8.1875 9.49805H11.2783C11.8306 9.49805 12.2783 9.05033 12.2783 8.49805C12.2783 7.94576 11.8306 7.49805 11.2783 7.49805H8.1875C7.63522 7.49805 7.1875 7.94576 7.1875 8.49805Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M19.9531 8.49805C19.9531 9.05033 20.4008 9.49805 20.9531 9.49805H23.8138C24.3661 9.49805 24.8138 9.05033 24.8138 8.49805C24.8138 7.94576 24.3661 7.49805 23.8138 7.49805H20.9531C20.4008 7.49805 19.9531 7.94576 19.9531 8.49805Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_12178_12382\">\r\n      <rect width=\"32\" height=\"32\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>R\u00e9sistant aux UV<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (CYCOLAC\u2122 Resin FR15U)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>HDPE<\/strong>\r\n                                            (DOW\u2122 HDPE\u00a0KT 10000 UE)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>HDPE<\/strong>\r\n                                            (ExxonMobil\u2122 HDPE HMA 016)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 66 glass-filled (30%)<\/strong>\r\n                                            (Zytel\u00ae 74G33W NC010)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (Makrolon\u00ae 6557)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PP<\/strong>\r\n                                            (Kingfa AP-202W)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                    <\/div>\r\n                            <div class=\"materials-accordion__column materials-accordion__column_desktop\">\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_12181_12535)\">\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M20.0008 40.0273C11.5715 40.0273 4.73828 33.194 4.73828 24.764C4.73854 20.9176 6.85157 17.3804 8.88454 14.6698C11.0191 11.8237 11.5742 8.55637 11.5742 5.93673C11.5742 4.63257 11.4363 3.51108 11.2989 2.71891C11.2303 2.32361 11.1623 2.01255 11.1126 1.80436L11.037 1.5097L11.0365 1.50793C10.9069 1.06461 11.0432 0.586155 11.3871 0.277714C11.7315 -0.0311394 12.2228 -0.114517 12.6498 0.0634079C12.7572 0.108162 15.6525 1.40437 18.4718 4.43608C20.8208 6.96189 23.1151 10.6945 23.6913 15.8678C23.7381 16.2882 23.7736 16.718 23.7968 17.1576C24.4433 16.5507 25.0128 15.7561 25.5038 14.8735C25.7417 14.446 25.9611 13.9978 26.1619 13.5403C26.6057 12.5295 26.9219 11.5584 27.1272 10.8375C27.2295 10.4784 27.3034 10.1846 27.3511 9.98308C27.375 9.88241 27.3923 9.80501 27.4033 9.75428L27.418 9.68493C27.5103 9.22499 27.8622 8.86099 28.3188 8.7532C28.7757 8.64534 29.2535 8.81381 29.5418 9.18437L29.6159 9.28197C29.6604 9.34122 29.7237 9.42672 29.8031 9.53694C29.9619 9.75731 30.1855 10.0769 30.4523 10.4834C30.9853 11.2956 31.6937 12.4595 32.4022 13.8766C33.8103 16.6928 35.2633 20.5963 35.2633 24.7648C35.2633 33.1941 28.43 40.0273 20.0008 40.0273ZM20.2452 37.6774C13.1415 37.6774 7.38273 31.9187 7.38269 24.8141C7.38269 24.8141 7.13828 20.3178 11.5 15C14.3936 11.4721 14 3.5 14 3.5C14 3.5 17.5 5.5 20 11C21.2661 13.7853 21.5019 15.5678 21.5245 17.0564C21.5305 17.4494 21.5216 17.8218 21.5129 18.1869L21.5117 18.2381C21.5056 18.494 21.5 18.7464 21.5 19C21.5 21 23.5 20.5 24 20C28 17 29.2868 12.7983 29.2868 12.7983C29.6628 13.4207 30.0814 14.1628 30.5 15C31.8263 17.6525 33.1077 21.1709 33.1077 24.8149C33.1077 31.9186 27.3489 37.6774 20.2452 37.6774Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M20.0008 40.0273C15.4547 40.0273 11.7695 36.3421 11.7695 31.7957C11.7696 29.666 12.9323 27.7624 13.9627 26.3886C14.9273 25.1024 15.1875 23.63 15.1875 22.4211C15.1875 21.8213 15.1231 21.3065 15.0593 20.9451C15.0275 20.7651 14.9963 20.6255 14.9743 20.5349L14.944 20.4183C14.8171 19.9903 14.9384 19.5271 15.259 19.2161C15.5805 18.9041 16.049 18.7973 16.474 18.9389L16.6661 19.0192C16.7192 19.0441 16.7915 19.0792 16.8803 19.1251C17.0576 19.2168 17.3015 19.3519 17.5891 19.5348C18.1627 19.8995 18.9204 20.461 19.6701 21.2562C20.7836 22.4373 21.8693 24.1267 22.3096 26.4073C22.3864 26.2603 22.4606 26.1051 22.532 25.9426C22.7399 25.469 22.8894 25.0105 22.9869 24.6681L23.1213 24.137C23.214 23.6776 23.5657 23.314 24.022 23.2063C24.4788 23.0985 24.9567 23.2669 25.2449 23.6375L25.3887 23.8314C25.4727 23.948 25.5896 24.115 25.7282 24.3262C26.0048 24.7477 26.3714 25.3502 26.7382 26.0837C27.4627 27.5327 28.232 29.5807 28.232 31.7961C28.232 36.3421 24.5468 40.0273 20.0008 40.0273ZM20.0008 37.6273C16.7803 37.6273 14.1696 35.0167 14.1695 31.7958C14.1695 31.7958 14.007 30.2496 16.332 27.1823C17.2892 25.9194 17.5891 22.4211 17.5891 22.4211C17.5891 22.4211 19.8457 24.6681 20 27C20.036 27.5434 20.0218 28.0582 20.0099 28.4896C20.0047 28.677 20 28.8486 20 29C20 30.5 21.575 30.1417 22 30C23.5 29.5 24.6042 27.1823 24.6042 27.1823C25.242 28.4642 25.832 30.1164 25.832 31.7961C25.832 35.0166 23.2213 37.6273 20.0008 37.6273Z\" fill=\"#476175\"\/>\r\n    <path d=\"M35.625 2.34375C35.625 2.99094 35.1003 3.51562 34.4531 3.51562C33.8059 3.51562 33.2812 2.99094 33.2812 2.34375C33.2812 1.69656 33.8059 1.17188 34.4531 1.17188C35.1003 1.17188 35.625 1.69656 35.625 2.34375Z\" fill=\"#476175\"\/>\r\n    <path d=\"M24.5518 1C23.1447 1 22 2.14477 22 3.55188C22 4.95898 23.1448 6.10375 24.5518 6.10375C25.9588 6.10375 27.1037 4.95898 27.1037 3.55188C27.1037 2.14477 25.9589 1 24.5518 1ZM24.5518 4.75773C23.8858 4.75773 23.3459 4.21785 23.3459 3.55188C23.3459 2.8859 23.8858 2.34602 24.5518 2.34602C25.2178 2.34602 25.7577 2.8859 25.7577 3.55188C25.7577 4.21785 25.2178 4.75773 24.5518 4.75773Z\" fill=\"#476175\"\/>\r\n    <path d=\"M4.375 7.1875C4.375 7.83469 4.89969 8.35938 5.54688 8.35938C6.19406 8.35938 6.71875 7.83469 6.71875 7.1875C6.71875 6.54031 6.19406 6.01562 5.54688 6.01562C4.89969 6.01562 4.375 6.54031 4.375 7.1875Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_12181_12535\">\r\n      <rect width=\"40\" height=\"40\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Ignifuge (UL 94 V-0 ou sup\u00e9rieur)<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (CYCOLAC\u2122 Resin FR15U)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (POLYLAC\u00ae PA-765A)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 66 glass-filled (35%)<\/strong>\r\n                                            (Ultramid\u00ae A3X2G7)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (Makrolon\u00ae 6557)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC glass-filled (10%)<\/strong>\r\n                                            (Makrolon\u00ae 9417)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC glass-filled (10%)<\/strong>\r\n                                            (LEXAN\u2122 FR Resin 500R)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC-ABS<\/strong>\r\n                                            (Bayblend\u00ae FR3008)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC-ASA<\/strong>\r\n                                            (LUPOY EU5000FS)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>Teflon <\/strong>\r\n                                            (PFA 440 HPB)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>TPV<\/strong>\r\n                                            (SantopreneTM 251-70W232)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M25.7623 5.72859V23.1022C28.0851 24.872 29.454 27.6251 29.4541 30.5904C29.4541 35.7789 25.2329 40 20.0445 40C14.8559 40 10.6348 35.7789 10.6348 30.5903C10.6348 27.6566 11.9964 24.9109 14.3051 23.1331V5.72859C14.3051 2.56984 16.8748 0 20.0337 0C23.1925 0 25.7623 2.56984 25.7623 5.72859ZM12.9808 30.5904C12.9808 34.4853 16.1495 37.6541 20.0445 37.6541C23.9393 37.6541 27.108 34.4853 27.108 30.5904C27.108 28.1982 25.9253 25.9912 23.9441 24.6863C23.5981 24.4584 23.4132 24.0788 23.4173 23.6931C23.4172 23.6903 23.417 23.6876 23.4168 23.6848C23.4166 23.6817 23.4164 23.6786 23.4164 23.6754V5.72859C23.4164 3.86336 21.8989 2.34594 20.0338 2.34594C18.1686 2.34594 16.6511 3.86336 16.6511 5.72859V8.14789V10.4938V11.2513V13.5973V14.398V16.7439V23.6755C16.6511 23.862 16.6064 24.0376 16.529 24.1941C16.4449 24.4057 16.2988 24.5953 16.0959 24.7324C14.1453 26.0502 12.9808 28.2401 12.9808 30.5904Z\" fill=\"#476175\"\/>\r\n  <path d=\"M21.2171 26.1547V5.64172C21.2171 4.99391 20.692 4.46875 20.0441 4.46875C19.3963 4.46875 18.8712 4.99391 18.8712 5.64172V26.1491C16.8456 26.6674 15.3438 28.508 15.3438 30.6928C15.3438 33.2788 17.4476 35.3827 20.0335 35.3827C22.6195 35.3827 24.7233 33.2788 24.7233 30.6928C24.7232 28.5156 23.2319 26.6805 21.2171 26.1547ZM20.0334 33.0366C18.7411 33.0366 17.6896 31.9852 17.6896 30.6927C17.6896 29.4003 18.7411 28.3489 20.0334 28.3489C21.3258 28.3489 22.3773 29.4003 22.3773 30.6927C22.3773 31.9852 21.3259 33.0366 20.0334 33.0366Z\" fill=\"#476175\"\/>\r\n  <path d=\"M9.5518 12C8.14469 12 7 13.1448 7 14.5519C7 15.959 8.14477 17.1037 9.5518 17.1037C10.9588 17.1037 12.1037 15.959 12.1037 14.5519C12.1037 13.1448 10.9589 12 9.5518 12ZM9.5518 15.7577C8.88582 15.7577 8.34594 15.2179 8.34594 14.5519C8.34594 13.8859 8.88582 13.346 9.5518 13.346C10.2178 13.346 10.7577 13.8859 10.7577 14.5519C10.7577 15.2179 10.2178 15.7577 9.5518 15.7577Z\" fill=\"#476175\"\/>\r\n  <path d=\"M35.7884 9C34.2509 9 33 10.2509 33 11.7884C33 13.3259 34.2509 14.5767 35.7884 14.5767C37.3259 14.5767 38.5767 13.3259 38.5767 11.7884C38.5767 10.2509 37.3259 9 35.7884 9ZM35.7884 12.2309C35.5444 12.2309 35.3459 12.0325 35.3459 11.7885C35.3459 11.5445 35.5444 11.3461 35.7884 11.3461C36.0323 11.3461 36.2308 11.5445 36.2308 11.7885C36.2309 12.0325 36.0323 12.2309 35.7884 12.2309Z\" fill=\"#476175\"\/>\r\n  <path d=\"M30.7354 2C29.3283 2 28.1836 3.14477 28.1836 4.55188C28.1836 5.95898 29.3284 7.10375 30.7354 7.10375C32.1424 7.10375 33.2873 5.95898 33.2873 4.55188C33.2873 3.14477 32.1425 2 30.7354 2ZM30.7354 5.75773C30.0694 5.75773 29.5295 5.21785 29.5295 4.55188C29.5295 3.8859 30.0694 3.34602 30.7354 3.34602C31.4014 3.34602 31.9413 3.8859 31.9413 4.55188C31.9413 5.21785 31.4014 5.75773 30.7354 5.75773Z\" fill=\"#476175\"\/>\r\n  <path d=\"M33.9784 18.4701H33.197V17.6886C33.197 17.0408 32.6718 16.5156 32.024 16.5156C31.3762 16.5156 30.851 17.0408 30.851 17.6886V18.4701H30.0695C29.4216 18.4701 28.8965 18.9952 28.8965 19.643C28.8965 20.2909 29.4216 20.816 30.0695 20.816H30.8509V21.5975C30.8509 22.2453 31.3761 22.7705 32.0239 22.7705C32.6717 22.7705 33.1969 22.2453 33.1969 21.5975V20.816H33.9784C34.6262 20.816 35.1513 20.2909 35.1513 19.643C35.1513 18.9952 34.6262 18.4701 33.9784 18.4701Z\" fill=\"#476175\"\/>\r\n  <path d=\"M8.08734 3.41883H7.84141V3.17297C7.84141 2.52516 7.31625 2 6.66844 2C6.02062 2 5.49547 2.52516 5.49547 3.17297V3.41883H5.17297C4.52516 3.41883 4 3.94398 4 4.5918C4 5.23961 4.52516 5.76477 5.17297 5.76477H5.49547V6.08727C5.49547 6.73508 6.02062 7.26023 6.66844 7.26023C7.31625 7.26023 7.84141 6.73508 7.84141 6.08727V5.76477H8.08734C8.73516 5.76477 9.26031 5.23961 9.26031 4.5918C9.26031 3.94398 8.73523 3.41883 8.08734 3.41883Z\" fill=\"#476175\"\/>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>R\u00e9sistant \u00e0 la chaleur<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (Kingfa FW-612 TC)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (LG ABS LG703W)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 6<\/strong>\r\n                                            (Kingfa PA6-G15 HSBK145)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PEEK glass-filled (30%)<\/strong>\r\n                                            (APEXTECH-HT\u00a0330GL30)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PEI<\/strong>\r\n                                            (LNP\u2122 THERMOCOMP\u2122 Compound EC006AQW)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_12181_12514)\">\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M17.9573 0C17.3021 0 16.7709 0.536504 16.7709 1.19831V4.68092H13.3228C12.6675 4.68092 12.1363 5.21742 12.1363 5.87923V10.5601C12.1363 11.0294 12.4034 11.4357 12.7923 11.6323C12.952 11.713 13.1321 11.7585 13.3228 11.7585H16.7709V15.2411C16.7709 15.9029 17.3021 16.4394 17.9573 16.4394H22.5919C22.742 16.4394 22.8855 16.4113 23.0176 16.3599L23.682 15.715C23.744 15.5696 23.7784 15.4094 23.7784 15.2411V11.7585H27.2265C27.8818 11.7585 28.413 11.222 28.413 10.5601V6.12562V5.87923C28.413 5.21742 27.8818 4.68092 27.2265 4.68092H23.7784V1.19831C23.7784 0.536504 23.2472 0 22.5919 0H17.9573ZM19.1438 2.39663V5.87923C19.1438 6.54104 18.6126 7.07755 17.9573 7.07755H14.5092V9.36183H17.9573C18.2077 9.36183 18.44 9.44017 18.6314 9.5739C18.941 9.79014 19.1438 10.1512 19.1438 10.5601V14.0428H21.4055V10.5601C21.4055 9.89834 21.9367 9.36183 22.5919 9.36183H26.0401V7.07755H25.7127H22.5919C21.9367 7.07755 21.4055 6.54104 21.4055 5.87923V2.39663H19.1438Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.2777 6.81291C7.27793 4.85658 5.70781 3.27763 3.77529 3.27665C1.84277 3.27566 1.72634 3.5299 0.989284 4.19332C0.252224 4.85674 0.000238803 5.69122 0.000570943 6.67422C-0.000508512 11.1835 0.000208185 13.9803 0.000570943 18.673C0.000208185 21.4698 0.772493 22.0762 1.48364 23.2838C2.4531 25.076 4.09256 27.8009 4.09256 27.8009L5.67683 30.544V32.9225H4.826C4.17074 32.9225 3.63955 33.459 3.63955 34.1208V38.8017C3.63955 39.4635 4.17074 40 4.826 40H35.7233C36.3785 40 36.9097 39.4635 36.9097 38.8017V34.1208C36.9097 33.459 36.3785 32.9225 35.7233 32.9225H34.593V30.544L38.7862 23.2838C39.5811 21.9074 40 20.3424 40 18.749V6.81542C40 4.86037 38.4303 3.27562 36.4945 3.27665C35.6706 3.27706 34.9125 3.56431 34.314 4.04536C33.5419 4.66581 33.0352 5.60864 32.9947 6.67422C32.993 6.72022 32.9921 6.76646 32.9921 6.81291L32.9925 13.4775C31.6634 13.0207 30.1353 13.4021 29.1788 14.5535L23.7753 21.0576C22.312 22.8189 21.5098 25.0447 21.5098 27.344V32.9225H19.0411V27.344C19.0411 25.3758 18.1733 23.4615 17.0863 21.8463C16.9034 21.5745 16.7063 21.3112 16.4956 21.0576L11.0921 14.5535C10.1353 13.4018 8.60669 13.0205 7.27735 13.4778L7.2777 6.81291ZM3.774 5.67327C3.14938 5.67293 2.64272 6.18429 2.64272 6.81542V18.749C2.64272 19.9181 2.95007 21.0664 3.53331 22.0762L7.88812 29.6162C7.99397 29.7995 8.04974 30.0078 8.04974 30.22V30.6188V32.9225H16.6682V27.344C16.6682 25.9962 16.0231 24.6818 15.3426 23.539C15.1468 23.21 14.9248 22.8953 14.6778 22.5981L9.27431 16.094C8.8731 15.6111 8.16023 15.5478 7.68178 15.9529C7.20301 16.3582 7.14034 17.0789 7.54194 17.5623L12.3508 23.3498C12.7721 23.8568 12.7067 24.6126 12.2047 25.0381C11.7028 25.4635 10.9544 25.3974 10.5332 24.8905L5.72427 19.1029C5.16571 18.4306 4.89692 17.6101 4.90453 16.7963L4.9044 16.7784L4.90479 6.81263C4.90486 6.18404 4.40082 5.67358 3.774 5.67327ZM32.9925 16.7796C32.9794 16.4703 32.8426 16.1675 32.5892 15.953C32.1107 15.5479 31.3978 15.6111 30.9966 16.094L25.593 22.5981C24.4883 23.9279 23.8827 25.6082 23.8827 27.344V32.9225H32.2201V30.22C32.2201 30.0078 32.2758 29.7995 32.3817 29.6162L36.7365 22.0762C37.3197 21.0664 37.6271 19.9181 37.6271 18.749V6.81542C37.6271 6.18429 37.1204 5.67293 36.4958 5.67327C35.869 5.67358 35.3649 6.18403 35.365 6.81262L35.3654 16.7413C35.3859 17.573 35.1178 18.4155 34.5466 19.1029L29.7377 24.8905C29.3165 25.3974 28.5681 25.4635 28.0662 25.0381C27.5642 24.6126 27.4988 23.8568 27.92 23.3498L32.7289 17.5623C32.9067 17.3484 32.9935 17.088 32.9935 16.8291C32.9931 16.8193 32.9929 16.8095 32.9927 16.7997L32.9925 16.7796ZM21.4611 35.3191V37.6034H34.5368V35.3191H21.4611ZM19.0882 37.6034V35.3191H17.8547H17.8536H6.01246V37.6034H19.0882Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_12181_12514\">\r\n      <rect width=\"40\" height=\"40\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Qualit\u00e9 m\u00e9dicale<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (LNP\u2122 STAT-KON\u2122 Compound AX02747)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 12<\/strong>\r\n                                            (Grilamid\u00ae L 16 nat)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PBT<\/strong>\r\n                                            (LNP\u2122 ELCRIN\u2122 W1000JiQ)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (LEXAN\u2122 HEALTHCARE RESIN HPS1)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PEI<\/strong>\r\n                                            (LNP\u2122 THERMOCOMP\u2122 Compound EC006AQW)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PMMA<\/strong>\r\n                                            (POLYCASA\u00ae ACRYL G 55)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>POM<\/strong>\r\n                                            (LNP\u2122 LUBRICOMP\u2122 Compound KL004)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_12181_12420)\">\r\n    <path d=\"M4.48029 29.8865L5.40216 30.6547C5.29522 30.783 5.19743 30.9144 5.10852 31.0483L4.48029 29.8865Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.68146 40.0562C3.02739 40.0562 -0.0611618 33.4618 3.55843 29.1183L15.3367 14.9843V5.8875C15.3367 5.22476 15.874 4.6875 16.5367 4.6875H24.3492C25.0119 4.6875 25.5492 5.22476 25.5492 5.8875V14.9843L37.3275 29.1183C40.9471 33.4618 37.8585 40.0562 32.2044 40.0562H8.68146ZM5.40216 30.6547L4.48029 29.8865L5.10852 31.0483C3.27119 33.8157 5.2293 37.6562 8.68146 37.6562H32.2044C35.8236 37.6562 37.8007 33.4351 35.4837 30.6547L23.4273 16.187C23.2476 15.9713 23.1492 15.6995 23.1492 15.4187V7.0875H17.7367V15.4187C17.7367 15.6995 17.6383 15.9713 17.4586 16.187L5.40216 30.6547Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.5367 4.6875C15.9051 4.6875 15.3929 4.17538 15.3929 3.54375C15.3929 2.91212 15.9051 2.4 16.5367 2.4H24.3492C24.9808 2.4 25.4929 2.91212 25.4929 3.54375C25.4929 4.17538 24.9808 4.6875 24.3492 4.6875H16.5367ZM12.9929 3.54375C12.9929 5.50087 14.5796 7.0875 16.5367 7.0875H24.3492C26.3063 7.0875 27.8929 5.50087 27.8929 3.54375C27.8929 1.58663 26.3063 0 24.3492 0H16.5367C14.5796 0 12.9929 1.58663 12.9929 3.54375Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M10.6766 31.209C9.59051 33.0469 10.9153 35.3687 13.0503 35.3687H27.8356C29.9706 35.3687 31.2954 33.0469 30.2093 31.209L22.8166 18.6983C21.7495 16.8923 19.1364 16.8922 18.0693 18.6983M18.0693 18.6983L10.6766 31.209L18.0693 18.6983ZM13.0503 32.9687C12.7737 32.9687 12.6021 32.668 12.7428 32.4299L20.1355 19.9192C20.2737 19.6853 20.6122 19.6853 20.7504 19.9192L28.1431 32.4299C28.2838 32.668 28.1122 32.9687 27.8356 32.9687H13.0503Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M23.6113 24.6378C23.7491 25.286 24.3864 25.6998 25.0346 25.562C25.6633 25.4284 26.1922 25.2878 26.6995 25.153C27.8929 24.836 28.9669 24.5506 30.9398 24.4608C31.6019 24.4306 32.1141 23.8694 32.084 23.2074C32.0538 22.5453 31.4927 22.0331 30.8306 22.0632C28.5855 22.1655 27.1765 22.5388 25.9073 22.8752C25.4427 22.9983 24.9968 23.1164 24.5355 23.2145C23.8873 23.3523 23.4735 23.9895 23.6113 24.6378Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M17.2746 24.6379C17.4124 23.9896 16.9987 23.3524 16.3504 23.2145C15.8892 23.1164 15.4434 22.9983 14.9789 22.8752C13.7096 22.5389 12.3006 22.1655 10.0553 22.0633C9.3932 22.0331 8.83206 22.5454 8.80192 23.2074C8.77177 23.8695 9.28404 24.4306 9.9461 24.4608C11.9191 24.5506 12.9933 24.836 14.1867 25.1531C14.6939 25.2879 15.2227 25.4284 15.8512 25.562C16.4995 25.6999 17.1367 25.2861 17.2746 24.6379Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M20.4429 28.7281C21.1057 28.7281 21.643 28.1909 21.643 27.5281V23.6219C21.643 22.9591 21.1057 22.4219 20.4429 22.4219C19.7802 22.4219 19.2429 22.9591 19.2429 23.6219V27.5281C19.2429 28.1909 19.7802 28.7281 20.4429 28.7281Z\" fill=\"#476175\"\/>\r\n    <path d=\"M21.4195 30.4578C21.4195 30.9971 20.9822 31.4344 20.4429 31.4344C19.9037 31.4344 19.4664 30.9971 19.4664 30.4578C19.4664 29.9185 19.9037 29.4812 20.4429 29.4812C20.9822 29.4812 21.4195 29.9185 21.4195 30.4578Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_12181_12420\">\r\n      <rect width=\"40\" height=\"40\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Conforme RoHS<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (Axpoly\u00ae ABS52 1007)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 12<\/strong>\r\n                                            (Grilamid\u00ae L 16 nat)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 66 glass-filled (35%)<\/strong>\r\n                                            (Ultramid\u00ae A3X2G7)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (POLYLAC\u00ae PA-757)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PP<\/strong>\r\n                                            (SEETEC PP H1500)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>TPV<\/strong>\r\n                                            (SantopreneTM 101-64)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                    <\/div>\r\n                            <div class=\"materials-accordion__column materials-accordion__column_desktop\">\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"34\" height=\"34\" viewBox=\"0 0 34 34\" fill=\"none\">\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.46875 13.2344C8.46875 20.0257 13.9743 25.5312 20.7656 25.5312H20.7656C27.557 25.5312 33.0625 20.0257 33.0625 13.2343C33.0625 6.44296 27.5568 0.937435 20.7656 0.937435C13.9743 0.937435 8.46875 6.44296 8.46875 13.2344ZM20.7656 23.5312C15.0789 23.5312 10.4688 18.9211 10.4688 13.2344C10.4688 7.54753 15.0789 2.93744 20.7656 2.93744C26.4523 2.93744 31.0625 7.54754 31.0625 13.2343C31.0625 18.9211 26.4525 23.5312 20.7656 23.5312\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M4.53924 29.4609C9.34146 34.263 17.1273 34.263 21.9295 29.4609L21.2224 28.7538L21.9295 29.4609C26.7316 24.6587 26.7317 16.8727 21.9295 12.0706C21.9295 12.0706 21.9295 12.0706 21.9295 12.0706M4.53923 29.4609C-0.26298 24.6589 -0.263178 16.8727 4.53924 12.0704C9.34145 7.2682 17.1275 7.26841 21.9295 12.0706M20.5153 28.0467C16.4941 32.0678 9.9746 32.0678 5.95344 28.0467L5.95343 28.0467C1.93228 24.0257 1.9321 17.5059 5.95343 13.4846L5.24634 12.7775L5.95344 13.4846C9.97459 9.46349 16.4943 9.46365 20.5153 13.4848L20.5153 13.4848C24.5364 17.5059 24.5364 24.0255 20.5153 28.0467Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.96477 27.4884C3.35529 27.8789 3.98846 27.8789 4.37898 27.4884L19.9589 11.9084C20.3494 11.5179 20.3494 10.8847 19.9589 10.4942C19.5683 10.1037 18.9352 10.1037 18.5446 10.4942L2.96477 26.0741C2.57424 26.4647 2.57424 27.0978 2.96477 27.4884Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.24602 22.1036C1.63654 22.4941 2.26971 22.4941 2.66023 22.1036L14.5678 10.196C14.9583 9.8055 14.9583 9.17234 14.5678 8.78182C14.1773 8.39129 13.5441 8.39129 13.1536 8.78182L1.24602 20.6894C0.855494 21.0799 0.855494 21.7131 1.24602 22.1036Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6.51163 31.0411C6.90214 31.4316 7.53531 31.4316 7.92584 31.0411L23.5063 15.4614C23.8968 15.0708 23.8968 14.4377 23.5063 14.0471C23.1158 13.6566 22.4826 13.6566 22.0921 14.0471L6.51166 29.6269C6.12113 30.0174 6.12111 30.6505 6.51163 31.0411Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M11.9023 32.7481C12.2928 33.1386 12.926 33.1386 13.3165 32.7481L25.224 20.8406C25.6146 20.4501 25.6146 19.8169 25.224 19.4264C24.8335 19.0359 24.2004 19.0359 23.8098 19.4264L11.9023 31.3339C11.5117 31.7244 11.5117 32.3576 11.9023 32.7481Z\" fill=\"#476175\"\/>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Clair\/transparent<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (Kingfa FW-612 TC)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 66<\/strong>\r\n                                            (Kingfa PA66-G35 AHBK003)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (LEXAN\u2122 HEALTHCARE RESIN HPS1)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (Makrolon\u00ae 6557)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PMMA<\/strong>\r\n                                            (POLYCASA\u00ae ACRYL G 55)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PP<\/strong>\r\n                                            (TAIRIPRO\u00ae K1011)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_11073_21576)\">\r\n    <path d=\"M17.0066 34.5406L13.9985 32.5891C13.4558 32.2368 12.7301 32.3914 12.3777 32.9343C12.0473 33.4438 12.1631 34.114 12.6271 34.4857H4.25633C3.56727 34.4857 2.95016 34.1294 2.60563 33.5327C2.26109 32.9359 2.26109 32.2234 2.60563 31.6266L8.14211 22.0371C8.4657 21.4767 8.27367 20.7601 7.7132 20.4365C7.15273 20.1129 6.43617 20.305 6.11258 20.8654L0.576094 30.4549C-0.192031 31.7854 -0.192031 33.3739 0.576094 34.7044C1.3443 36.0349 2.72 36.8292 4.25633 36.8292H12.4172C11.9508 37.1777 11.8052 37.8264 12.1005 38.3457C12.3165 38.7254 12.7125 38.9383 13.1201 38.9383C13.3164 38.9383 13.5155 38.8889 13.6984 38.7849L17.2719 36.7521C17.6274 36.5498 17.8518 36.1767 17.8637 35.7677C17.8702 35.5435 17.812 35.3265 17.7019 35.1393C17.5619 34.8562 17.3118 34.6374 17.0066 34.5406Z\" fill=\"#476175\"\/>\r\n    <path d=\"M39.4248 30.4567L34.008 21.0438C34.5627 21.3055 35.2323 21.0952 35.5326 20.5507C35.8451 19.984 35.6389 19.2712 35.0722 18.9588L31.472 16.9737C31.1139 16.7762 30.6784 16.7798 30.3234 16.9834C29.9685 17.1868 29.7454 17.5607 29.7348 17.9697L29.6323 21.9398C29.6156 22.5868 30.1265 23.1248 30.7734 23.1415C30.7838 23.1417 30.7941 23.1419 30.8043 23.1419C31.3777 23.1419 31.8578 22.7273 31.9559 22.1763L37.3944 31.6271C37.7389 32.2238 37.7389 32.9364 37.3944 33.5332C37.0498 34.1299 36.4327 34.4862 35.7437 34.4862H25.0057C24.3586 34.4862 23.834 35.0109 23.834 35.658C23.834 36.3051 24.3586 36.8297 25.0057 36.8297H35.7437C37.28 36.8297 38.6557 36.0354 39.4239 34.7049C40.1921 33.3744 40.1921 31.7858 39.4248 30.4567Z\" fill=\"#476175\"\/>\r\n    <path d=\"M25.6761 25.9835C27.7543 23.9054 27.4195 20.3896 27.4042 20.241C27.3475 19.6886 26.9107 19.2519 26.3583 19.1952C26.2709 19.1861 25.0166 19.0667 23.5757 19.3935C23.577 19.3484 23.5778 19.3033 23.5778 19.2582C23.5778 16.3194 20.8551 14.0701 20.7392 13.9758C20.3084 13.6253 19.691 13.6253 19.2601 13.9758C19.1442 14.0701 16.4215 16.3194 16.4215 19.2582C16.4215 19.3033 16.4224 19.3484 16.4236 19.3935C14.9828 19.0667 13.7286 19.1861 13.641 19.1951C13.0886 19.2518 12.6518 19.6885 12.5951 20.241C12.5799 20.3896 12.245 23.9053 14.3232 25.9835C15.6563 27.3165 17.58 27.6564 18.828 27.7249V28.8538C18.828 29.5009 19.3526 30.0255 19.9997 30.0255C20.6468 30.0255 21.1714 29.5009 21.1714 28.8538V27.7249C22.4194 27.6564 24.3432 27.3164 25.6761 25.9835ZM24.0191 24.3264C23.302 25.0435 22.1292 25.3036 21.2233 25.3763C21.296 24.4694 21.5561 23.2971 22.273 22.5803C22.9897 21.8636 24.1617 21.6035 25.0674 21.5306C25.0034 22.3874 24.7703 23.5753 24.0191 24.3264ZM18.7649 19.2582C18.7649 18.2442 19.4103 17.231 19.9995 16.5389C20.5893 17.2316 21.2343 18.2444 21.2343 19.2582C21.2884 20.3495 20.6152 20.8756 19.9996 21.6767C19.6726 21.3096 18.7649 20.1969 18.7649 19.2582ZM15.9803 24.3264C15.2631 23.6094 15.0031 22.4365 14.9304 21.5306C15.8372 21.6034 17.0096 21.8635 17.7263 22.5803C18.4435 23.2974 18.7035 24.4702 18.7763 25.3761C17.8694 25.3034 16.6971 25.0432 15.9803 24.3264Z\" fill=\"#476175\"\/>\r\n    <path d=\"M11.1889 14.4006C11.3721 14.5087 11.5778 14.5628 11.7836 14.5628C11.9737 14.5628 12.1641 14.5166 12.3371 14.4238L15.8376 12.5478C16.408 12.2421 16.6225 11.532 16.3168 10.9616C16.0311 10.4284 15.3918 10.2064 14.844 10.4293L18.3494 4.35898C18.694 3.76219 19.3111 3.40594 20.0001 3.40594C20.6892 3.40594 21.3063 3.76219 21.6508 4.35898L25.648 11.2823C25.9716 11.8427 26.6882 12.0347 27.2486 11.7112C27.8091 11.3876 28.0011 10.671 27.6775 10.1105L23.6804 3.18727C22.9122 1.8568 21.5364 1.0625 20.0001 1.0625C18.4638 1.0625 17.088 1.8568 16.3199 3.18719L12.8879 9.13031C12.814 8.55266 12.3211 8.10859 11.7268 8.10859C11.7213 8.10859 11.7157 8.10859 11.7101 8.10867C11.0631 8.11766 10.5457 8.64953 10.5548 9.29656L10.6121 13.4074C10.6177 13.8164 10.8364 14.193 11.1889 14.4006Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_11073_21576\">\r\n      <rect width=\"40\" height=\"40\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Biocompatible<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (LNP\u2122 COLORCOMP\u2122 Compound A1000FXB)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PBT<\/strong>\r\n                                            (LNP\u2122 ELCRIN\u2122 W1000JiQ)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (LNP\u2122 ELCRIN\u2122 HPH4504HB)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC-ABS<\/strong>\r\n                                            (LNP\u2122 COLORCOMP\u2122 Compound N1000EXB)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PEI<\/strong>\r\n                                            (LNP\u2122 THERMOCOMP\u2122 Compound EC006AQW)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_11073_21617)\">\r\n    <path d=\"M38.8281 0H1.17188C0.524687 0 0 0.524687 0 1.17188V38.8281C0 39.4753 0.524687 40 1.17188 40H38.8281C39.4753 40 40 39.4753 40 38.8281V1.17188C40 0.524687 39.4753 0 38.8281 0ZM37.6562 37.6562H2.34375V2.34375H37.6562V37.6562Z\" fill=\"#476175\"\/>\r\n    <path d=\"M5.85938 7.03125C6.50658 7.03125 7.03125 6.50658 7.03125 5.85938C7.03125 5.21217 6.50658 4.6875 5.85938 4.6875C5.21217 4.6875 4.6875 5.21217 4.6875 5.85938C4.6875 6.50658 5.21217 7.03125 5.85938 7.03125Z\" fill=\"#476175\"\/>\r\n    <path d=\"M34.1406 7.03125C34.7878 7.03125 35.3125 6.50658 35.3125 5.85938C35.3125 5.21217 34.7878 4.6875 34.1406 4.6875C33.4934 4.6875 32.9688 5.21217 32.9688 5.85938C32.9688 6.50658 33.4934 7.03125 34.1406 7.03125Z\" fill=\"#476175\"\/>\r\n    <path d=\"M5.85938 35.3125C6.50658 35.3125 7.03125 34.7878 7.03125 34.1406C7.03125 33.4934 6.50658 32.9688 5.85938 32.9688C5.21217 32.9688 4.6875 33.4934 4.6875 34.1406C4.6875 34.7878 5.21217 35.3125 5.85938 35.3125Z\" fill=\"#476175\"\/>\r\n    <path d=\"M34.1406 35.3125C34.7878 35.3125 35.3125 34.7878 35.3125 34.1406C35.3125 33.4934 34.7878 32.9688 34.1406 32.9688C33.4934 32.9688 32.9688 33.4934 32.9688 34.1406C32.9688 34.7878 33.4934 35.3125 34.1406 35.3125Z\" fill=\"#476175\"\/>\r\n    <path d=\"M26.9539 15.6376H22.444L24.7896 9.00602C25.0592 8.24375 24.4924 7.44336 23.6848 7.44336H17.1141C16.6044 7.44336 16.1532 7.77281 15.998 8.25828L11.9314 20.9738C11.6898 21.7295 12.255 22.5025 13.0476 22.5025H16.7411L14.522 31.0912C14.2055 32.3166 15.8056 33.1051 16.5829 32.1023L27.8801 17.5273C28.4758 16.7587 27.9263 15.6376 26.9539 15.6376ZM18.2137 26.1727L19.3891 21.6237C19.5805 20.8827 19.0203 20.1588 18.2544 20.1588H14.653L17.9698 9.78703H22.0273L19.6817 16.4186C19.4121 17.1809 19.9789 17.9812 20.7866 17.9812H24.563L18.2137 26.1727Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_11073_21617\">\r\n      <rect width=\"40\" height=\"40\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Antistatique (ESD)<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (ELIXTM ABS P2H-AT)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (LNP\u2122 STAT-KON\u2122 Compound AX02747)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (Novodur\u00ae P2H-AT)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (LEXAN\u2122 FR Resin SLD3000)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>POM<\/strong>\r\n                                            (LNP\u2122 STAT-LOY\u2122 Compound K3000Z)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PP<\/strong>\r\n                                            (Borealis PP HG313MO)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                    <\/div>\r\n                                        <div class=\"materials-accordion__column materials-accordion__column_mobile\">\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_11073_21476)\">\r\n    <path d=\"M20.0009 0C10.2833 0 2.41797 7.86312 2.41797 17.5808C2.41797 23.8785 5.75359 29.6398 11.1703 32.7863L11.1694 36.4756C11.1692 37.4156 11.5352 38.2994 12.1998 38.9641C14.4279 41.1923 18.208 39.5782 18.2074 36.4755L18.2071 35.1226C20.1904 35.2529 22.1938 35.056 24.1454 34.5066V36.4837C24.1454 38.4198 25.7208 39.9949 27.6571 39.9949C29.5934 39.9949 31.1688 38.4198 31.1688 36.4837V31.1592C35.1386 27.8877 37.5838 22.9888 37.5838 17.5808C37.584 7.86406 29.7195 0 20.0009 0ZM15.5196 37.3072C14.78 38.0467 13.5129 37.5166 13.5131 36.4762C13.5134 35.6727 13.5162 24.1547 13.5163 23.4357C14.2646 23.5883 15.0662 23.5977 15.8605 23.4357L15.8638 36.4761C15.8638 36.79 15.7416 37.0852 15.5196 37.3072ZM28.8252 36.4837C28.8252 37.1276 28.3012 37.6515 27.6572 37.6515C27.0132 37.6515 26.4892 37.1276 26.4892 36.4837V28.9065C26.4892 28.2594 25.9645 27.7348 25.3173 27.7348C25.0588 27.7348 24.8486 27.5245 24.8486 27.2661V16.9724C24.8486 14.5369 26.5491 12.491 28.8252 11.9591V36.4837ZM31.1689 27.952V10.653C31.1689 10.0059 30.6442 9.48125 29.997 9.48125C25.8658 9.48125 22.5048 12.8418 22.5048 16.9725V27.2661C22.5048 28.3988 23.1781 29.3772 24.1455 29.8223V32.0566C22.2453 32.6827 20.2364 32.927 18.2066 32.7734L18.2041 22.3777C19.624 21.3084 20.544 19.6092 20.544 17.6989V10.6236C20.544 9.97648 20.0193 9.45188 19.3721 9.45188C18.7249 9.45188 18.2002 9.97648 18.2002 10.6236V17.6989C18.2002 19.2257 17.2202 20.5273 15.8565 21.0098V10.6237C15.8565 9.97656 15.3318 9.45195 14.6846 9.45195C14.0374 9.45195 13.5127 9.97656 13.5127 10.6237V21.0072C12.153 20.5226 11.1768 19.2229 11.1768 17.699V10.6237C11.1768 9.97656 10.6521 9.45195 10.0049 9.45195C9.35773 9.45195 8.83305 9.97656 8.83305 10.6237V17.699C8.83305 19.6093 9.75305 21.3085 11.173 22.3778L11.1711 30.0029C7.17453 27.1654 4.7618 22.567 4.7618 17.5809C4.76172 9.17891 11.598 2.34344 20.0009 2.34344C28.4039 2.34344 35.2402 9.17891 35.2402 17.5808C35.2402 21.4895 33.7802 25.1539 31.1689 27.952Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_11073_21476\">\r\n      <rect width=\"40\" height=\"40\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Qualit\u00e9 alimentaire<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (POLYLAC\u00ae PA-757F)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 12<\/strong>\r\n                                            (Grilamid\u00ae L 16 nat)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (LEXAN\u2122 RESIN 124R)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PEEK glass-filled (30%)<\/strong>\r\n                                            (APEXTECH-HT\u00a0330GL30)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PMMA<\/strong>\r\n                                            (POLYCASA\u00ae ACRYL G 55)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PP<\/strong>\r\n                                            (TAIRIPRO\u00ae K1011)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"34\" height=\"34\" viewBox=\"0 0 34 34\" fill=\"none\">\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.46875 13.2344C8.46875 20.0257 13.9743 25.5312 20.7656 25.5312H20.7656C27.557 25.5312 33.0625 20.0257 33.0625 13.2343C33.0625 6.44296 27.5568 0.937435 20.7656 0.937435C13.9743 0.937435 8.46875 6.44296 8.46875 13.2344ZM20.7656 23.5312C15.0789 23.5312 10.4688 18.9211 10.4688 13.2344C10.4688 7.54753 15.0789 2.93744 20.7656 2.93744C26.4523 2.93744 31.0625 7.54754 31.0625 13.2343C31.0625 18.9211 26.4525 23.5312 20.7656 23.5312\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M4.53924 29.4609C9.34146 34.263 17.1273 34.263 21.9295 29.4609L21.2224 28.7538L21.9295 29.4609C26.7316 24.6587 26.7317 16.8727 21.9295 12.0706C21.9295 12.0706 21.9295 12.0706 21.9295 12.0706M4.53923 29.4609C-0.26298 24.6589 -0.263178 16.8727 4.53924 12.0704C9.34145 7.2682 17.1275 7.26841 21.9295 12.0706M20.5153 28.0467C16.4941 32.0678 9.9746 32.0678 5.95344 28.0467L5.95343 28.0467C1.93228 24.0257 1.9321 17.5059 5.95343 13.4846L5.24634 12.7775L5.95344 13.4846C9.97459 9.46349 16.4943 9.46365 20.5153 13.4848L20.5153 13.4848C24.5364 17.5059 24.5364 24.0255 20.5153 28.0467Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.96477 27.4884C3.35529 27.8789 3.98846 27.8789 4.37898 27.4884L19.9589 11.9084C20.3494 11.5179 20.3494 10.8847 19.9589 10.4942C19.5683 10.1037 18.9352 10.1037 18.5446 10.4942L2.96477 26.0741C2.57424 26.4647 2.57424 27.0978 2.96477 27.4884Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.24602 22.1036C1.63654 22.4941 2.26971 22.4941 2.66023 22.1036L14.5678 10.196C14.9583 9.8055 14.9583 9.17234 14.5678 8.78182C14.1773 8.39129 13.5441 8.39129 13.1536 8.78182L1.24602 20.6894C0.855494 21.0799 0.855494 21.7131 1.24602 22.1036Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6.51163 31.0411C6.90214 31.4316 7.53531 31.4316 7.92584 31.0411L23.5063 15.4614C23.8968 15.0708 23.8968 14.4377 23.5063 14.0471C23.1158 13.6566 22.4826 13.6566 22.0921 14.0471L6.51166 29.6269C6.12113 30.0174 6.12111 30.6505 6.51163 31.0411Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M11.9023 32.7481C12.2928 33.1386 12.926 33.1386 13.3165 32.7481L25.224 20.8406C25.6146 20.4501 25.6146 19.8169 25.224 19.4264C24.8335 19.0359 24.2004 19.0359 23.8098 19.4264L11.9023 31.3339C11.5117 31.7244 11.5117 32.3576 11.9023 32.7481Z\" fill=\"#476175\"\/>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Clair\/transparent<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (Kingfa FW-612 TC)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 66<\/strong>\r\n                                            (Kingfa PA66-G35 AHBK003)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (LEXAN\u2122 HEALTHCARE RESIN HPS1)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (Makrolon\u00ae 6557)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PMMA<\/strong>\r\n                                            (POLYCASA\u00ae ACRYL G 55)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PP<\/strong>\r\n                                            (TAIRIPRO\u00ae K1011)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M25.7623 5.72859V23.1022C28.0851 24.872 29.454 27.6251 29.4541 30.5904C29.4541 35.7789 25.2329 40 20.0445 40C14.8559 40 10.6348 35.7789 10.6348 30.5903C10.6348 27.6566 11.9964 24.9109 14.3051 23.1331V5.72859C14.3051 2.56984 16.8748 0 20.0337 0C23.1925 0 25.7623 2.56984 25.7623 5.72859ZM12.9808 30.5904C12.9808 34.4853 16.1495 37.6541 20.0445 37.6541C23.9393 37.6541 27.108 34.4853 27.108 30.5904C27.108 28.1982 25.9253 25.9912 23.9441 24.6863C23.5981 24.4584 23.4132 24.0788 23.4173 23.6931C23.4172 23.6903 23.417 23.6876 23.4168 23.6848C23.4166 23.6817 23.4164 23.6786 23.4164 23.6754V5.72859C23.4164 3.86336 21.8989 2.34594 20.0338 2.34594C18.1686 2.34594 16.6511 3.86336 16.6511 5.72859V8.14789V10.4938V11.2513V13.5973V14.398V16.7439V23.6755C16.6511 23.862 16.6064 24.0376 16.529 24.1941C16.4449 24.4057 16.2988 24.5953 16.0959 24.7324C14.1453 26.0502 12.9808 28.2401 12.9808 30.5904Z\" fill=\"#476175\"\/>\r\n  <path d=\"M21.2171 26.1547V5.64172C21.2171 4.99391 20.692 4.46875 20.0441 4.46875C19.3963 4.46875 18.8712 4.99391 18.8712 5.64172V26.1491C16.8456 26.6674 15.3438 28.508 15.3438 30.6928C15.3438 33.2788 17.4476 35.3827 20.0335 35.3827C22.6195 35.3827 24.7233 33.2788 24.7233 30.6928C24.7232 28.5156 23.2319 26.6805 21.2171 26.1547ZM20.0334 33.0366C18.7411 33.0366 17.6896 31.9852 17.6896 30.6927C17.6896 29.4003 18.7411 28.3489 20.0334 28.3489C21.3258 28.3489 22.3773 29.4003 22.3773 30.6927C22.3773 31.9852 21.3259 33.0366 20.0334 33.0366Z\" fill=\"#476175\"\/>\r\n  <path d=\"M9.5518 12C8.14469 12 7 13.1448 7 14.5519C7 15.959 8.14477 17.1037 9.5518 17.1037C10.9588 17.1037 12.1037 15.959 12.1037 14.5519C12.1037 13.1448 10.9589 12 9.5518 12ZM9.5518 15.7577C8.88582 15.7577 8.34594 15.2179 8.34594 14.5519C8.34594 13.8859 8.88582 13.346 9.5518 13.346C10.2178 13.346 10.7577 13.8859 10.7577 14.5519C10.7577 15.2179 10.2178 15.7577 9.5518 15.7577Z\" fill=\"#476175\"\/>\r\n  <path d=\"M35.7884 9C34.2509 9 33 10.2509 33 11.7884C33 13.3259 34.2509 14.5767 35.7884 14.5767C37.3259 14.5767 38.5767 13.3259 38.5767 11.7884C38.5767 10.2509 37.3259 9 35.7884 9ZM35.7884 12.2309C35.5444 12.2309 35.3459 12.0325 35.3459 11.7885C35.3459 11.5445 35.5444 11.3461 35.7884 11.3461C36.0323 11.3461 36.2308 11.5445 36.2308 11.7885C36.2309 12.0325 36.0323 12.2309 35.7884 12.2309Z\" fill=\"#476175\"\/>\r\n  <path d=\"M30.7354 2C29.3283 2 28.1836 3.14477 28.1836 4.55188C28.1836 5.95898 29.3284 7.10375 30.7354 7.10375C32.1424 7.10375 33.2873 5.95898 33.2873 4.55188C33.2873 3.14477 32.1425 2 30.7354 2ZM30.7354 5.75773C30.0694 5.75773 29.5295 5.21785 29.5295 4.55188C29.5295 3.8859 30.0694 3.34602 30.7354 3.34602C31.4014 3.34602 31.9413 3.8859 31.9413 4.55188C31.9413 5.21785 31.4014 5.75773 30.7354 5.75773Z\" fill=\"#476175\"\/>\r\n  <path d=\"M33.9784 18.4701H33.197V17.6886C33.197 17.0408 32.6718 16.5156 32.024 16.5156C31.3762 16.5156 30.851 17.0408 30.851 17.6886V18.4701H30.0695C29.4216 18.4701 28.8965 18.9952 28.8965 19.643C28.8965 20.2909 29.4216 20.816 30.0695 20.816H30.8509V21.5975C30.8509 22.2453 31.3761 22.7705 32.0239 22.7705C32.6717 22.7705 33.1969 22.2453 33.1969 21.5975V20.816H33.9784C34.6262 20.816 35.1513 20.2909 35.1513 19.643C35.1513 18.9952 34.6262 18.4701 33.9784 18.4701Z\" fill=\"#476175\"\/>\r\n  <path d=\"M8.08734 3.41883H7.84141V3.17297C7.84141 2.52516 7.31625 2 6.66844 2C6.02062 2 5.49547 2.52516 5.49547 3.17297V3.41883H5.17297C4.52516 3.41883 4 3.94398 4 4.5918C4 5.23961 4.52516 5.76477 5.17297 5.76477H5.49547V6.08727C5.49547 6.73508 6.02062 7.26023 6.66844 7.26023C7.31625 7.26023 7.84141 6.73508 7.84141 6.08727V5.76477H8.08734C8.73516 5.76477 9.26031 5.23961 9.26031 4.5918C9.26031 3.94398 8.73523 3.41883 8.08734 3.41883Z\" fill=\"#476175\"\/>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>R\u00e9sistant \u00e0 la chaleur<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (Kingfa FW-612 TC)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (LG ABS LG703W)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 6<\/strong>\r\n                                            (Kingfa PA6-G15 HSBK145)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PEEK glass-filled (30%)<\/strong>\r\n                                            (APEXTECH-HT\u00a0330GL30)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PEI<\/strong>\r\n                                            (LNP\u2122 THERMOCOMP\u2122 Compound EC006AQW)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_11073_21586)\">\r\n    <path d=\"M39.469 22.5952C38.9786 21.7446 38.1867 21.1362 37.2391 20.8819C36.2914 20.6277 35.3015 20.7578 34.4512 21.249L32.2824 22.5026C31.4667 20.9182 30.2856 19.5525 28.8122 18.5057C27.2377 17.3871 25.429 16.7085 23.5253 16.5104V13.7001C23.5253 11.9899 24.3927 10.3519 25.8453 9.31839L26.3219 8.97952C26.7581 9.38004 27.291 9.68562 27.9045 9.88291C28.4255 10.0504 28.986 10.1332 29.5731 10.1332C30.7707 10.1332 32.0794 9.78852 33.3907 9.1143C36.7028 7.41153 38.0738 2.48385 38.1305 2.27492C38.2892 1.69048 37.9765 1.08135 37.4091 0.869681C37.2063 0.794047 32.4071 -0.962405 29.0945 0.740838C27.495 1.5632 26.2964 2.66356 25.6283 3.923C25.0954 4.92749 24.9341 5.96878 25.1481 6.93796L24.4866 7.40833C23.1032 8.39266 22.0932 9.77016 21.575 11.3121C21.1307 10.9526 20.6186 10.6305 20.0449 10.3569L18.9133 9.8172C19.1194 8.85482 18.9571 7.82259 18.4285 6.8263C17.7604 5.56686 16.5618 4.4665 14.9623 3.64414C11.6496 1.94098 6.85047 3.69735 6.64772 3.77298C6.08023 3.98465 5.76754 4.59378 5.9263 5.17822C5.98311 5.38716 7.35412 10.3148 10.6661 12.0175C11.9775 12.6917 13.2861 13.0365 14.4838 13.0365C15.071 13.0365 15.6314 12.9536 16.1523 12.7861C16.7761 12.5856 17.3161 12.2726 17.7563 11.8624L19.0358 12.4727C20.3791 13.1134 21.1811 14.0553 21.1811 14.9924V16.5098C17.7509 16.8696 14.6761 18.7957 12.8503 21.7502H9.59891C8.87047 21.7502 8.14101 21.9311 7.48883 22.2736L7.08948 22.4837V21.1548C7.08948 20.5075 6.56474 19.9827 5.91747 19.9827H1.21107C0.56381 19.9827 0.0390625 20.5075 0.0390625 21.1548V38.828C0.0390625 39.4752 0.56381 40 1.21107 40H5.91747C6.56474 40 7.08948 39.4752 7.08948 38.828V37.5199L12.0669 36.0247C12.3948 35.9262 12.7346 35.8762 13.0769 35.8762H22.8477C23.9169 35.8762 24.9656 35.5834 25.8806 35.0294L38.1356 27.6087C39.2619 26.9522 39.9609 25.7352 39.9609 24.4293C39.9609 23.7874 39.7908 23.1532 39.469 22.5952ZM30.1664 2.82545C30.855 2.47143 31.7058 2.34266 32.5701 2.34266C33.6157 2.34266 34.6809 2.5312 35.5009 2.7374C34.9335 4.17616 33.8419 6.24679 32.3191 7.02969C30.9423 7.73743 29.595 7.96417 28.6221 7.65132C28.1315 7.49357 27.7794 7.21205 27.5754 6.81451C26.9507 5.59609 28.0404 3.91847 30.1664 2.82545ZM15.435 10.5545C14.4622 10.8672 13.1148 10.6407 11.7379 9.93291C10.2152 9.15001 9.12347 7.07938 8.55606 5.64062C10.054 5.26417 12.3688 4.94632 13.8906 5.72876C16.0165 6.82185 17.1061 8.49939 16.4814 9.71781C16.2777 10.1153 15.9255 10.3968 15.435 10.5545ZM22.3534 18.7921C25.7079 18.7921 28.7685 20.7202 30.2498 23.6775L26.4516 25.9499C25.9056 26.2771 25.2823 26.4495 24.6467 26.4495C24.6346 26.4495 24.6224 26.4494 24.6103 26.4493C24.6057 26.4493 24.6013 26.4493 24.5967 26.4493L22.1841 26.4522C22.3141 26.0848 22.3855 25.6899 22.3855 25.2785C22.3855 23.3329 20.8041 21.7501 18.8603 21.7501H15.7614C17.4159 19.8898 19.7991 18.7921 22.3534 18.7921ZM4.74546 37.656H2.38308V22.3268H4.74546V37.656ZM36.9514 25.5859C36.9446 25.5899 36.9378 25.5939 36.931 25.598L24.6664 33.0244C24.1178 33.3566 23.4888 33.5323 22.8477 33.5323H13.0769C12.506 33.5323 11.9393 33.6156 11.3926 33.7798L7.08948 35.0725V25.1323L8.57958 24.3482C8.89618 24.1819 9.24864 24.094 9.59891 24.094H18.8601C19.5115 24.094 20.0413 24.6253 20.0413 25.2784C20.0413 25.8894 19.5775 26.3936 18.9844 26.4561L13.5639 26.4629C12.9166 26.4636 12.3926 26.989 12.3934 27.6364C12.3942 28.2832 12.9188 28.807 13.5654 28.8069H13.5669L24.5927 28.7932C25.6703 28.8037 26.7306 28.5152 27.6564 27.9605L35.6239 23.2784C35.9312 23.101 36.2889 23.0539 36.6315 23.1457C36.9743 23.2376 37.2608 23.4579 37.4384 23.7659C37.5551 23.9684 37.6168 24.1978 37.6168 24.4292C37.6169 24.9053 37.3619 25.3484 36.9514 25.5859Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_11073_21586\">\r\n      <rect width=\"40\" height=\"40\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Biod\u00e9gradable<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>PLA<\/strong>\r\n                                            (Anbio BG4400)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PLA<\/strong>\r\n                                            (GS Pla\u00ae AD92W)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_11073_21617)\">\r\n    <path d=\"M38.8281 0H1.17188C0.524687 0 0 0.524687 0 1.17188V38.8281C0 39.4753 0.524687 40 1.17188 40H38.8281C39.4753 40 40 39.4753 40 38.8281V1.17188C40 0.524687 39.4753 0 38.8281 0ZM37.6562 37.6562H2.34375V2.34375H37.6562V37.6562Z\" fill=\"#476175\"\/>\r\n    <path d=\"M5.85938 7.03125C6.50658 7.03125 7.03125 6.50658 7.03125 5.85938C7.03125 5.21217 6.50658 4.6875 5.85938 4.6875C5.21217 4.6875 4.6875 5.21217 4.6875 5.85938C4.6875 6.50658 5.21217 7.03125 5.85938 7.03125Z\" fill=\"#476175\"\/>\r\n    <path d=\"M34.1406 7.03125C34.7878 7.03125 35.3125 6.50658 35.3125 5.85938C35.3125 5.21217 34.7878 4.6875 34.1406 4.6875C33.4934 4.6875 32.9688 5.21217 32.9688 5.85938C32.9688 6.50658 33.4934 7.03125 34.1406 7.03125Z\" fill=\"#476175\"\/>\r\n    <path d=\"M5.85938 35.3125C6.50658 35.3125 7.03125 34.7878 7.03125 34.1406C7.03125 33.4934 6.50658 32.9688 5.85938 32.9688C5.21217 32.9688 4.6875 33.4934 4.6875 34.1406C4.6875 34.7878 5.21217 35.3125 5.85938 35.3125Z\" fill=\"#476175\"\/>\r\n    <path d=\"M34.1406 35.3125C34.7878 35.3125 35.3125 34.7878 35.3125 34.1406C35.3125 33.4934 34.7878 32.9688 34.1406 32.9688C33.4934 32.9688 32.9688 33.4934 32.9688 34.1406C32.9688 34.7878 33.4934 35.3125 34.1406 35.3125Z\" fill=\"#476175\"\/>\r\n    <path d=\"M26.9539 15.6376H22.444L24.7896 9.00602C25.0592 8.24375 24.4924 7.44336 23.6848 7.44336H17.1141C16.6044 7.44336 16.1532 7.77281 15.998 8.25828L11.9314 20.9738C11.6898 21.7295 12.255 22.5025 13.0476 22.5025H16.7411L14.522 31.0912C14.2055 32.3166 15.8056 33.1051 16.5829 32.1023L27.8801 17.5273C28.4758 16.7587 27.9263 15.6376 26.9539 15.6376ZM18.2137 26.1727L19.3891 21.6237C19.5805 20.8827 19.0203 20.1588 18.2544 20.1588H14.653L17.9698 9.78703H22.0273L19.6817 16.4186C19.4121 17.1809 19.9789 17.9812 20.7866 17.9812H24.563L18.2137 26.1727Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_11073_21617\">\r\n      <rect width=\"40\" height=\"40\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Antistatique (ESD)<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (ELIXTM ABS P2H-AT)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (LNP\u2122 STAT-KON\u2122 Compound AX02747)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (Novodur\u00ae P2H-AT)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (LEXAN\u2122 FR Resin SLD3000)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>POM<\/strong>\r\n                                            (LNP\u2122 STAT-LOY\u2122 Compound K3000Z)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PP<\/strong>\r\n                                            (Borealis PP HG313MO)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_12181_12420)\">\r\n    <path d=\"M4.48029 29.8865L5.40216 30.6547C5.29522 30.783 5.19743 30.9144 5.10852 31.0483L4.48029 29.8865Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.68146 40.0562C3.02739 40.0562 -0.0611618 33.4618 3.55843 29.1183L15.3367 14.9843V5.8875C15.3367 5.22476 15.874 4.6875 16.5367 4.6875H24.3492C25.0119 4.6875 25.5492 5.22476 25.5492 5.8875V14.9843L37.3275 29.1183C40.9471 33.4618 37.8585 40.0562 32.2044 40.0562H8.68146ZM5.40216 30.6547L4.48029 29.8865L5.10852 31.0483C3.27119 33.8157 5.2293 37.6562 8.68146 37.6562H32.2044C35.8236 37.6562 37.8007 33.4351 35.4837 30.6547L23.4273 16.187C23.2476 15.9713 23.1492 15.6995 23.1492 15.4187V7.0875H17.7367V15.4187C17.7367 15.6995 17.6383 15.9713 17.4586 16.187L5.40216 30.6547Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.5367 4.6875C15.9051 4.6875 15.3929 4.17538 15.3929 3.54375C15.3929 2.91212 15.9051 2.4 16.5367 2.4H24.3492C24.9808 2.4 25.4929 2.91212 25.4929 3.54375C25.4929 4.17538 24.9808 4.6875 24.3492 4.6875H16.5367ZM12.9929 3.54375C12.9929 5.50087 14.5796 7.0875 16.5367 7.0875H24.3492C26.3063 7.0875 27.8929 5.50087 27.8929 3.54375C27.8929 1.58663 26.3063 0 24.3492 0H16.5367C14.5796 0 12.9929 1.58663 12.9929 3.54375Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M10.6766 31.209C9.59051 33.0469 10.9153 35.3687 13.0503 35.3687H27.8356C29.9706 35.3687 31.2954 33.0469 30.2093 31.209L22.8166 18.6983C21.7495 16.8923 19.1364 16.8922 18.0693 18.6983M18.0693 18.6983L10.6766 31.209L18.0693 18.6983ZM13.0503 32.9687C12.7737 32.9687 12.6021 32.668 12.7428 32.4299L20.1355 19.9192C20.2737 19.6853 20.6122 19.6853 20.7504 19.9192L28.1431 32.4299C28.2838 32.668 28.1122 32.9687 27.8356 32.9687H13.0503Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M23.6113 24.6378C23.7491 25.286 24.3864 25.6998 25.0346 25.562C25.6633 25.4284 26.1922 25.2878 26.6995 25.153C27.8929 24.836 28.9669 24.5506 30.9398 24.4608C31.6019 24.4306 32.1141 23.8694 32.084 23.2074C32.0538 22.5453 31.4927 22.0331 30.8306 22.0632C28.5855 22.1655 27.1765 22.5388 25.9073 22.8752C25.4427 22.9983 24.9968 23.1164 24.5355 23.2145C23.8873 23.3523 23.4735 23.9895 23.6113 24.6378Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M17.2746 24.6379C17.4124 23.9896 16.9987 23.3524 16.3504 23.2145C15.8892 23.1164 15.4434 22.9983 14.9789 22.8752C13.7096 22.5389 12.3006 22.1655 10.0553 22.0633C9.3932 22.0331 8.83206 22.5454 8.80192 23.2074C8.77177 23.8695 9.28404 24.4306 9.9461 24.4608C11.9191 24.5506 12.9933 24.836 14.1867 25.1531C14.6939 25.2879 15.2227 25.4284 15.8512 25.562C16.4995 25.6999 17.1367 25.2861 17.2746 24.6379Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M20.4429 28.7281C21.1057 28.7281 21.643 28.1909 21.643 27.5281V23.6219C21.643 22.9591 21.1057 22.4219 20.4429 22.4219C19.7802 22.4219 19.2429 22.9591 19.2429 23.6219V27.5281C19.2429 28.1909 19.7802 28.7281 20.4429 28.7281Z\" fill=\"#476175\"\/>\r\n    <path d=\"M21.4195 30.4578C21.4195 30.9971 20.9822 31.4344 20.4429 31.4344C19.9037 31.4344 19.4664 30.9971 19.4664 30.4578C19.4664 29.9185 19.9037 29.4812 20.4429 29.4812C20.9822 29.4812 21.4195 29.9185 21.4195 30.4578Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_12181_12420\">\r\n      <rect width=\"40\" height=\"40\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Conforme RoHS<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (Axpoly\u00ae ABS52 1007)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 12<\/strong>\r\n                                            (Grilamid\u00ae L 16 nat)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 66 glass-filled (35%)<\/strong>\r\n                                            (Ultramid\u00ae A3X2G7)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (POLYLAC\u00ae PA-757)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PP<\/strong>\r\n                                            (SEETEC PP H1500)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>TPV<\/strong>\r\n                                            (SantopreneTM 101-64)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                    <\/div>\r\n                            <div class=\"materials-accordion__column materials-accordion__column_mobile\">\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_12181_12535)\">\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M20.0008 40.0273C11.5715 40.0273 4.73828 33.194 4.73828 24.764C4.73854 20.9176 6.85157 17.3804 8.88454 14.6698C11.0191 11.8237 11.5742 8.55637 11.5742 5.93673C11.5742 4.63257 11.4363 3.51108 11.2989 2.71891C11.2303 2.32361 11.1623 2.01255 11.1126 1.80436L11.037 1.5097L11.0365 1.50793C10.9069 1.06461 11.0432 0.586155 11.3871 0.277714C11.7315 -0.0311394 12.2228 -0.114517 12.6498 0.0634079C12.7572 0.108162 15.6525 1.40437 18.4718 4.43608C20.8208 6.96189 23.1151 10.6945 23.6913 15.8678C23.7381 16.2882 23.7736 16.718 23.7968 17.1576C24.4433 16.5507 25.0128 15.7561 25.5038 14.8735C25.7417 14.446 25.9611 13.9978 26.1619 13.5403C26.6057 12.5295 26.9219 11.5584 27.1272 10.8375C27.2295 10.4784 27.3034 10.1846 27.3511 9.98308C27.375 9.88241 27.3923 9.80501 27.4033 9.75428L27.418 9.68493C27.5103 9.22499 27.8622 8.86099 28.3188 8.7532C28.7757 8.64534 29.2535 8.81381 29.5418 9.18437L29.6159 9.28197C29.6604 9.34122 29.7237 9.42672 29.8031 9.53694C29.9619 9.75731 30.1855 10.0769 30.4523 10.4834C30.9853 11.2956 31.6937 12.4595 32.4022 13.8766C33.8103 16.6928 35.2633 20.5963 35.2633 24.7648C35.2633 33.1941 28.43 40.0273 20.0008 40.0273ZM20.2452 37.6774C13.1415 37.6774 7.38273 31.9187 7.38269 24.8141C7.38269 24.8141 7.13828 20.3178 11.5 15C14.3936 11.4721 14 3.5 14 3.5C14 3.5 17.5 5.5 20 11C21.2661 13.7853 21.5019 15.5678 21.5245 17.0564C21.5305 17.4494 21.5216 17.8218 21.5129 18.1869L21.5117 18.2381C21.5056 18.494 21.5 18.7464 21.5 19C21.5 21 23.5 20.5 24 20C28 17 29.2868 12.7983 29.2868 12.7983C29.6628 13.4207 30.0814 14.1628 30.5 15C31.8263 17.6525 33.1077 21.1709 33.1077 24.8149C33.1077 31.9186 27.3489 37.6774 20.2452 37.6774Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M20.0008 40.0273C15.4547 40.0273 11.7695 36.3421 11.7695 31.7957C11.7696 29.666 12.9323 27.7624 13.9627 26.3886C14.9273 25.1024 15.1875 23.63 15.1875 22.4211C15.1875 21.8213 15.1231 21.3065 15.0593 20.9451C15.0275 20.7651 14.9963 20.6255 14.9743 20.5349L14.944 20.4183C14.8171 19.9903 14.9384 19.5271 15.259 19.2161C15.5805 18.9041 16.049 18.7973 16.474 18.9389L16.6661 19.0192C16.7192 19.0441 16.7915 19.0792 16.8803 19.1251C17.0576 19.2168 17.3015 19.3519 17.5891 19.5348C18.1627 19.8995 18.9204 20.461 19.6701 21.2562C20.7836 22.4373 21.8693 24.1267 22.3096 26.4073C22.3864 26.2603 22.4606 26.1051 22.532 25.9426C22.7399 25.469 22.8894 25.0105 22.9869 24.6681L23.1213 24.137C23.214 23.6776 23.5657 23.314 24.022 23.2063C24.4788 23.0985 24.9567 23.2669 25.2449 23.6375L25.3887 23.8314C25.4727 23.948 25.5896 24.115 25.7282 24.3262C26.0048 24.7477 26.3714 25.3502 26.7382 26.0837C27.4627 27.5327 28.232 29.5807 28.232 31.7961C28.232 36.3421 24.5468 40.0273 20.0008 40.0273ZM20.0008 37.6273C16.7803 37.6273 14.1696 35.0167 14.1695 31.7958C14.1695 31.7958 14.007 30.2496 16.332 27.1823C17.2892 25.9194 17.5891 22.4211 17.5891 22.4211C17.5891 22.4211 19.8457 24.6681 20 27C20.036 27.5434 20.0218 28.0582 20.0099 28.4896C20.0047 28.677 20 28.8486 20 29C20 30.5 21.575 30.1417 22 30C23.5 29.5 24.6042 27.1823 24.6042 27.1823C25.242 28.4642 25.832 30.1164 25.832 31.7961C25.832 35.0166 23.2213 37.6273 20.0008 37.6273Z\" fill=\"#476175\"\/>\r\n    <path d=\"M35.625 2.34375C35.625 2.99094 35.1003 3.51562 34.4531 3.51562C33.8059 3.51562 33.2812 2.99094 33.2812 2.34375C33.2812 1.69656 33.8059 1.17188 34.4531 1.17188C35.1003 1.17188 35.625 1.69656 35.625 2.34375Z\" fill=\"#476175\"\/>\r\n    <path d=\"M24.5518 1C23.1447 1 22 2.14477 22 3.55188C22 4.95898 23.1448 6.10375 24.5518 6.10375C25.9588 6.10375 27.1037 4.95898 27.1037 3.55188C27.1037 2.14477 25.9589 1 24.5518 1ZM24.5518 4.75773C23.8858 4.75773 23.3459 4.21785 23.3459 3.55188C23.3459 2.8859 23.8858 2.34602 24.5518 2.34602C25.2178 2.34602 25.7577 2.8859 25.7577 3.55188C25.7577 4.21785 25.2178 4.75773 24.5518 4.75773Z\" fill=\"#476175\"\/>\r\n    <path d=\"M4.375 7.1875C4.375 7.83469 4.89969 8.35938 5.54688 8.35938C6.19406 8.35938 6.71875 7.83469 6.71875 7.1875C6.71875 6.54031 6.19406 6.01562 5.54688 6.01562C4.89969 6.01562 4.375 6.54031 4.375 7.1875Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_12181_12535\">\r\n      <rect width=\"40\" height=\"40\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Ignifuge (UL 94 V-0 ou sup\u00e9rieur)<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (CYCOLAC\u2122 Resin FR15U)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (POLYLAC\u00ae PA-765A)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 66 glass-filled (35%)<\/strong>\r\n                                            (Ultramid\u00ae A3X2G7)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (Makrolon\u00ae 6557)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC glass-filled (10%)<\/strong>\r\n                                            (Makrolon\u00ae 9417)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC glass-filled (10%)<\/strong>\r\n                                            (LEXAN\u2122 FR Resin 500R)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC-ABS<\/strong>\r\n                                            (Bayblend\u00ae FR3008)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC-ASA<\/strong>\r\n                                            (LUPOY EU5000FS)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>Teflon <\/strong>\r\n                                            (PFA 440 HPB)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>TPV<\/strong>\r\n                                            (SantopreneTM 251-70W232)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M35.0137 18.2125C34.0265 18.2125 33.2262 19.0128 33.2262 20.0001C33.2262 20.9873 34.0265 21.7876 35.0137 21.7876C36.001 21.7876 36.8013 20.9873 36.8013 20.0001C36.8013 19.0128 36.001 18.2125 35.0137 18.2125ZM30.8262 20.0001C30.8262 17.6873 32.701 15.8125 35.0137 15.8125C37.3264 15.8125 39.2013 17.6873 39.2013 20.0001C39.2013 22.3128 37.3264 24.1876 35.0137 24.1876C32.701 24.1876 30.8262 22.3128 30.8262 20.0001Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M32.772 28.7438C30.5472 28.7438 28.7438 30.5472 28.7438 32.772C28.7438 34.9967 30.5472 36.8002 32.772 36.8002C34.9967 36.8002 36.8002 34.9967 36.8002 32.772C36.8002 30.5472 34.9967 28.7438 32.772 28.7438ZM26.3438 32.772C26.3438 29.2218 29.2218 26.3438 32.772 26.3438C36.3222 26.3438 39.2002 29.2218 39.2002 32.772C39.2002 36.3222 36.3222 39.2002 32.772 39.2002C29.2218 39.2002 26.3438 36.3222 26.3438 32.772Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6.48211 3.20078C4.66988 3.20078 3.20078 4.66988 3.20078 6.48211C3.20078 8.29434 4.66988 9.76344 6.48211 9.76344C8.29434 9.76344 9.76344 8.29434 9.76344 6.48211C9.76344 4.66988 8.29434 3.20078 6.48211 3.20078ZM0.800781 6.48211C0.800781 3.3444 3.3444 0.800781 6.48211 0.800781C9.61982 0.800781 12.1634 3.3444 12.1634 6.48211C12.1634 9.61982 9.61982 12.1634 6.48211 12.1634C3.3444 12.1634 0.800781 9.61982 0.800781 6.48211Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M4.24145 18.9605C3.6667 18.9605 3.20078 19.4265 3.20078 20.0012C3.20078 20.576 3.6667 21.0419 4.24145 21.0419C4.81619 21.0419 5.28211 20.576 5.28211 20.0012C5.28211 19.4265 4.81619 18.9605 4.24145 18.9605ZM0.800781 20.0012C0.800781 18.101 2.34122 16.5605 4.24145 16.5605C6.14167 16.5605 7.68211 18.101 7.68211 20.0012C7.68211 21.9014 6.14167 23.4419 4.24145 23.4419C2.34122 23.4419 0.800781 21.9014 0.800781 20.0012Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M5.28125 20.0008C5.28125 19.338 5.81851 18.8008 6.48125 18.8008H12.531C13.1938 18.8008 13.731 19.338 13.731 20.0008C13.731 20.6635 13.1938 21.2008 12.531 21.2008H6.48125C5.81851 21.2008 5.28125 20.6635 5.28125 20.0008Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M26.2695 20.0008C26.2695 19.338 26.8068 18.8008 27.4695 18.8008H32.0255C32.6883 18.8008 33.2255 19.338 33.2255 20.0008C33.2255 20.6635 32.6883 21.2008 32.0255 21.2008H27.4695C26.8068 21.2008 26.2695 20.6635 26.2695 20.0008Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M30.4563 3.20078C29.8815 3.20078 29.4156 3.6667 29.4156 4.24145C29.4156 4.81619 29.8815 5.28211 30.4563 5.28211C31.031 5.28211 31.497 4.81619 31.497 4.24145C31.497 3.6667 31.031 3.20078 30.4563 3.20078ZM27.0156 4.24145C27.0156 2.34122 28.5561 0.800781 30.4563 0.800781C32.3565 0.800781 33.897 2.34122 33.897 4.24145C33.897 6.14167 32.3565 7.68211 30.4563 7.68211C28.5561 7.68211 27.0156 6.14167 27.0156 4.24145Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M9.54418 34.7203C8.96944 34.7203 8.50352 35.1862 8.50352 35.761C8.50352 36.3357 8.96944 36.8016 9.54418 36.8016C10.1189 36.8016 10.5848 36.3357 10.5848 35.761C10.5848 35.1862 10.1189 34.7203 9.54418 34.7203ZM6.10352 35.761C6.10352 33.8608 7.64395 32.3203 9.54418 32.3203C11.4444 32.3203 12.9848 33.8608 12.9848 35.761C12.9848 37.6612 11.4444 39.2016 9.54418 39.2016C7.64395 39.2016 6.10352 37.6612 6.10352 35.761Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M20.0009 13.732C16.5387 13.732 13.732 16.5387 13.732 20.0009C13.732 23.4631 16.5387 26.2698 20.0009 26.2698C23.4631 26.2698 26.2698 23.4631 26.2698 20.0009C26.2698 16.5387 23.4631 13.732 20.0009 13.732ZM11.332 20.0009C11.332 15.2132 15.2132 11.332 20.0009 11.332C24.7886 11.332 28.6698 15.2132 28.6698 20.0009C28.6698 24.7886 24.7886 28.6698 20.0009 28.6698C15.2132 28.6698 11.332 24.7886 11.332 20.0009Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M24.4335 24.4335C24.9021 23.9649 25.6619 23.9649 26.1306 24.4335L29.9242 28.2272C30.3929 28.6958 30.3929 29.4556 29.9242 29.9242C29.4556 30.3929 28.6958 30.3929 28.2272 29.9242L24.4335 26.1306C23.9649 25.6619 23.9649 24.9021 24.4335 24.4335Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.8046 8.80264C9.27323 8.33401 10.033 8.33401 10.5017 8.80264L15.5703 13.8713C16.039 14.34 16.039 15.0998 15.5703 15.5684C15.1017 16.037 14.3419 16.037 13.8733 15.5684L8.8046 10.4997C8.33597 10.0311 8.33597 9.27127 8.8046 8.80264Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M29.8814 5.10842C30.4337 5.47484 30.5843 6.21955 30.2179 6.77179L25.1297 14.4403C24.7633 14.9925 24.0186 15.1432 23.4664 14.7768C22.9141 14.4104 22.7635 13.6656 23.1299 13.1134L28.2181 5.44488C28.5845 4.89264 29.3292 4.742 29.8814 5.10842Z\" fill=\"#476175\"\/>\r\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.5337 25.2237C17.086 25.5901 17.2366 26.3348 16.8702 26.887L11.7821 34.5555C11.4157 35.1078 10.671 35.2584 10.1187 34.892C9.56647 34.5256 9.41583 33.7809 9.78224 33.2286L14.8703 25.5601C15.2368 25.0079 15.9815 24.8572 16.5337 25.2237Z\" fill=\"#476175\"\/>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Renforc\u00e9 fibres de verre<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>PA 6<\/strong>\r\n                                            (Kingfa PA6-G15 HSBK145)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 66<\/strong>\r\n                                            (Kingfa PA66-G35 AHBK003)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC glass-filled (10%)<\/strong>\r\n                                            (Makrolon\u00ae 9417)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC glass-filled (10%)<\/strong>\r\n                                            (LEXAN\u2122 FR Resin 500R)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC glass-filled (30%)<\/strong>\r\n                                            (Bayblend\u00ae T88 GF-30)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PEEK glass-filled (30%)<\/strong>\r\n                                            (APEXTECH-HT\u00a0330GL30)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_11073_21576)\">\r\n    <path d=\"M17.0066 34.5406L13.9985 32.5891C13.4558 32.2368 12.7301 32.3914 12.3777 32.9343C12.0473 33.4438 12.1631 34.114 12.6271 34.4857H4.25633C3.56727 34.4857 2.95016 34.1294 2.60563 33.5327C2.26109 32.9359 2.26109 32.2234 2.60563 31.6266L8.14211 22.0371C8.4657 21.4767 8.27367 20.7601 7.7132 20.4365C7.15273 20.1129 6.43617 20.305 6.11258 20.8654L0.576094 30.4549C-0.192031 31.7854 -0.192031 33.3739 0.576094 34.7044C1.3443 36.0349 2.72 36.8292 4.25633 36.8292H12.4172C11.9508 37.1777 11.8052 37.8264 12.1005 38.3457C12.3165 38.7254 12.7125 38.9383 13.1201 38.9383C13.3164 38.9383 13.5155 38.8889 13.6984 38.7849L17.2719 36.7521C17.6274 36.5498 17.8518 36.1767 17.8637 35.7677C17.8702 35.5435 17.812 35.3265 17.7019 35.1393C17.5619 34.8562 17.3118 34.6374 17.0066 34.5406Z\" fill=\"#476175\"\/>\r\n    <path d=\"M39.4248 30.4567L34.008 21.0438C34.5627 21.3055 35.2323 21.0952 35.5326 20.5507C35.8451 19.984 35.6389 19.2712 35.0722 18.9588L31.472 16.9737C31.1139 16.7762 30.6784 16.7798 30.3234 16.9834C29.9685 17.1868 29.7454 17.5607 29.7348 17.9697L29.6323 21.9398C29.6156 22.5868 30.1265 23.1248 30.7734 23.1415C30.7838 23.1417 30.7941 23.1419 30.8043 23.1419C31.3777 23.1419 31.8578 22.7273 31.9559 22.1763L37.3944 31.6271C37.7389 32.2238 37.7389 32.9364 37.3944 33.5332C37.0498 34.1299 36.4327 34.4862 35.7437 34.4862H25.0057C24.3586 34.4862 23.834 35.0109 23.834 35.658C23.834 36.3051 24.3586 36.8297 25.0057 36.8297H35.7437C37.28 36.8297 38.6557 36.0354 39.4239 34.7049C40.1921 33.3744 40.1921 31.7858 39.4248 30.4567Z\" fill=\"#476175\"\/>\r\n    <path d=\"M25.6761 25.9835C27.7543 23.9054 27.4195 20.3896 27.4042 20.241C27.3475 19.6886 26.9107 19.2519 26.3583 19.1952C26.2709 19.1861 25.0166 19.0667 23.5757 19.3935C23.577 19.3484 23.5778 19.3033 23.5778 19.2582C23.5778 16.3194 20.8551 14.0701 20.7392 13.9758C20.3084 13.6253 19.691 13.6253 19.2601 13.9758C19.1442 14.0701 16.4215 16.3194 16.4215 19.2582C16.4215 19.3033 16.4224 19.3484 16.4236 19.3935C14.9828 19.0667 13.7286 19.1861 13.641 19.1951C13.0886 19.2518 12.6518 19.6885 12.5951 20.241C12.5799 20.3896 12.245 23.9053 14.3232 25.9835C15.6563 27.3165 17.58 27.6564 18.828 27.7249V28.8538C18.828 29.5009 19.3526 30.0255 19.9997 30.0255C20.6468 30.0255 21.1714 29.5009 21.1714 28.8538V27.7249C22.4194 27.6564 24.3432 27.3164 25.6761 25.9835ZM24.0191 24.3264C23.302 25.0435 22.1292 25.3036 21.2233 25.3763C21.296 24.4694 21.5561 23.2971 22.273 22.5803C22.9897 21.8636 24.1617 21.6035 25.0674 21.5306C25.0034 22.3874 24.7703 23.5753 24.0191 24.3264ZM18.7649 19.2582C18.7649 18.2442 19.4103 17.231 19.9995 16.5389C20.5893 17.2316 21.2343 18.2444 21.2343 19.2582C21.2884 20.3495 20.6152 20.8756 19.9996 21.6767C19.6726 21.3096 18.7649 20.1969 18.7649 19.2582ZM15.9803 24.3264C15.2631 23.6094 15.0031 22.4365 14.9304 21.5306C15.8372 21.6034 17.0096 21.8635 17.7263 22.5803C18.4435 23.2974 18.7035 24.4702 18.7763 25.3761C17.8694 25.3034 16.6971 25.0432 15.9803 24.3264Z\" fill=\"#476175\"\/>\r\n    <path d=\"M11.1889 14.4006C11.3721 14.5087 11.5778 14.5628 11.7836 14.5628C11.9737 14.5628 12.1641 14.5166 12.3371 14.4238L15.8376 12.5478C16.408 12.2421 16.6225 11.532 16.3168 10.9616C16.0311 10.4284 15.3918 10.2064 14.844 10.4293L18.3494 4.35898C18.694 3.76219 19.3111 3.40594 20.0001 3.40594C20.6892 3.40594 21.3063 3.76219 21.6508 4.35898L25.648 11.2823C25.9716 11.8427 26.6882 12.0347 27.2486 11.7112C27.8091 11.3876 28.0011 10.671 27.6775 10.1105L23.6804 3.18727C22.9122 1.8568 21.5364 1.0625 20.0001 1.0625C18.4638 1.0625 17.088 1.8568 16.3199 3.18719L12.8879 9.13031C12.814 8.55266 12.3211 8.10859 11.7268 8.10859C11.7213 8.10859 11.7157 8.10859 11.7101 8.10867C11.0631 8.11766 10.5457 8.64953 10.5548 9.29656L10.6121 13.4074C10.6177 13.8164 10.8364 14.193 11.1889 14.4006Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_11073_21576\">\r\n      <rect width=\"40\" height=\"40\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Biocompatible<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (LNP\u2122 COLORCOMP\u2122 Compound A1000FXB)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PBT<\/strong>\r\n                                            (LNP\u2122 ELCRIN\u2122 W1000JiQ)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (LNP\u2122 ELCRIN\u2122 HPH4504HB)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC-ABS<\/strong>\r\n                                            (LNP\u2122 COLORCOMP\u2122 Compound N1000EXB)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PEI<\/strong>\r\n                                            (LNP\u2122 THERMOCOMP\u2122 Compound EC006AQW)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_12181_12514)\">\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M17.9573 0C17.3021 0 16.7709 0.536504 16.7709 1.19831V4.68092H13.3228C12.6675 4.68092 12.1363 5.21742 12.1363 5.87923V10.5601C12.1363 11.0294 12.4034 11.4357 12.7923 11.6323C12.952 11.713 13.1321 11.7585 13.3228 11.7585H16.7709V15.2411C16.7709 15.9029 17.3021 16.4394 17.9573 16.4394H22.5919C22.742 16.4394 22.8855 16.4113 23.0176 16.3599L23.682 15.715C23.744 15.5696 23.7784 15.4094 23.7784 15.2411V11.7585H27.2265C27.8818 11.7585 28.413 11.222 28.413 10.5601V6.12562V5.87923C28.413 5.21742 27.8818 4.68092 27.2265 4.68092H23.7784V1.19831C23.7784 0.536504 23.2472 0 22.5919 0H17.9573ZM19.1438 2.39663V5.87923C19.1438 6.54104 18.6126 7.07755 17.9573 7.07755H14.5092V9.36183H17.9573C18.2077 9.36183 18.44 9.44017 18.6314 9.5739C18.941 9.79014 19.1438 10.1512 19.1438 10.5601V14.0428H21.4055V10.5601C21.4055 9.89834 21.9367 9.36183 22.5919 9.36183H26.0401V7.07755H25.7127H22.5919C21.9367 7.07755 21.4055 6.54104 21.4055 5.87923V2.39663H19.1438Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.2777 6.81291C7.27793 4.85658 5.70781 3.27763 3.77529 3.27665C1.84277 3.27566 1.72634 3.5299 0.989284 4.19332C0.252224 4.85674 0.000238803 5.69122 0.000570943 6.67422C-0.000508512 11.1835 0.000208185 13.9803 0.000570943 18.673C0.000208185 21.4698 0.772493 22.0762 1.48364 23.2838C2.4531 25.076 4.09256 27.8009 4.09256 27.8009L5.67683 30.544V32.9225H4.826C4.17074 32.9225 3.63955 33.459 3.63955 34.1208V38.8017C3.63955 39.4635 4.17074 40 4.826 40H35.7233C36.3785 40 36.9097 39.4635 36.9097 38.8017V34.1208C36.9097 33.459 36.3785 32.9225 35.7233 32.9225H34.593V30.544L38.7862 23.2838C39.5811 21.9074 40 20.3424 40 18.749V6.81542C40 4.86037 38.4303 3.27562 36.4945 3.27665C35.6706 3.27706 34.9125 3.56431 34.314 4.04536C33.5419 4.66581 33.0352 5.60864 32.9947 6.67422C32.993 6.72022 32.9921 6.76646 32.9921 6.81291L32.9925 13.4775C31.6634 13.0207 30.1353 13.4021 29.1788 14.5535L23.7753 21.0576C22.312 22.8189 21.5098 25.0447 21.5098 27.344V32.9225H19.0411V27.344C19.0411 25.3758 18.1733 23.4615 17.0863 21.8463C16.9034 21.5745 16.7063 21.3112 16.4956 21.0576L11.0921 14.5535C10.1353 13.4018 8.60669 13.0205 7.27735 13.4778L7.2777 6.81291ZM3.774 5.67327C3.14938 5.67293 2.64272 6.18429 2.64272 6.81542V18.749C2.64272 19.9181 2.95007 21.0664 3.53331 22.0762L7.88812 29.6162C7.99397 29.7995 8.04974 30.0078 8.04974 30.22V30.6188V32.9225H16.6682V27.344C16.6682 25.9962 16.0231 24.6818 15.3426 23.539C15.1468 23.21 14.9248 22.8953 14.6778 22.5981L9.27431 16.094C8.8731 15.6111 8.16023 15.5478 7.68178 15.9529C7.20301 16.3582 7.14034 17.0789 7.54194 17.5623L12.3508 23.3498C12.7721 23.8568 12.7067 24.6126 12.2047 25.0381C11.7028 25.4635 10.9544 25.3974 10.5332 24.8905L5.72427 19.1029C5.16571 18.4306 4.89692 17.6101 4.90453 16.7963L4.9044 16.7784L4.90479 6.81263C4.90486 6.18404 4.40082 5.67358 3.774 5.67327ZM32.9925 16.7796C32.9794 16.4703 32.8426 16.1675 32.5892 15.953C32.1107 15.5479 31.3978 15.6111 30.9966 16.094L25.593 22.5981C24.4883 23.9279 23.8827 25.6082 23.8827 27.344V32.9225H32.2201V30.22C32.2201 30.0078 32.2758 29.7995 32.3817 29.6162L36.7365 22.0762C37.3197 21.0664 37.6271 19.9181 37.6271 18.749V6.81542C37.6271 6.18429 37.1204 5.67293 36.4958 5.67327C35.869 5.67358 35.3649 6.18403 35.365 6.81262L35.3654 16.7413C35.3859 17.573 35.1178 18.4155 34.5466 19.1029L29.7377 24.8905C29.3165 25.3974 28.5681 25.4635 28.0662 25.0381C27.5642 24.6126 27.4988 23.8568 27.92 23.3498L32.7289 17.5623C32.9067 17.3484 32.9935 17.088 32.9935 16.8291C32.9931 16.8193 32.9929 16.8095 32.9927 16.7997L32.9925 16.7796ZM21.4611 35.3191V37.6034H34.5368V35.3191H21.4611ZM19.0882 37.6034V35.3191H17.8547H17.8536H6.01246V37.6034H19.0882Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_12181_12514\">\r\n      <rect width=\"40\" height=\"40\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>Qualit\u00e9 m\u00e9dicale<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (LNP\u2122 STAT-KON\u2122 Compound AX02747)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 12<\/strong>\r\n                                            (Grilamid\u00ae L 16 nat)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PBT<\/strong>\r\n                                            (LNP\u2122 ELCRIN\u2122 W1000JiQ)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (LEXAN\u2122 HEALTHCARE RESIN HPS1)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PEI<\/strong>\r\n                                            (LNP\u2122 THERMOCOMP\u2122 Compound EC006AQW)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PMMA<\/strong>\r\n                                            (POLYCASA\u00ae ACRYL G 55)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>POM<\/strong>\r\n                                            (LNP\u2122 LUBRICOMP\u2122 Compound KL004)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                            \r\n<div class=\"materials-accordion__item accordion__item\">\r\n    <div class=\"materials-accordion__item-title-wrapper accordion__title\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\">\r\n  <g clip-path=\"url(#clip0_12178_12382)\">\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-0.0625 31.0625C-0.0625 31.6148 0.385215 32.0625 0.9375 32.0625H31.0573C31.6095 32.0625 32.0573 31.6148 32.0573 31.0625V26.4513C32.0573 25.899 31.6095 25.4513 31.0573 25.4513H0.9375C0.385215 25.4513 -0.0625 25.899 -0.0625 26.4513V31.0625ZM1.9375 30.0625V27.4513H30.0573V30.0625H1.9375Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.3095 31.9842C7.81866 31.7702 8.058 31.184 7.84406 30.6749L5.90656 26.0636C5.69263 25.5545 5.10644 25.3151 4.59727 25.5291C4.0881 25.743 3.84877 26.3292 4.06271 26.8384L6.00021 31.4496C6.21414 31.9588 6.80033 32.1981 7.3095 31.9842Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.3329 31.9842C12.8421 31.7702 13.0814 31.184 12.8675 30.6749L10.93 26.0636C10.7161 25.5545 10.1299 25.3151 9.62071 25.5291C9.11154 25.743 8.87221 26.3292 9.08615 26.8384L11.0236 31.4496C11.2376 31.9588 11.8238 32.1981 12.3329 31.9842Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M17.3486 31.9842C17.8577 31.7702 18.0971 31.184 17.8831 30.6749L15.9456 26.0636C15.7317 25.5545 15.1455 25.3151 14.6363 25.5291C14.1272 25.743 13.8878 26.3292 14.1018 26.8384L16.0393 31.4496C16.2532 31.9588 16.8394 32.1981 17.3486 31.9842Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M22.372 31.9842C22.8812 31.7702 23.1205 31.184 22.9066 30.6749L20.9691 26.0636C20.7551 25.5545 20.1689 25.3151 19.6598 25.5291C19.1506 25.743 18.9113 26.3292 19.1252 26.8384L21.0627 31.4496C21.2766 31.9588 21.8628 32.1981 22.372 31.9842Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M27.3876 31.9842C27.8968 31.7702 28.1361 31.184 27.9222 30.6749L25.9847 26.0636C25.7708 25.5545 25.1846 25.3151 24.6754 25.5291C24.1662 25.743 23.9269 26.3292 24.1408 26.8384L26.0783 31.4496C26.2923 31.9588 26.8785 32.1981 27.3876 31.9842Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.0147 27.4512C16.2799 27.4512 16.5343 27.3458 16.7218 27.1583L23.771 20.109C24.0519 19.8282 24.1399 19.4079 23.9954 19.038C23.8508 18.6681 23.5011 18.4188 23.1043 18.4027L20.0568 18.2796C19.505 18.2573 19.0395 18.6866 19.0173 19.2384C18.995 19.7903 19.4242 20.2557 19.9761 20.278L20.7427 20.309L16.0147 25.037L10.2774 19.2997C9.8869 18.9092 9.25373 18.9092 8.86321 19.2997C8.47268 19.6902 8.47268 20.3234 8.86321 20.7139L15.3076 27.1583C15.4951 27.3458 15.7495 27.4512 16.0147 27.4512Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M23.0625 23.2109C23.6148 23.2109 24.0625 22.7632 24.0625 22.2109V19.4019C24.0625 18.8497 23.6148 18.4019 23.0625 18.4019C22.5102 18.4019 22.0625 18.8497 22.0625 19.4019V22.2109C22.0625 22.7632 22.5102 23.2109 23.0625 23.2109Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M9.06633 15.3555C9.45685 15.7461 10.09 15.7461 10.4805 15.3555L13.3059 12.5302C13.6964 12.1396 13.6964 11.5065 13.3059 11.116C12.9154 10.7254 12.2822 10.7254 11.8917 11.116L9.06633 13.9413C8.67581 14.3319 8.67581 14.965 9.06633 15.3555Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M10.2812 8.49744C10.2812 11.722 12.8953 14.3359 16.1197 14.3359C19.3443 14.3359 21.9583 11.722 21.9583 8.49744C21.9583 5.2729 19.3443 2.65888 16.1197 2.65888C12.8953 2.65888 10.2812 5.27291 10.2812 8.49744ZM16.1197 12.3359C13.9998 12.3359 12.2812 10.6174 12.2812 8.49744C12.2812 6.37746 13.9999 4.65888 16.1197 4.65888C18.2397 4.65888 19.9583 6.37747 19.9583 8.49744C19.9583 10.6174 18.2397 12.3359 16.1197 12.3359Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.1094 17.0234C16.6617 17.0234 17.1094 16.5757 17.1094 16.0234V13.3353C17.1094 12.783 16.6617 12.3352 16.1094 12.3352C15.5571 12.3352 15.1094 12.783 15.1094 13.3353V16.0234C15.1094 16.5757 15.5571 17.0234 16.1094 17.0234Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18.9335 5.88679C19.324 6.27732 19.9572 6.27732 20.3477 5.88679L23.1569 3.07767C23.5474 2.68715 23.5474 2.05398 23.1569 1.66346C22.7663 1.27293 22.1332 1.27293 21.7426 1.66346L18.9335 4.47258C18.543 4.8631 18.543 5.49627 18.9335 5.88679Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.1094 4.66211C16.6617 4.66211 17.1094 4.21439 17.1094 3.66211V1.00092C17.1094 0.448637 16.6617 0.000922203 16.1094 0.000922203C15.5571 0.000922203 15.1094 0.448637 15.1094 1.00092V3.66211C15.1094 4.21439 15.5571 4.66211 16.1094 4.66211Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M13.2963 5.89461C13.6868 5.50408 13.6868 4.87092 13.2963 4.48039L10.4805 1.66464C10.09 1.27412 9.45685 1.27412 9.06633 1.66464C8.67581 2.05517 8.67581 2.68833 9.06633 3.07886L11.8821 5.89461C12.2726 6.28513 12.9058 6.28513 13.2963 5.89461Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M23.1575 15.3555C23.548 14.965 23.548 14.3319 23.1575 13.9413L20.3321 11.116C19.9416 10.7254 19.3084 10.7254 18.9179 11.116C18.5274 11.5065 18.5274 12.1396 18.9179 12.5302L21.7433 15.3555C22.1338 15.7461 22.767 15.7461 23.1575 15.3555Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.1875 8.49805C7.1875 9.05033 7.63522 9.49805 8.1875 9.49805H11.2783C11.8306 9.49805 12.2783 9.05033 12.2783 8.49805C12.2783 7.94576 11.8306 7.49805 11.2783 7.49805H8.1875C7.63522 7.49805 7.1875 7.94576 7.1875 8.49805Z\" fill=\"#476175\"\/>\r\n    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M19.9531 8.49805C19.9531 9.05033 20.4008 9.49805 20.9531 9.49805H23.8138C24.3661 9.49805 24.8138 9.05033 24.8138 8.49805C24.8138 7.94576 24.3661 7.49805 23.8138 7.49805H20.9531C20.4008 7.49805 19.9531 7.94576 19.9531 8.49805Z\" fill=\"#476175\"\/>\r\n  <\/g>\r\n  <defs>\r\n    <clipPath id=\"clip0_12178_12382\">\r\n      <rect width=\"32\" height=\"32\" fill=\"white\"\/>\r\n    <\/clipPath>\r\n  <\/defs>\r\n<\/svg>                <h3 class=\"materials-accordion__item-title title title--04\">\r\n            <span>R\u00e9sistant aux UV<\/span>\r\n        <\/h3>\r\n    <\/div>\r\n    <div class=\"materials-accordion__content-wrapper\">\r\n        <ul class=\"materials-accordion__content\">\r\n                            <li>\r\n                    <strong>ABS<\/strong>\r\n                                            (CYCOLAC\u2122 Resin FR15U)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>HDPE<\/strong>\r\n                                            (DOW\u2122 HDPE\u00a0KT 10000 UE)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>HDPE<\/strong>\r\n                                            (ExxonMobil\u2122 HDPE HMA 016)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PA 66 glass-filled (30%)<\/strong>\r\n                                            (Zytel\u00ae 74G33W NC010)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PC<\/strong>\r\n                                            (Makrolon\u00ae 6557)\r\n                                    <\/li>\r\n                            <li>\r\n                    <strong>PP<\/strong>\r\n                                            (Kingfa AP-202W)\r\n                                    <\/li>\r\n                    <\/ul>\r\n    <\/div>\r\n<\/div>\r\n                                    <\/div>\r\n                    <\/div>\r\n\r\n            <\/div>\r\n<\/section>\r\n\n\n<section class=\"finishes slider-block  light blue-10\">\r\n    <div class=\"finishes__container section container\">\r\n        <div class=\"slider__title-wrapper\">\r\n            <h2 class=\"title title--02\">Finitions de surface pour le moulage par injection<\/h2>\r\n            <div class=\"slider__btns\">\r\n                <button type=\"button\" class=\"slider__btn-prev slider__btn finishes__slider-btn-prev\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"26\" height=\"26\" viewBox=\"0 0 26 26\" fill=\"none\">\r\n                    <path\r\n                        d=\"M17.4935 4.19138L7.82476 12.5297C7.548 12.7683 7.548 13.2279 7.82476 13.4691L17.4935 21.8074C17.8541 22.1172 18.3822 21.8379 18.3822 21.3377V4.66111C18.3822 4.16091 17.8541 3.88161 17.4935 4.19138Z\"\r\n                        fill=\"white\"\r\n                    \/>\r\n                    <\/svg>\r\n                <\/button>\r\n                <button type=\"button\" class=\" slider__btn-next slider__btn finishes__slider-btn-next\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"26\" height=\"26\" viewBox=\"0 0 26 26\" fill=\"none\">\r\n                    <path\r\n                        d=\"M18.1746 12.5297L8.50586 4.19138C8.14531 3.88161 7.61719 4.16091 7.61719 4.66111V21.3377C7.61719 21.8379 8.14531 22.1172 8.50586 21.8074L18.1746 13.4691C18.4514 13.2304 18.4514 12.7683 18.1746 12.5297Z\"\r\n                        fill=\"white\"\r\n                    \/>\r\n                    <\/svg>\r\n                <\/button>\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"finishes__slider slider__container\">\r\n            <div class=\"swiper-wrapper\">\r\n                                        <div class=\"finishes__item swiper-slide card\">\r\n                            <div class=\"finishes__item-image finishes__item-image_full\">\r\n                                <img decoding=\"async\" width=\"1455\" height=\"774\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/injection-moulding-part-black-polypropylene-3.png\" class=\"attachment-full size-full\" alt=\"\" style=\"object-position:center;\" srcset=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/injection-moulding-part-black-polypropylene-3.png 1455w, https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/injection-moulding-part-black-polypropylene-3-480x255.png 480w, https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/injection-moulding-part-black-polypropylene-3-1440x766.png 1440w, https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/injection-moulding-part-black-polypropylene-3-768x409.png 768w\" sizes=\"(max-width: 1455px) 100vw, 1455px\" \/>                            <\/div>\r\n                            <div class=\"finishes__item-container\">\r\n                                <div class=\"finishes__item-main\">\r\n                                    <div>\r\n                                        <div class=\"finishes__item-content\">\r\n                                            <h4 class=\"title title--04\">Surface standard<\/h4>\r\n                                            <div class=\"finishes__item-content-text\">\r\n                                                <ul>\n<li>Finition choisie par le mouleur. G\u00e9n\u00e9ralement SPI C-1 selon la g\u00e9om\u00e9trie et les d\u00e9pouilles.<\/li>\n<li>Les surfaces internes non visibles sont laiss\u00e9es brutes d\u2019usinage.<\/li>\n<\/ul>\n                                                                                            <\/div>\r\n                                        <\/div>\r\n                                        <div class=\"read-more-btn text-btn\">\r\n                                            <span class=\"open\"> Lire la suite<\/span>    \r\n                                            <span class=\"close\"> Masquer<\/span>            \r\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                                            <path d=\"M20.719 6H18.9612C18.8417 6 18.7292 6.05859 18.6589 6.15469L12.0003 15.3328L5.3417 6.15469C5.27139 6.05859 5.15889 6 5.03936 6H3.28155C3.1292 6 3.04014 6.17344 3.1292 6.29766L11.3933 17.6906C11.6933 18.1031 12.3073 18.1031 12.605 17.6906L20.869 6.29766C20.9605 6.17344 20.8714 6 20.719 6Z\" fill=\"#0E6AED\"\/>\r\n                                            <\/svg>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"finishes__item swiper-slide card\">\r\n                            <div class=\"finishes__item-image \">\r\n                                                                        <div class=\"swiper finishes-options__slider\" data-id=\"6a98137f7c06d\">\r\n                                            <div class=\"swiper-wrapper\">\r\n                                                                                                    <div class=\"swiper-slide\">\r\n                                                                                                                <img decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/07\/SPI-Finishes.gif\" class=\"attachment-full size-full\" alt=\"Injection moulding SPI surface finishes\" style=\"object-position:center;\" \/>                                                    <\/div>\r\n                                                                                                    <div class=\"swiper-slide\">\r\n                                                                                                                <img decoding=\"async\" width=\"2048\" height=\"1676\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/04\/SPI-Mold-Finish-Guide.jpg\" class=\"attachment-full size-full\" alt=\"SPI Mould Finish Guide\" style=\"object-position:center;\" srcset=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/04\/SPI-Mold-Finish-Guide.jpg 2048w, https:\/\/xometry.eu\/wp-content\/uploads\/2021\/04\/SPI-Mold-Finish-Guide-480x393.jpg 480w, https:\/\/xometry.eu\/wp-content\/uploads\/2021\/04\/SPI-Mold-Finish-Guide-1440x1178.jpg 1440w, https:\/\/xometry.eu\/wp-content\/uploads\/2021\/04\/SPI-Mold-Finish-Guide-768x629.jpg 768w, https:\/\/xometry.eu\/wp-content\/uploads\/2021\/04\/SPI-Mold-Finish-Guide-1536x1257.jpg 1536w, https:\/\/xometry.eu\/wp-content\/uploads\/2021\/04\/SPI-Mold-Finish-Guide-1600x1309.jpg 1600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                                                    <\/div>\r\n                                                                                            <\/div>\r\n                                            <div class=\"swiper-button-next next-6a98137f7c06d\"><\/div>\r\n                                            <div class=\"swiper-button-prev prev-6a98137f7c06d\"><\/div>\r\n                                            <div class=\"swiper-pagination\"><\/div>\r\n                                        <\/div>\r\n                                                                <\/div>\r\n                            <div class=\"finishes__item-container\">\r\n                                <div class=\"finishes__item-main\">\r\n                                    <div>\r\n                                        <div class=\"finishes__item-content\">\r\n                                            <h4 class=\"title title--04\">SPI<\/h4>\r\n                                            <div class=\"finishes__item-content-text\">\r\n                                                <p>Les finitions SPI sont un ensemble de finitions de moule standard avec diff\u00e9rentes textures polies pour des propri\u00e9t\u00e9s am\u00e9lior\u00e9es.<\/p>\n                                                                                                    <div>\r\n                                                    Notes :                                                        <p>Il est recommand\u00e9 de fournir un CMF (couleur\/mat\u00e9riau\/finition) qui d\u00e9finit les caract\u00e9ristiques visuelles et tactiles d&rsquo;un produit, afin de garantir la coh\u00e9rence de la conception et la pr\u00e9cision de la fabrication.<\/p>\n                                                    <\/div>\r\n                                                                                            <\/div>\r\n                                        <\/div>\r\n                                        <div class=\"read-more-btn text-btn\">\r\n                                            <span class=\"open\"> Lire la suite<\/span>    \r\n                                            <span class=\"close\"> Masquer<\/span>            \r\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                                            <path d=\"M20.719 6H18.9612C18.8417 6 18.7292 6.05859 18.6589 6.15469L12.0003 15.3328L5.3417 6.15469C5.27139 6.05859 5.15889 6 5.03936 6H3.28155C3.1292 6 3.04014 6.17344 3.1292 6.29766L11.3933 17.6906C11.6933 18.1031 12.3073 18.1031 12.605 17.6906L20.869 6.29766C20.9605 6.17344 20.8714 6 20.719 6Z\" fill=\"#0E6AED\"\/>\r\n                                            <\/svg>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                                                            <div class=\"finishes__item-footer\">\r\n                                            <h5 class=\"title title--05\">R\u00e9sultat final :<\/h5>\r\n                                                                                                <ul>\r\n                                                                                                                                                                        <li>Lourdement poli, allant du semi-brillant au mat fin et grossier selon la s\u00e9lection<\/li>\r\n                                                                                                                                                                                                                                <li>A1, A2, A3, B1, B2, B3, C1, C2, C3, D1, D2, D3<\/li>\r\n                                                                                                                                                            <\/ul>\r\n                                                                                    <\/div>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"finishes__item swiper-slide card\">\r\n                            <div class=\"finishes__item-image \">\r\n                                                                        <div class=\"swiper finishes-options__slider\" data-id=\"6a98137f7d1a8\">\r\n                                            <div class=\"swiper-wrapper\">\r\n                                                                                                    <div class=\"swiper-slide\">\r\n                                                                                                                <img decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/08\/STD-Finishes-light.gif\" class=\"attachment-full size-full\" alt=\"Injection moulding VDI surface finishes\" style=\"object-position:center;\" \/>                                                    <\/div>\r\n                                                                                                    <div class=\"swiper-slide\">\r\n                                                                                                                <img decoding=\"async\" width=\"646\" height=\"540\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/07\/Injection-Moulding-VDI-Finishes.png\" class=\"attachment-full size-full\" alt=\"Injection Moulding VDI Finishes\" style=\"object-position:center;\" srcset=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/07\/Injection-Moulding-VDI-Finishes.png 646w, https:\/\/xometry.eu\/wp-content\/uploads\/2021\/07\/Injection-Moulding-VDI-Finishes-480x401.png 480w\" sizes=\"(max-width: 646px) 100vw, 646px\" \/>                                                    <\/div>\r\n                                                                                            <\/div>\r\n                                            <div class=\"swiper-button-next next-6a98137f7d1a8\"><\/div>\r\n                                            <div class=\"swiper-button-prev prev-6a98137f7d1a8\"><\/div>\r\n                                            <div class=\"swiper-pagination\"><\/div>\r\n                                        <\/div>\r\n                                                                <\/div>\r\n                            <div class=\"finishes__item-container\">\r\n                                <div class=\"finishes__item-main\">\r\n                                    <div>\r\n                                        <div class=\"finishes__item-content\">\r\n                                            <h4 class=\"title title--04\">VDI<\/h4>\r\n                                            <div class=\"finishes__item-content-text\">\r\n                                                <p>VDI est une norme internationale pour le texturage de moules de surfaces mates. Elle est principalement trait\u00e9e par usinage par \u00e9lectro-\u00e9rosion (EDM) lors de l&rsquo;usinage de moules.<\/p>\n                                                                                                    <div>\r\n                                                    Notes :                                                        <p>Il est recommand\u00e9 de fournir un CMF (couleur\/mat\u00e9riau\/finition) qui d\u00e9finit les caract\u00e9ristiques visuelles et tactiles d&rsquo;un produit, afin de garantir la coh\u00e9rence de la conception et la pr\u00e9cision de la fabrication.<\/p>\n                                                    <\/div>\r\n                                                                                            <\/div>\r\n                                        <\/div>\r\n                                        <div class=\"read-more-btn text-btn\">\r\n                                            <span class=\"open\"> Lire la suite<\/span>    \r\n                                            <span class=\"close\"> Masquer<\/span>            \r\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                                            <path d=\"M20.719 6H18.9612C18.8417 6 18.7292 6.05859 18.6589 6.15469L12.0003 15.3328L5.3417 6.15469C5.27139 6.05859 5.15889 6 5.03936 6H3.28155C3.1292 6 3.04014 6.17344 3.1292 6.29766L11.3933 17.6906C11.6933 18.1031 12.3073 18.1031 12.605 17.6906L20.869 6.29766C20.9605 6.17344 20.8714 6 20.719 6Z\" fill=\"#0E6AED\"\/>\r\n                                            <\/svg>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                                                            <div class=\"finishes__item-footer\">\r\n                                            <h5 class=\"title title--05\">R\u00e9sultat final :<\/h5>\r\n                                                                                                <ul>\r\n                                                                                                                                                                        <li>Grain fin \u00e0 gros selon la s\u00e9lection<\/li>\r\n                                                                                                                                                                                                                                <li>VDI12, VDI15, VDI18,VDI21, VDI 24, VDI27, VDI30, VDI33, VDI36, VDI39, VDI42, VDI45<\/li>\r\n                                                                                                                                                            <\/ul>\r\n                                                                                    <\/div>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"finishes__item swiper-slide card\">\r\n                            <div class=\"finishes__item-image finishes__item-image_full\">\r\n                                <img decoding=\"async\" width=\"970\" height=\"582\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2023\/09\/custom.png\" class=\"attachment-full size-full\" alt=\"\" style=\"object-position:center;\" srcset=\"https:\/\/xometry.eu\/wp-content\/uploads\/2023\/09\/custom.png 970w, https:\/\/xometry.eu\/wp-content\/uploads\/2023\/09\/custom-480x288.png 480w, https:\/\/xometry.eu\/wp-content\/uploads\/2023\/09\/custom-768x461.png 768w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/>                            <\/div>\r\n                            <div class=\"finishes__item-container\">\r\n                                <div class=\"finishes__item-main\">\r\n                                    <div>\r\n                                        <div class=\"finishes__item-content\">\r\n                                            <h4 class=\"title title--04\">Finition personnalis\u00e9e<\/h4>\r\n                                            <div class=\"finishes__item-content-text\">\r\n                                                <p>Pour des exigences particuli\u00e8res au-del\u00e0 des standards SPI ou VDI, nous proposons des finitions enti\u00e8rement personnalisables. Partagez vos besoins sp\u00e9cifiques et nous travaillerons avec vous pour obtenir le rendu attendu.<\/p>\n                                                                                            <\/div>\r\n                                        <\/div>\r\n                                        <div class=\"read-more-btn text-btn\">\r\n                                            <span class=\"open\"> Lire la suite<\/span>    \r\n                                            <span class=\"close\"> Masquer<\/span>            \r\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                                            <path d=\"M20.719 6H18.9612C18.8417 6 18.7292 6.05859 18.6589 6.15469L12.0003 15.3328L5.3417 6.15469C5.27139 6.05859 5.15889 6 5.03936 6H3.28155C3.1292 6 3.04014 6.17344 3.1292 6.29766L11.3933 17.6906C11.6933 18.1031 12.3073 18.1031 12.605 17.6906L20.869 6.29766C20.9605 6.17344 20.8714 6 20.719 6Z\" fill=\"#0E6AED\"\/>\r\n                                            <\/svg>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                <\/div>\r\n            <div class=\"slider__pagination\"><\/div>\r\n        <\/div>\r\n            <\/div>\r\n<\/section>\n\n<section class=\"additional-capabilities light dark-to-light-gradient\">\r\n  <div class=\"additional-capabilities__container section container\">\r\n        <div class=\"section__title-wrapper\">\r\n                    <h2 class=\"title title--02\">Op\u00e9rations secondaires<\/h2>\r\n                    <div class=\"section__description\">\r\n                <p>Les op\u00e9rations secondaires am\u00e9liorent la fonctionnalit\u00e9 ou l\u2019esth\u00e9tique de vos pi\u00e8ces apr\u00e8s moulage. Vous pouvez les sp\u00e9cifier dans vos plans techniques. Voici les options disponibles :<\/p>\n            <\/div>\r\n            <\/div>\r\n    <div class=\"additional-capabilities__wpapper\"> \r\n                    <div class=\"additional-capabilities__image-wrapper\">\r\n                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/02\/additional-capabilities-scaled.jpg\" alt=\"additional capabilities\" class=\"desktop-position_center mobile-position_center\">\r\n            <\/div>\r\n                <div class=\"additional-capabilities__list\"> \r\n                            <div class=\"additional-capabilities__item accordion__item\"> \r\n                <div class=\"additional-capabilities__item-title-wrapper accordion__title\"> \r\n                    <h3 class=\"additional-capabilities__item-title title title--04\"> \r\n                    Inserts                    <\/h3> \r\n                <\/div> \r\n                <div class=\"additional-capabilities__item-content-wrapper\"> \r\n                    <div class=\"additional-capabilities__item-content\"> \r\n                    <p>Nous pouvons installer des inserts standards en tailles UNF et m\u00e9triques, couramment utilis\u00e9s pour cr\u00e9er des connexions filet\u00e9es durables dans les pi\u00e8ces plastiques.<\/p>\n                    <\/div> \r\n                <\/div> \r\n                <\/div> \r\n                            <div class=\"additional-capabilities__item accordion__item\"> \r\n                <div class=\"additional-capabilities__item-title-wrapper accordion__title\"> \r\n                    <h3 class=\"additional-capabilities__item-title title title--04\"> \r\n                    Tampographie                    <\/h3> \r\n                <\/div> \r\n                <div class=\"additional-capabilities__item-content-wrapper\"> \r\n                    <div class=\"additional-capabilities__item-content\"> \r\n                    <p>Permet de transf\u00e9rer une image 2D sur une pi\u00e8ce 3D. Toutes les images sont v\u00e9rifi\u00e9es pour s\u2019assurer de leur compatibilit\u00e9 avec le proc\u00e9d\u00e9.<\/p>\n                    <\/div> \r\n                <\/div> \r\n                <\/div> \r\n                            <div class=\"additional-capabilities__item accordion__item\"> \r\n                <div class=\"additional-capabilities__item-title-wrapper accordion__title\"> \r\n                    <h3 class=\"additional-capabilities__item-title title title--04\"> \r\n                    Gravure laser                    <\/h3> \r\n                <\/div> \r\n                <div class=\"additional-capabilities__item-content-wrapper\"> \r\n                    <div class=\"additional-capabilities__item-content\"> \r\n                    <p>Grave de fa\u00e7on permanente des d\u00e9tails tels que des num\u00e9ros de pi\u00e8ce, logos ou marquages personnalis\u00e9s sur vos pi\u00e8ces, avec pr\u00e9cision et durabilit\u00e9.<\/p>\n                    <\/div> \r\n                <\/div> \r\n                <\/div> \r\n                            <div class=\"additional-capabilities__item accordion__item\"> \r\n                <div class=\"additional-capabilities__item-title-wrapper accordion__title\"> \r\n                    <h3 class=\"additional-capabilities__item-title title title--04\"> \r\n                    Peinture                    <\/h3> \r\n                <\/div> \r\n                <div class=\"additional-capabilities__item-content-wrapper\"> \r\n                    <div class=\"additional-capabilities__item-content\"> \r\n                    <p>Application d\u2019une couche de peinture de couleur personnalis\u00e9e pour des raisons esth\u00e9tiques ou fonctionnelles, comme une meilleure r\u00e9sistance aux UV ou une durabilit\u00e9 accrue.<\/p>\n                    <\/div> \r\n                <\/div> \r\n                <\/div> \r\n                            <div class=\"additional-capabilities__item accordion__item\"> \r\n                <div class=\"additional-capabilities__item-title-wrapper accordion__title\"> \r\n                    <h3 class=\"additional-capabilities__item-title title title--04\"> \r\n                    S\u00e9rigraphie                    <\/h3> \r\n                <\/div> \r\n                <div class=\"additional-capabilities__item-content-wrapper\"> \r\n                    <div class=\"additional-capabilities__item-content\"> \r\n                    <p>Application d\u2019encre \u00e0 travers un pochoir pour cr\u00e9er des motifs ou du texte sur une pi\u00e8ce, id\u00e9al pour les surfaces plates ou l\u00e9g\u00e8rement courbes.<\/p>\n                    <\/div> \r\n                <\/div> \r\n                <\/div> \r\n                            <div class=\"additional-capabilities__item accordion__item\"> \r\n                <div class=\"additional-capabilities__item-title-wrapper accordion__title\"> \r\n                    <h3 class=\"additional-capabilities__item-title title title--04\"> \r\n                    Soudure par ultrasons                    <\/h3> \r\n                <\/div> \r\n                <div class=\"additional-capabilities__item-content-wrapper\"> \r\n                    <div class=\"additional-capabilities__item-content\"> \r\n                    <p>Assemble deux composants plastiques \u00e0 l\u2019aide de vibrations ultrasonores \u00e0 haute fr\u00e9quence, cr\u00e9ant une liaison solide et homog\u00e8ne sans \u00e9l\u00e9ments de fixation suppl\u00e9mentaires.<\/p>\n                    <\/div> \r\n                <\/div> \r\n                <\/div> \r\n                            <div class=\"additional-capabilities__item accordion__item\"> \r\n                <div class=\"additional-capabilities__item-title-wrapper accordion__title\"> \r\n                    <h3 class=\"additional-capabilities__item-title title title--04\"> \r\n                    Rev\u00eatement UV                    <\/h3> \r\n                <\/div> \r\n                <div class=\"additional-capabilities__item-content-wrapper\"> \r\n                    <div class=\"additional-capabilities__item-content\"> \r\n                    <p>Ajoute une couche protectrice am\u00e9liorant la durabilit\u00e9, la r\u00e9sistance aux rayures et la stabilit\u00e9 UV, avec une finition brillante ou mate.<\/p>\n                    <\/div> \r\n                <\/div> \r\n                <\/div> \r\n                            <div class=\"additional-capabilities__item accordion__item\"> \r\n                <div class=\"additional-capabilities__item-title-wrapper accordion__title\"> \r\n                    <h3 class=\"additional-capabilities__item-title title title--04\"> \r\n                    Rivetage \u00e0 chaud                    <\/h3> \r\n                <\/div> \r\n                <div class=\"additional-capabilities__item-content-wrapper\"> \r\n                    <div class=\"additional-capabilities__item-content\"> \r\n                    <p>Utilise la chaleur et la pression pour ins\u00e9rer des \u00e9l\u00e9ments m\u00e9talliques ou former un joint dans des pi\u00e8ces en plastique, souvent utilis\u00e9e pour des assemblages durables.<\/p>\n                    <\/div> \r\n                <\/div> \r\n                <\/div> \r\n                            <div class=\"additional-capabilities__item accordion__item\"> \r\n                <div class=\"additional-capabilities__item-title-wrapper accordion__title\"> \r\n                    <h3 class=\"additional-capabilities__item-title title title--04\"> \r\n                    Marquage \u00e0 chaud                    <\/h3> \r\n                <\/div> \r\n                <div class=\"additional-capabilities__item-content-wrapper\"> \r\n                    <div class=\"additional-capabilities__item-content\"> \r\n                    <p>Applique un film m\u00e9tallique ou pigment\u00e9 sur la surface de la pi\u00e8ce pour des marquages d\u00e9coratifs, comme des logos ou du texte, avec un rendu haut de gamme.<\/p>\n                    <\/div> \r\n                <\/div> \r\n                <\/div> \r\n                            <div class=\"additional-capabilities__item accordion__item\"> \r\n                <div class=\"additional-capabilities__item-title-wrapper accordion__title\"> \r\n                    <h3 class=\"additional-capabilities__item-title title title--04\"> \r\n                    Assemblage                    <\/h3> \r\n                <\/div> \r\n                <div class=\"additional-capabilities__item-content-wrapper\"> \r\n                    <div class=\"additional-capabilities__item-content\"> \r\n                    <p>Xometry propose le montage des pi\u00e8ces moul\u00e9es par injection, y compris les services d\u2019\u00e9tiquetage et d\u2019emballage. Discutez de vos besoins sp\u00e9cifiques avec votre interlocuteur commercial pour adapter le processus \u00e0 vos exigences.<\/p>\n                    <\/div> \r\n                <\/div> \r\n                <\/div> \r\n                    <\/div>\r\n    <\/div>\r\n      <\/div>\r\n<\/section>\r\n\n\n\r\n<section class=\"comparison-table light  white\">\r\n    <div class=\"comparison-table__container section container\">\r\n        <div class=\"section__title-wrapper\">\r\n            <h2 class=\"title title--02\">  Injection plastique compar\u00e9e \u00e0 d&rsquo;autres proc\u00e9d\u00e9s<\/h2>\r\n            <div class=\"section__description\">\r\n                Comparez facilement les avantages et limites du moulage par injection par rapport \u00e0 d\u2019autres proc\u00e9d\u00e9s de fabrication.            <\/div>\r\n            \r\n            <h4 class=\"section__subtitle-bottom title title--05\">\r\n\r\n                <img decoding=\"async\" src=\"https:\/\/xometry.eu\/wp-content\/themes\/xometry\/dist\/img\/icons\/idea.svg\" alt=\"\">\r\n                Utilisez les menus d\u00e9roulants de chaque colonne pour s\u00e9lectionner et comparer les services c\u00f4te \u00e0 c\u00f4te.            <\/h4>\r\n        <\/div>\r\n                    <div class=\"comparison-table__table\">\r\n                <div class=\"converter__lottie-container\"><\/div>\r\n                <table class =\"loading\">\r\n                    <thead>\r\n                        <tr>\r\n                             \r\n                                <th data-taxonomy='Moulage par injection'>\r\n                                    <div class=\"custom-select__wrapper\">\r\n                                        <select class=\"custom-select light \">\r\n                                            <option value=\"1172\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/12\/injection-moulding-icon.svg\">\r\n                                                Moulage par injection                                            <\/option>\r\n                                            <option value=\"1518\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2023\/07\/vacuum-casting-icon.svg\">Coul\u00e9e sous vide<\/option><option value=\"1519\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2023\/07\/compression-moulding-icon.svg\">Moulage par compression<\/option><option value=\"1148\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/12\/3d-printing-fdm-icon.svg\">Impression 3D<\/option><option value=\"1520\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2022\/02\/61d70e3c11d456d4c6c1d952_die-casting-icon.svg\">Moulage sous pression<\/option><option value=\"1145\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/12\/cnc-machining-icon.svg\">Usinage CNC<\/option>                                        <\/select>\r\n                                    <\/div>\r\n                                    <div class=\"text-m short_description\">Production en s\u00e9rie de pi\u00e8ces plastiques complexes, \u00e0 haute pr\u00e9cision<\/div>                                    <a href=\"https:\/\/get.xometry.eu\/?locale=fr\" class=\"btn btn--primary\">Obtenir un devis instantan\u00e9<\/a>                                \r\n                                <\/th>\r\n                                 \r\n                                <th data-taxonomy='Coul\u00e9e sous vide'>\r\n                                    <div class=\"custom-select__wrapper\">\r\n                                        <select class=\"custom-select light \">\r\n                                            <option value=\"1518\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2023\/07\/vacuum-casting-icon.svg\">\r\n                                                Coul\u00e9e sous vide                                            <\/option>\r\n                                            <option value=\"1172\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/12\/injection-moulding-icon.svg\">Moulage par injection<\/option><option value=\"1519\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2023\/07\/compression-moulding-icon.svg\">Moulage par compression<\/option><option value=\"1148\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/12\/3d-printing-fdm-icon.svg\">Impression 3D<\/option><option value=\"1520\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2022\/02\/61d70e3c11d456d4c6c1d952_die-casting-icon.svg\">Moulage sous pression<\/option><option value=\"1145\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/12\/cnc-machining-icon.svg\">Usinage CNC<\/option>                                        <\/select>\r\n                                    <\/div>\r\n                                    <div class=\"text-m short_description\">Fabrication de petites s\u00e9ries de pi\u00e8ces d\u00e9taill\u00e9es avec une qualit\u00e9 proche de la production finale<\/div>                                    <a href=\"https:\/\/get.xometry.eu\/?locale=fr\" class=\"btn btn--primary\">Obtenir un devis instantan\u00e9<\/a>                                \r\n                                <\/th>\r\n                                 \r\n                                <th data-taxonomy='Moulage par compression'>\r\n                                    <div class=\"custom-select__wrapper\">\r\n                                        <select class=\"custom-select light \">\r\n                                            <option value=\"1519\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2023\/07\/compression-moulding-icon.svg\">\r\n                                                Moulage par compression                                            <\/option>\r\n                                            <option value=\"1172\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/12\/injection-moulding-icon.svg\">Moulage par injection<\/option><option value=\"1518\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2023\/07\/vacuum-casting-icon.svg\">Coul\u00e9e sous vide<\/option><option value=\"1148\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/12\/3d-printing-fdm-icon.svg\">Impression 3D<\/option><option value=\"1520\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2022\/02\/61d70e3c11d456d4c6c1d952_die-casting-icon.svg\">Moulage sous pression<\/option><option value=\"1145\" data-image=\"https:\/\/xometry.eu\/wp-content\/uploads\/2021\/12\/cnc-machining-icon.svg\">Usinage CNC<\/option>                                        <\/select>\r\n                                    <\/div>\r\n                                    <div class=\"text-m short_description\">S\u00e9ries allant jusqu\u2019\u00e0 5 000 pi\u00e8ces, en caoutchouc, silicone ou mat\u00e9riaux thermodurcissables<\/div>                                    <a href=\"https:\/\/get.xometry.eu\/?locale=fr\" class=\"btn btn--primary\">Obtenir un devis instantan\u00e9<\/a>                                \r\n                                <\/th>\r\n                                  \r\n                        <\/tr>\r\n                    <\/thead>\r\n                    <tbody data-fields=\"[&quot;optimal_quantity_range&quot;,&quot;technology_description&quot;,&quot;lead_time&quot;,&quot;instant_quote_availability&quot;,&quot;maximum_part_size&quot;,&quot;mould_life&quot;,&quot;material_selection&quot;,&quot;prototyping&quot;,&quot;high_volume_production&quot;,&quot;part_design_complexity&quot;,&quot;standard_surface_finish&quot;,&quot;post_processing&quot;,&quot;cost_of_design_mistakes&quot;,&quot;advantages&quot;,&quot;disadvantages&quot;]\">\r\n                        <tr class='optimal_quantity_range'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>Quantit\u00e9 optimale<\/h4><p>50 &#8211; 1,000,000<\/p><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>Quantit\u00e9 optimale<\/h4><p>1 &#8211; 100<\/p><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>Quantit\u00e9 optimale<\/h4><p>1 &#8211; 5,000<\/p><\/td><\/tr><tr class='technology_description'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>Description de la technologie<\/h4><p><p>La r\u00e9sine plastique est chauff\u00e9e, inject\u00e9e sous pression dans un moule, puis refroidie pour produire des pi\u00e8ces pr\u00e9cises et reproductibles.<\/p>\n<\/p><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>Description de la technologie<\/h4><p><p>Un moule en silicone est utilis\u00e9 pour couler la r\u00e9sine sous vide, id\u00e9al pour le prototypage ou les petites s\u00e9ries de haute qualit\u00e9.<\/p>\n<\/p><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>Description de la technologie<\/h4><p><p>Le mat\u00e9riau est plac\u00e9 dans un moule chauff\u00e9, puis comprim\u00e9 pour obtenir la forme finale, adapt\u00e9 aux \u00e9lastom\u00e8res et thermodurcissables.<\/p>\n<\/p><\/td><\/tr><tr class='lead_time'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>D\u00e9lai de fabrication<\/h4><p>30 jours<button type=\"button\" class=\"additional-info-btn\">\r\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"14\" height=\"14\" viewBox=\"0 0 14 14\" fill=\"none\">\r\n          <path d=\"M7 0C3.13428 0 0 3.13541 0 7C0 10.8668 3.13428 14 7 14C10.8657 14 14 10.8668 14 7C14 3.13541 10.8657 0 7 0ZM7 12.6452C3.88015 12.6452 1.35484 10.1209 1.35484 7C1.35484 3.88119 3.88026 1.35484 7 1.35484C10.1187 1.35484 12.6452 3.88023 12.6452 7C12.6452 10.1198 10.1209 12.6452 7 12.6452ZM7 3.10484C7.65473 3.10484 8.18548 3.6356 8.18548 4.29032C8.18548 4.94505 7.65473 5.47581 7 5.47581C6.34527 5.47581 5.81452 4.94505 5.81452 4.29032C5.81452 3.6356 6.34527 3.10484 7 3.10484ZM8.58064 10.2742C8.58064 10.4612 8.42899 10.6129 8.24193 10.6129H5.75806C5.57101 10.6129 5.41935 10.4612 5.41935 10.2742V9.59677C5.41935 9.40972 5.57101 9.25806 5.75806 9.25806H6.09677V7.45161H5.75806C5.57101 7.45161 5.41935 7.29995 5.41935 7.1129V6.43548C5.41935 6.24843 5.57101 6.09677 5.75806 6.09677H7.56452C7.75157 6.09677 7.90323 6.24843 7.90323 6.43548V9.25806H8.24193C8.42899 9.25806 8.58064 9.40972 8.58064 9.59677V10.2742Z\" fill=\"#22445F\"><\/path>\r\n        <\/svg>\r\n        <span class=\"additional-info-block tooltip-item\"><p>\u00c0 partir de 30 jours ouvr\u00e9s<\/p>\n<\/span>\r\n    <\/button><\/p><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>D\u00e9lai de fabrication<\/h4><p>20 jours<\/p><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>D\u00e9lai de fabrication<\/h4><p>20 jours<button type=\"button\" class=\"additional-info-btn\">\r\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"14\" height=\"14\" viewBox=\"0 0 14 14\" fill=\"none\">\r\n          <path d=\"M7 0C3.13428 0 0 3.13541 0 7C0 10.8668 3.13428 14 7 14C10.8657 14 14 10.8668 14 7C14 3.13541 10.8657 0 7 0ZM7 12.6452C3.88015 12.6452 1.35484 10.1209 1.35484 7C1.35484 3.88119 3.88026 1.35484 7 1.35484C10.1187 1.35484 12.6452 3.88023 12.6452 7C12.6452 10.1198 10.1209 12.6452 7 12.6452ZM7 3.10484C7.65473 3.10484 8.18548 3.6356 8.18548 4.29032C8.18548 4.94505 7.65473 5.47581 7 5.47581C6.34527 5.47581 5.81452 4.94505 5.81452 4.29032C5.81452 3.6356 6.34527 3.10484 7 3.10484ZM8.58064 10.2742C8.58064 10.4612 8.42899 10.6129 8.24193 10.6129H5.75806C5.57101 10.6129 5.41935 10.4612 5.41935 10.2742V9.59677C5.41935 9.40972 5.57101 9.25806 5.75806 9.25806H6.09677V7.45161H5.75806C5.57101 7.45161 5.41935 7.29995 5.41935 7.1129V6.43548C5.41935 6.24843 5.57101 6.09677 5.75806 6.09677H7.56452C7.75157 6.09677 7.90323 6.24843 7.90323 6.43548V9.25806H8.24193C8.42899 9.25806 8.58064 9.40972 8.58064 9.59677V10.2742Z\" fill=\"#22445F\"><\/path>\r\n        <\/svg>\r\n        <span class=\"additional-info-block tooltip-item\"><p>\u00c0 partir de 20 jours ouvr\u00e9s<\/p>\n<\/span>\r\n    <\/button><\/p><\/td><\/tr><tr class='instant_quote_availability'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>Option de chiffrage instantan\u00e9<\/h4><p>Oui<\/p><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>Option de chiffrage instantan\u00e9<\/h4><p>Oui<\/p><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>Option de chiffrage instantan\u00e9<\/h4><p>Non<\/p><\/td><\/tr><tr class='maximum_part_size'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>Taille maximale de la pi\u00e8ce<\/h4><p>1,289&#215;1,910&#215;1,006 mm<\/p><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>Taille maximale de la pi\u00e8ce<\/h4><p>2,500&#215;2,200&#215;1,800 mm<\/p><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>Taille maximale de la pi\u00e8ce<\/h4><p>500x500x mm<\/p><\/td><\/tr><tr class='mould_life'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>Dur\u00e9e de vie du moule<\/h4><p>10,000 &#8211; 1,000,000 cycles<\/p><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>Dur\u00e9e de vie du moule<\/h4><p>1 &#8211; 20 cycles<\/p><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>Dur\u00e9e de vie du moule<\/h4><p>10,000 &#8211; 1,000,000 cycles<\/p><\/td><\/tr><tr class='material_selection'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>S\u00e9lection de mat\u00e9riaux<\/h4><p>Tous thermoplastiques et thermodurcissables, options personnalis\u00e9es<\/p><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>S\u00e9lection de mat\u00e9riaux<\/h4><p>Plastiques rigides (de type ABS, PMMA, PP ou PC), plastiques de type caoutchouc.<\/p><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>S\u00e9lection de mat\u00e9riaux<\/h4><p>Mat\u00e9riaux en caoutchouc ou en silicone<\/p><\/td><\/tr><tr class='prototyping'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>Prototypage<\/h4><p><div class=\"comparison-table__stars\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#E6F0FD\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#E6F0FD\"\/>\r\n                    <\/svg><\/div><\/p><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>Prototypage<\/h4><p><div class=\"comparison-table__stars\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#E6F0FD\"\/>\r\n                    <\/svg><\/div><\/p><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>Prototypage<\/h4><p><div class=\"comparison-table__stars\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#E6F0FD\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#E6F0FD\"\/>\r\n                    <\/svg><\/div><\/p><\/td><\/tr><tr class='high_volume_production'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>Production en s\u00e9rie<\/h4><p><div class=\"comparison-table__stars\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><\/div><\/p><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>Production en s\u00e9rie<\/h4><p><div class=\"comparison-table__stars\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#E6F0FD\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#E6F0FD\"\/>\r\n                    <\/svg><\/div><\/p><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>Production en s\u00e9rie<\/h4><p><div class=\"comparison-table__stars\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#E6F0FD\"\/>\r\n                    <\/svg><\/div><\/p><\/td><\/tr><tr class='part_design_complexity'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>Complexit\u00e9 du design de la pi\u00e8ce<\/h4><p><div class=\"comparison-table__stars\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><\/div><\/p><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>Complexit\u00e9 du design de la pi\u00e8ce<\/h4><p><div class=\"comparison-table__stars\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#E6F0FD\"\/>\r\n                    <\/svg><\/div><\/p><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>Complexit\u00e9 du design de la pi\u00e8ce<\/h4><p><div class=\"comparison-table__stars\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#E6F0FD\"\/>\r\n                    <\/svg><\/div><\/p><\/td><\/tr><tr class='standard_surface_finish'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>Finition de surface standard<\/h4><p><div class=\"comparison-table__stars\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><\/div><\/p><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>Finition de surface standard<\/h4><p><div class=\"comparison-table__stars\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><\/div><\/p><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>Finition de surface standard<\/h4><p><div class=\"comparison-table__stars\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#0e6aed\"\/>\r\n                    <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.9088 1.58103C12.8288 1.40757 12.7007 1.26066 12.5398 1.15769C12.3789 1.05472 12.1918 1 12.0008 1C11.8098 1 11.6227 1.05472 11.4618 1.15769C11.3009 1.26066 11.1728 1.40757 11.0928 1.58103L8.2228 7.80103L1.4218 8.60803C1.23205 8.63043 1.05269 8.70673 0.904952 8.82789C0.757211 8.94905 0.647271 9.10999 0.588146 9.29168C0.52902 9.47337 0.523184 9.6682 0.571328 9.8531C0.619471 10.038 0.719579 10.2052 0.859804 10.335L5.8898 14.985L4.5548 21.705C4.51772 21.8924 4.53506 22.0864 4.60475 22.2642C4.67444 22.442 4.79359 22.5961 4.94809 22.7083C5.10259 22.8205 5.286 22.8862 5.47663 22.8975C5.66725 22.9087 5.85713 22.8652 6.0238 22.772L12.0008 19.426L17.9778 22.772C18.1446 22.8656 18.3347 22.9094 18.5256 22.8983C18.7165 22.8871 18.9002 22.8214 19.055 22.709C19.2097 22.5966 19.3289 22.4422 19.3986 22.264C19.4682 22.0859 19.4853 21.8916 19.4478 21.704L18.1128 14.986L23.1418 10.335C23.282 10.2052 23.3821 10.038 23.4303 9.8531C23.4784 9.6682 23.4726 9.47337 23.4135 9.29168C23.3543 9.10999 23.2444 8.94905 23.0967 8.82789C22.9489 8.70673 22.7696 8.63043 22.5798 8.60803L15.7778 7.80003L12.9088 1.58103Z\" fill=\"#E6F0FD\"\/>\r\n                    <\/svg><\/div><\/p><\/td><\/tr><tr class='post_processing'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>Post-traitement<\/h4><p>Non<\/p><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>Post-traitement<\/h4><p>Non<\/p><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>Post-traitement<\/h4><p>Non<\/p><\/td><\/tr><tr class='cost_of_design_mistakes'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>Co\u00fbt des erreurs de conception<\/h4><p>\u00c9lev\u00e9<\/p><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>Co\u00fbt des erreurs de conception<\/h4><p>Faible<\/p><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>Co\u00fbt des erreurs de conception<\/h4><p>Faible<\/p><\/td><\/tr><tr class='advantages'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>Avantages<\/h4><ul><li>Grande r\u00e9p\u00e9tabilit\u00e9 pour une qualit\u00e9 de pi\u00e8ce constante<\/li><li>Id\u00e9al pour les volumes de production importants<\/li><li>Large gamme d&rsquo;options de mat\u00e9riaux pour convenir \u00e0 une grande vari\u00e9t\u00e9 d&rsquo;applications<\/li><li>Capacit\u00e9 \u00e0 r\u00e9pondre \u00e0 des exigences de couleur personnalis\u00e9es, garantissant des tons pr\u00e9cis<\/li><\/ul><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>Avantages<\/h4><ul><li>Id\u00e9ale pour les petites s\u00e9ries et les prototypes d\u00e9taill\u00e9s avec des d\u00e9lais courts<\/li><li>Finition esth\u00e9tique de haute qualit\u00e9, parfaite pour les d\u00e9monstrations ou \u00e9chantillons visuels (ex. : lentilles, composants robotiques)<\/li><\/ul><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>Avantages<\/h4><ul><li>Solution \u00e9conomique pour des s\u00e9ries jusqu\u2019\u00e0 5 000 pi\u00e8ces<\/li><li>Particuli\u00e8rement adapt\u00e9 aux mat\u00e9riaux comme le caoutchouc (NBR, FFKM) ou les thermodurcissables<\/li><\/ul><\/td><\/tr><tr class='disadvantages'><td class='tooltip-parent' data-taxonomy='Moulage par injection'><h4 class='text-s'>Inconv\u00e9nients<\/h4><ul><li>Investissement initial \u00e9lev\u00e9 dans l&rsquo;outillage de moule<\/li><li>Co\u00fbts \u00e9lev\u00e9s pour les modifications ou am\u00e9liorations de moule, en particulier si le design n&rsquo;est pas fig\u00e9 avant la production du moule<\/li><li>Flexibilit\u00e9 limit\u00e9e pour les designs tr\u00e8s complexes ou tr\u00e8s d\u00e9taill\u00e9s<\/li><\/ul><\/td><td class='tooltip-parent' data-taxonomy='Coul\u00e9e sous vide'><h4 class='text-s'>Inconv\u00e9nients<\/h4><ul><li>Dur\u00e9e de vie limit\u00e9e des moules (environ 20 pi\u00e8ces)<\/li><\/ul><\/td><td class='tooltip-parent' data-taxonomy='Moulage par compression'><h4 class='text-s'>Inconv\u00e9nients<\/h4><ul><li>Options de mat\u00e9riaux limit\u00e9es<\/li><li>Complexit\u00e9 de design limit\u00e9<\/li><\/ul><\/td><\/tr>                        <tr class=\"row-with-link\">\r\n                            <td data-taxonomy='Moulage par injection'>                                    <a href=\"https:\/\/xometry.eu\/fr\/moulage-par-injection\/\" class=\"text-btn\">\r\n                                    Explorer davantage Moulage par injection                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\"\r\n                                            fill=\"none\">\r\n                                            <path\r\n                                                d=\"M1.66794 10.8333L16.3228 10.8333L13.5787 13.5774C13.2533 13.9028 13.2533 14.4305 13.5787 14.7559C13.9041 15.0814 14.4318 15.0814 14.7572 14.7559L18.9239 10.5893C19.2493 10.2639 19.2493 9.7362 18.9239 9.41075L14.7572 5.24409C14.5945 5.08137 14.3812 4.99998 14.1679 4.99998C13.9547 4.99998 13.7414 5.08137 13.5787 5.24409C13.2533 5.56948 13.2533 6.09714 13.5787 6.42259L16.3228 9.16664L1.66794 9.16664C1.20772 9.16664 0.834609 9.53975 0.834609 9.99997C0.834608 10.4602 1.20772 10.8333 1.66794 10.8333Z\"\r\n                                                fill=\"#1A5ADE\" \/>\r\n                                        <\/svg>\r\n                                    <\/a>\r\n                                <\/td><td data-taxonomy='Coul\u00e9e sous vide'>                                    <a href=\"https:\/\/xometry.eu\/fr\/coulee-sous-vide\/\" class=\"text-btn\">\r\n                                    Explorer davantage Coul\u00e9e sous vide                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\"\r\n                                            fill=\"none\">\r\n                                            <path\r\n                                                d=\"M1.66794 10.8333L16.3228 10.8333L13.5787 13.5774C13.2533 13.9028 13.2533 14.4305 13.5787 14.7559C13.9041 15.0814 14.4318 15.0814 14.7572 14.7559L18.9239 10.5893C19.2493 10.2639 19.2493 9.7362 18.9239 9.41075L14.7572 5.24409C14.5945 5.08137 14.3812 4.99998 14.1679 4.99998C13.9547 4.99998 13.7414 5.08137 13.5787 5.24409C13.2533 5.56948 13.2533 6.09714 13.5787 6.42259L16.3228 9.16664L1.66794 9.16664C1.20772 9.16664 0.834609 9.53975 0.834609 9.99997C0.834608 10.4602 1.20772 10.8333 1.66794 10.8333Z\"\r\n                                                fill=\"#1A5ADE\" \/>\r\n                                        <\/svg>\r\n                                    <\/a>\r\n                                <\/td><td data-taxonomy='Moulage par compression'>                                    <a href=\"https:\/\/xometry.eu\/fr\/moulage-par-compression\/\" class=\"text-btn\">\r\n                                    Explorer davantage Moulage par compression                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\"\r\n                                            fill=\"none\">\r\n                                            <path\r\n                                                d=\"M1.66794 10.8333L16.3228 10.8333L13.5787 13.5774C13.2533 13.9028 13.2533 14.4305 13.5787 14.7559C13.9041 15.0814 14.4318 15.0814 14.7572 14.7559L18.9239 10.5893C19.2493 10.2639 19.2493 9.7362 18.9239 9.41075L14.7572 5.24409C14.5945 5.08137 14.3812 4.99998 14.1679 4.99998C13.9547 4.99998 13.7414 5.08137 13.5787 5.24409C13.2533 5.56948 13.2533 6.09714 13.5787 6.42259L16.3228 9.16664L1.66794 9.16664C1.20772 9.16664 0.834609 9.53975 0.834609 9.99997C0.834608 10.4602 1.20772 10.8333 1.66794 10.8333Z\"\r\n                                                fill=\"#1A5ADE\" \/>\r\n                                        <\/svg>\r\n                                    <\/a>\r\n                                <\/td>                        <\/tr>\r\n                    <\/tbody>\r\n                <\/table>\r\n            <\/div>\r\n            <\/div>\r\n<\/section>\n\n\r\n<section class=\"faq light white\"  >\r\n    <div class=\"faq__container section container\">\r\n        <div class=\"faq__wrapper\">\r\n            <h2 class=\"title title--02\">Foire aux questions<\/h2>\r\n            <div class=\"faq__list\">\r\n                                                                                                    <div class=\"faq__item  \">\r\n                            <div class=\"faq__item-question title title--04\">\r\n                                Quels sont les co\u00fbts et les d\u00e9lais de fabrication typiques pour le moulage par injection ?                                <svg\r\n                                    xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\r\n                                    width=\"28\"\r\n                                    height=\"28\"\r\n                                    viewBox=\"0 0 28 28\"\r\n                                    fill=\"none\"\r\n                                    class=\"toggle-icon\"\r\n                                >\r\n                                    <g class=\"plus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H14.875V8.96875C14.875 8.84844 14.7766 8.75 14.6563 8.75H13.3438C13.2234 8.75 13.125 8.84844 13.125 8.96875V13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H13.125V19.0313C13.125 19.1516 13.2234 19.25 13.3438 19.25H14.6563C14.7766 19.25 14.875 19.1516 14.875 19.0313V14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                    <g class=\"minus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                <\/svg>\r\n                            <\/div>\r\n                            <div class=\"faq__item-answer-wrapper\">\r\n                                <div class=\"faq__item-answer\">\r\n                                    <p>Les co\u00fbts varient en fonction de la complexit\u00e9 de l\u2019outillage, des mat\u00e9riaux choisis et du volume de production. Le d\u00e9lai de fabrication du moule est g\u00e9n\u00e9ralement de 20 \u00e0 30 jours ouvrables, et la production de pi\u00e8ces peut commencer sous 8 jours selon la taille du lot et les exigences de livraison.<\/p>\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                                                    <div class=\"faq__item  \">\r\n                            <div class=\"faq__item-question title title--04\">\r\n                                Puis-je commander des prototypes avant de lancer la production ?                                <svg\r\n                                    xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\r\n                                    width=\"28\"\r\n                                    height=\"28\"\r\n                                    viewBox=\"0 0 28 28\"\r\n                                    fill=\"none\"\r\n                                    class=\"toggle-icon\"\r\n                                >\r\n                                    <g class=\"plus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H14.875V8.96875C14.875 8.84844 14.7766 8.75 14.6563 8.75H13.3438C13.2234 8.75 13.125 8.84844 13.125 8.96875V13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H13.125V19.0313C13.125 19.1516 13.2234 19.25 13.3438 19.25H14.6563C14.7766 19.25 14.875 19.1516 14.875 19.0313V14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                    <g class=\"minus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                <\/svg>\r\n                            <\/div>\r\n                            <div class=\"faq__item-answer-wrapper\">\r\n                                <div class=\"faq__item-answer\">\r\n                                    <p>Oui, Xometry propose la fabrication d\u2019\u00e9chantillons (T1) avant la mise en production compl\u00e8te. Des it\u00e9rations suppl\u00e9mentaires (T2, T3, etc.) peuvent \u00eatre r\u00e9alis\u00e9es selon vos retours.<\/p>\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                                                    <div class=\"faq__item  \">\r\n                            <div class=\"faq__item-question title title--04\">\r\n                                Proposez-vous une assistance pour la conception ou le choix des mat\u00e9riaux ?                                <svg\r\n                                    xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\r\n                                    width=\"28\"\r\n                                    height=\"28\"\r\n                                    viewBox=\"0 0 28 28\"\r\n                                    fill=\"none\"\r\n                                    class=\"toggle-icon\"\r\n                                >\r\n                                    <g class=\"plus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H14.875V8.96875C14.875 8.84844 14.7766 8.75 14.6563 8.75H13.3438C13.2234 8.75 13.125 8.84844 13.125 8.96875V13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H13.125V19.0313C13.125 19.1516 13.2234 19.25 13.3438 19.25H14.6563C14.7766 19.25 14.875 19.1516 14.875 19.0313V14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                    <g class=\"minus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                <\/svg>\r\n                            <\/div>\r\n                            <div class=\"faq__item-answer-wrapper\">\r\n                                <div class=\"faq__item-answer\">\r\n                                    <p>Oui. Nos ing\u00e9nieurs vous accompagnent dans l\u2019optimisation de vos designs gr\u00e2ce \u00e0 une analyse DFM, et vous aident \u00e0 s\u00e9lectionner les mat\u00e9riaux les plus adapt\u00e9s \u00e0 votre application.<\/p>\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                                                    <div class=\"faq__item  \">\r\n                            <div class=\"faq__item-question title title--04\">\r\n                                Pouvez-vous produire des pi\u00e8ces avec des tol\u00e9rances serr\u00e9es ?                                <svg\r\n                                    xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\r\n                                    width=\"28\"\r\n                                    height=\"28\"\r\n                                    viewBox=\"0 0 28 28\"\r\n                                    fill=\"none\"\r\n                                    class=\"toggle-icon\"\r\n                                >\r\n                                    <g class=\"plus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H14.875V8.96875C14.875 8.84844 14.7766 8.75 14.6563 8.75H13.3438C13.2234 8.75 13.125 8.84844 13.125 8.96875V13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H13.125V19.0313C13.125 19.1516 13.2234 19.25 13.3438 19.25H14.6563C14.7766 19.25 14.875 19.1516 14.875 19.0313V14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                    <g class=\"minus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                <\/svg>\r\n                            <\/div>\r\n                            <div class=\"faq__item-answer-wrapper\">\r\n                                <div class=\"faq__item-answer\">\r\n                                    <p>Nous suivons par d\u00e9faut les tol\u00e9rances DIN 16742, mais nous pouvons atteindre des tol\u00e9rances plus strictes selon vos dessins techniques et les sp\u00e9cificit\u00e9s du projet.<\/p>\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                                                    <div class=\"faq__item  \">\r\n                            <div class=\"faq__item-question title title--04\">\r\n                                Quelles certifications proposez-vous ?                                <svg\r\n                                    xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\r\n                                    width=\"28\"\r\n                                    height=\"28\"\r\n                                    viewBox=\"0 0 28 28\"\r\n                                    fill=\"none\"\r\n                                    class=\"toggle-icon\"\r\n                                >\r\n                                    <g class=\"plus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H14.875V8.96875C14.875 8.84844 14.7766 8.75 14.6563 8.75H13.3438C13.2234 8.75 13.125 8.84844 13.125 8.96875V13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H13.125V19.0313C13.125 19.1516 13.2234 19.25 13.3438 19.25H14.6563C14.7766 19.25 14.875 19.1516 14.875 19.0313V14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                    <g class=\"minus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                <\/svg>\r\n                            <\/div>\r\n                            <div class=\"faq__item-answer-wrapper\">\r\n                                <div class=\"faq__item-answer\">\r\n                                    <p>Nous proposons les certifications suivantes : ISO 9001, AS9100, ISO 13485, et moulage en salle blanche ISO 7\/8 pour les applications m\u00e9dicales.<\/p>\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                                                    <div class=\"faq__item  \">\r\n                            <div class=\"faq__item-question title title--04\">\r\n                                Quels types de mat\u00e9riaux sont disponibles ?                                <svg\r\n                                    xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\r\n                                    width=\"28\"\r\n                                    height=\"28\"\r\n                                    viewBox=\"0 0 28 28\"\r\n                                    fill=\"none\"\r\n                                    class=\"toggle-icon\"\r\n                                >\r\n                                    <g class=\"plus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H14.875V8.96875C14.875 8.84844 14.7766 8.75 14.6563 8.75H13.3438C13.2234 8.75 13.125 8.84844 13.125 8.96875V13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H13.125V19.0313C13.125 19.1516 13.2234 19.25 13.3438 19.25H14.6563C14.7766 19.25 14.875 19.1516 14.875 19.0313V14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                    <g class=\"minus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                <\/svg>\r\n                            <\/div>\r\n                            <div class=\"faq__item-answer-wrapper\">\r\n                                <div class=\"faq__item-answer\">\r\n                                    <p>Nous offrons un large choix de plastiques standards et techniques, ainsi que des mat\u00e9riaux personnalis\u00e9s. Gr\u00e2ce \u00e0 notre r\u00e9seau de partenaires, nous pouvons sourcer tout mat\u00e9riau requis.<\/p>\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                                                    <div class=\"faq__item  \">\r\n                            <div class=\"faq__item-question title title--04\">\r\n                                Pouvez-vous appliquer diff\u00e9rentes couleurs du m\u00eame mat\u00e9riau ?                                <svg\r\n                                    xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\r\n                                    width=\"28\"\r\n                                    height=\"28\"\r\n                                    viewBox=\"0 0 28 28\"\r\n                                    fill=\"none\"\r\n                                    class=\"toggle-icon\"\r\n                                >\r\n                                    <g class=\"plus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H14.875V8.96875C14.875 8.84844 14.7766 8.75 14.6563 8.75H13.3438C13.2234 8.75 13.125 8.84844 13.125 8.96875V13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H13.125V19.0313C13.125 19.1516 13.2234 19.25 13.3438 19.25H14.6563C14.7766 19.25 14.875 19.1516 14.875 19.0313V14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                    <g class=\"minus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                <\/svg>\r\n                            <\/div>\r\n                            <div class=\"faq__item-answer-wrapper\">\r\n                                <div class=\"faq__item-answer\">\r\n                                    <p>Oui, nous pouvons mouler plusieurs couleurs d\u2019un m\u00eame mat\u00e9riau, m\u00eame dans une seule commande. Veuillez noter que cela peut entra\u00eener des co\u00fbts suppl\u00e9mentaires li\u00e9s aux purges.<\/p>\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                                                    <div class=\"faq__item  \">\r\n                            <div class=\"faq__item-question title title--04\">\r\n                                \u00c0 qui appartient le moule ?                                <svg\r\n                                    xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\r\n                                    width=\"28\"\r\n                                    height=\"28\"\r\n                                    viewBox=\"0 0 28 28\"\r\n                                    fill=\"none\"\r\n                                    class=\"toggle-icon\"\r\n                                >\r\n                                    <g class=\"plus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H14.875V8.96875C14.875 8.84844 14.7766 8.75 14.6563 8.75H13.3438C13.2234 8.75 13.125 8.84844 13.125 8.96875V13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H13.125V19.0313C13.125 19.1516 13.2234 19.25 13.3438 19.25H14.6563C14.7766 19.25 14.875 19.1516 14.875 19.0313V14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                    <g class=\"minus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                <\/svg>\r\n                            <\/div>\r\n                            <div class=\"faq__item-answer-wrapper\">\r\n                                <div class=\"faq__item-answer\">\r\n                                    <p>Le moule vous appartient. Il est conserv\u00e9 en toute s\u00e9curit\u00e9 dans nos installations et peut \u00eatre exp\u00e9di\u00e9 sur demande (des frais de transport et d\u2019emballage peuvent s\u2019appliquer). Merci de pr\u00e9ciser si vous commandez un moule exportable ou non.<\/p>\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                                                    <div class=\"faq__item  \">\r\n                            <div class=\"faq__item-question title title--04\">\r\n                                Combien de temps le moule est-il conserv\u00e9 ?                                <svg\r\n                                    xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\r\n                                    width=\"28\"\r\n                                    height=\"28\"\r\n                                    viewBox=\"0 0 28 28\"\r\n                                    fill=\"none\"\r\n                                    class=\"toggle-icon\"\r\n                                >\r\n                                    <g class=\"plus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H14.875V8.96875C14.875 8.84844 14.7766 8.75 14.6563 8.75H13.3438C13.2234 8.75 13.125 8.84844 13.125 8.96875V13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H13.125V19.0313C13.125 19.1516 13.2234 19.25 13.3438 19.25H14.6563C14.7766 19.25 14.875 19.1516 14.875 19.0313V14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                    <g class=\"minus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                <\/svg>\r\n                            <\/div>\r\n                            <div class=\"faq__item-answer-wrapper\">\r\n                                <div class=\"faq__item-answer\">\r\n                                    <p>Nous stockons votre moule pendant au moins deux ans dans nos installations partenaires, avec possibilit\u00e9 de prolongation sur demande.<\/p>\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                                                    <div class=\"faq__item  \">\r\n                            <div class=\"faq__item-question title title--04\">\r\n                                Quel est le d\u00e9lai pour un r\u00e9assort ?                                <svg\r\n                                    xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\r\n                                    width=\"28\"\r\n                                    height=\"28\"\r\n                                    viewBox=\"0 0 28 28\"\r\n                                    fill=\"none\"\r\n                                    class=\"toggle-icon\"\r\n                                >\r\n                                    <g class=\"plus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H14.875V8.96875C14.875 8.84844 14.7766 8.75 14.6563 8.75H13.3438C13.2234 8.75 13.125 8.84844 13.125 8.96875V13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H13.125V19.0313C13.125 19.1516 13.2234 19.25 13.3438 19.25H14.6563C14.7766 19.25 14.875 19.1516 14.875 19.0313V14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                    <g class=\"minus\">\r\n                                    <path\r\n                                        d=\"M19.0313 13.125H8.96875C8.84844 13.125 8.75 13.2234 8.75 13.3438V14.6563C8.75 14.7766 8.84844 14.875 8.96875 14.875H19.0313C19.1516 14.875 19.25 14.7766 19.25 14.6563V13.3438C19.25 13.2234 19.1516 13.125 19.0313 13.125Z\"\r\n                                    \/>\r\n                                    <path\r\n                                        d=\"M14 1.75C7.23516 1.75 1.75 7.23516 1.75 14C1.75 20.7648 7.23516 26.25 14 26.25C20.7648 26.25 26.25 20.7648 26.25 14C26.25 7.23516 20.7648 1.75 14 1.75ZM14 24.1719C8.38359 24.1719 3.82813 19.6164 3.82813 14C3.82813 8.38359 8.38359 3.82813 14 3.82813C19.6164 3.82813 24.1719 8.38359 24.1719 14C24.1719 19.6164 19.6164 24.1719 14 24.1719Z\"\r\n                                    \/>\r\n                                    <\/g>\r\n                                <\/svg>\r\n                            <\/div>\r\n                            <div class=\"faq__item-answer-wrapper\">\r\n                                <div class=\"faq__item-answer\">\r\n                                    <p>Nous r\u00e9pondons \u00e0 vos demandes de r\u00e9assort sous 48 h. Les d\u00e9lais de fabrication varient selon la taille du lot et les plannings de production.<\/p>\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                                <\/div>\r\n        <\/div>\r\n            <\/div>\r\n<\/section>\n\n<section class=\"slider__block three-slides  light light-to-dark-gradient\">\r\n    <div class=\"slider__section section container\">\r\n        <div class=\"slider__title-wrapper\">\r\n            <h2 class=\"title title--02\">Autres avis de clients<\/h2>\r\n            <div class=\"slider__btns\">\r\n                <button type=\"button\" class=\"slider__btn-prev\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"26\" height=\"26\" viewBox=\"0 0 26 26\" fill=\"none\">\r\n                    <path\r\n                        d=\"M17.4935 4.19138L7.82476 12.5297C7.548 12.7683 7.548 13.2279 7.82476 13.4691L17.4935 21.8074C17.8541 22.1172 18.3822 21.8379 18.3822 21.3377V4.66111C18.3822 4.16091 17.8541 3.88161 17.4935 4.19138Z\"\r\n                        fill=\"white\"\r\n                    \/>\r\n                    <\/svg>\r\n                <\/button>\r\n                <button type=\"button\" class=\"slider__btn-next\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"26\" height=\"26\" viewBox=\"0 0 26 26\" fill=\"none\">\r\n                    <path\r\n                        d=\"M18.1746 12.5297L8.50586 4.19138C8.14531 3.88161 7.61719 4.16091 7.61719 4.66111V21.3377C7.61719 21.8379 8.14531 22.1172 8.50586 21.8074L18.1746 13.4691C18.4514 13.2304 18.4514 12.7683 18.1746 12.5297Z\"\r\n                        fill=\"white\"\r\n                    \/>\r\n                    <\/svg>\r\n                <\/button>\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"slider__container\">\r\n            <div class=\"swiper-wrapper\">\r\n                                        <div class=\"reviews__item swiper-slide card\">\r\n                            <div class=\"reviews__item-text\">\r\n                                <p>\u00ab Nous n&rsquo;avions vraiment aucune id\u00e9e de ce qui \u00e9tait rentable pour nous en mati\u00e8re de moulage par injection, car l&rsquo;expertise de notre \u00e9quipe est enti\u00e8rement dans les domaines de l&rsquo;\u00e9lectricit\u00e9 et de l&rsquo;\u00e9lectronique. C&rsquo;est \u00e0 ce moment-l\u00e0 que Xometry Turquie est intervenu et a rapidement commenc\u00e9 la livraison. \u00bb<\/p>\n                            <\/div>\r\n                            <div class=\"reviews__item-footer\">\r\n                                <img decoding=\"async\" class=\"reviews__item-logo\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/03\/byqee-logo.png\" alt=\"Eda I\u015f\u0131k, Byqee\" \/>\r\n                                <h3 class=\"reviews__item-title title title--04\"> Eda I\u015f\u0131k, Byqee<\/h3>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"reviews__item swiper-slide card\">\r\n                            <div class=\"reviews__item-text\">\r\n                                <p>\u00ab Xometry est plus qu&rsquo;un simple fournisseur ; c&rsquo;est un v\u00e9ritable partenaire de solution. Leurs services de moulage par injection nous ont aid\u00e9s \u00e0 produire efficacement des composants durables pour notre borne de recharge de v\u00e9hicules \u00e9lectriques, garantissant \u00e0 la fois la qualit\u00e9 et la fiabilit\u00e9. \u00bb<\/p>\n                            <\/div>\r\n                            <div class=\"reviews__item-footer\">\r\n                                <img decoding=\"async\" class=\"reviews__item-logo\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2025\/01\/orge-logo.png\" alt=\"Ahmet Birle\u015ftirici, Orge\" \/>\r\n                                <h3 class=\"reviews__item-title title title--04\"> Ahmet Birle\u015ftirici, Orge<\/h3>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"reviews__item swiper-slide card\">\r\n                            <div class=\"reviews__item-text\">\r\n                                <p>\u00ab La collaboration avec les services de moulage par injection de Xometry nous a permis de r\u00e9inventer des produits m\u00e9dicaux tels que notre st\u00e9thoscope Tulip et notre lampe de diagnostic L\u00fbx, assurant \u00e0 la fois un design innovant et une fabrication de haute qualit\u00e9. \u00bb<\/p>\n                            <\/div>\r\n                            <div class=\"reviews__item-footer\">\r\n                                <img decoding=\"async\" class=\"reviews__item-logo\" src=\"https:\/\/xometry.eu\/wp-content\/uploads\/2024\/09\/doccheck-logo.png\" alt=\"David Marshall, DocCheck\" \/>\r\n                                <h3 class=\"reviews__item-title title title--04\"> David Marshall, DocCheck<\/h3>\r\n                            <\/div>\r\n                        <\/div>\r\n                                <\/div>\r\n            <div class=\"slider__pagination\"><\/div>\r\n        <\/div>\r\n            <\/div>\r\n<\/section>\n\n\r\n<section class=\"final-cta dark dark-blue-100\" >\r\n    <div class=\"final-cta__container section container\">\r\n        <h2 class=\"title title--02\">Commencez votre devis de moulage instantan\u00e9 d\u00e8s maintenant avec Xometry<\/h2>\r\n        <div class=\"hero__cards-list\">\r\n              \r\n    <a href=\"https:\/\/get.xometry.eu\/?locale=fr\" class=\"hero__cards-item card \">\r\n        <h3 class=\"title title--03\">Besoin d&rsquo;un petit lot de production ?<\/h3>\r\n        <div class=\"hero__cards-item-text \"><p>Essayez notre moteur de devis instantan\u00e9, propuls\u00e9 par l\u2019IA : t\u00e9l\u00e9chargez votre design et obtenez un devis en ligne en quelques clics.<\/p>\n<\/div>\r\n        <span class=\"btn btn--primary \">Obtenir un devis instantan\u00e9<\/span>\r\n            <\/a>\r\n  \r\n    <a href=\"https:\/\/get.xometry.eu\/high-volume-manufacturing\/?locale=fr\" class=\"hero__cards-item card \">\r\n        <h3 class=\"title title--03\">Besoin de lots de production de volume moyen ou \u00e9lev\u00e9 ou d&rsquo;un projet de production complexe ?<\/h3>\r\n        <div class=\"hero__cards-item-text \"><p>D\u00e9crivez les sp\u00e9cificit\u00e9s de votre projet directement sur notre plateforme.<\/p>\n<\/div>\r\n        <span class=\"btn btn--primary \">Cr\u00e9er un compte<\/span>\r\n            <\/a>\r\n        <\/div>\r\n        <div class=\"final-cta__footer-list\">\r\n                            <div class=\"final-cta__footer-item\">\r\n                    <h4 class=\"text-l\">Clients<\/h4>\r\n                    <div class=\"title title--02 text--semi-bold\">85 000<\/div>\r\n                <\/div>\r\n                                        <div class=\"final-cta__footer-item\">\r\n                    <h4 class=\"text-l\">Pi\u00e8ces exp\u00e9di\u00e9es<\/h4>\r\n                    <div class=\"title title--02 text--semi-bold\">165 millions<\/div>\r\n                <\/div>\r\n                                        <div class=\"final-cta__footer-item trustpilot\">\r\n                   <div class=\"trustpilot-widget stat-item\" data-locale=\"fr\" data-template-id=\"53aa8807dec7e10d38f59f32\" data-businessunit-id=\"60b8c942cc8732000134c923\" data-style-height=\"100%\" data-style-width=\"145px\" data-theme=\"dark\"><a href=\"https:\/\/www.trustpilot.com\/review\/xometry.eu\" target=\"_blank\" rel=\"noopener\">Trustpilot<\/a><\/div>                <\/div>\r\n                    <\/div>\r\n    <\/div>\r\n<\/section>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":183521,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-new-style.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-155638","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.5 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Services d&#039;injection plastique sur mesure | Xometry Europe<\/title>\n<meta name=\"description\" content=\"Services de moulage par injection sur mesure, avec une \u00e9valuation technique experte et un accompagnement en conception d\u00e9taill\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xometry.eu\/fr\/moulage-par-injection\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Services d&#039;injection plastique sur mesure | Xometry Europe\" \/>\n<meta property=\"og:description\" content=\"Services de moulage par injection sur mesure, avec une \u00e9valuation technique experte et un accompagnement en conception d\u00e9taill\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xometry.eu\/fr\/moulage-par-injection\/\" \/>\n<meta property=\"og:site_name\" content=\"Xometry Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-27T18:03:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xometry.eu\/wp-content\/uploads\/2023\/02\/FR-Injection-Moulding-service-page.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1229\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Injection plastique\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xometry.eu\\\/fr\\\/moulage-par-injection\\\/\",\"url\":\"https:\\\/\\\/xometry.eu\\\/fr\\\/moulage-par-injection\\\/\",\"name\":\"Services d'injection plastique sur mesure | Xometry Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xometry.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xometry.eu\\\/fr\\\/moulage-par-injection\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xometry.eu\\\/fr\\\/moulage-par-injection\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xometry.eu\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/FR-Injection-moulding.jpg\",\"datePublished\":\"2025-03-06T14:24:19+00:00\",\"dateModified\":\"2026-07-27T18:03:52+00:00\",\"description\":\"Services de moulage par injection sur mesure, avec une \u00e9valuation technique experte et un accompagnement en conception d\u00e9taill\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xometry.eu\\\/fr\\\/moulage-par-injection\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xometry.eu\\\/fr\\\/moulage-par-injection\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/xometry.eu\\\/fr\\\/moulage-par-injection\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xometry.eu\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/FR-Injection-moulding.jpg\",\"contentUrl\":\"https:\\\/\\\/xometry.eu\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/FR-Injection-moulding.jpg\",\"width\":2400,\"height\":1260},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xometry.eu\\\/fr\\\/moulage-par-injection\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/xometry.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Injection plastique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xometry.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/xometry.eu\\\/fr\\\/\",\"name\":\"Xometry Europe\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/xometry.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xometry.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Services d'injection plastique sur mesure | Xometry Europe","description":"Services de moulage par injection sur mesure, avec une \u00e9valuation technique experte et un accompagnement en conception d\u00e9taill\u00e9.","robots":{"index":"index","follow":"nofollow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xometry.eu\/fr\/moulage-par-injection\/","og_locale":"fr_FR","og_type":"article","og_title":"Services d'injection plastique sur mesure | Xometry Europe","og_description":"Services de moulage par injection sur mesure, avec une \u00e9valuation technique experte et un accompagnement en conception d\u00e9taill\u00e9.","og_url":"https:\/\/xometry.eu\/fr\/moulage-par-injection\/","og_site_name":"Xometry Europe","article_modified_time":"2026-07-27T18:03:52+00:00","og_image":[{"width":2400,"height":1229,"url":"https:\/\/xometry.eu\/wp-content\/uploads\/2023\/02\/FR-Injection-Moulding-service-page.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Injection plastique","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xometry.eu\/fr\/moulage-par-injection\/","url":"https:\/\/xometry.eu\/fr\/moulage-par-injection\/","name":"Services d'injection plastique sur mesure | Xometry Europe","isPartOf":{"@id":"https:\/\/xometry.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xometry.eu\/fr\/moulage-par-injection\/#primaryimage"},"image":{"@id":"https:\/\/xometry.eu\/fr\/moulage-par-injection\/#primaryimage"},"thumbnailUrl":"https:\/\/xometry.eu\/wp-content\/uploads\/2026\/07\/FR-Injection-moulding.jpg","datePublished":"2025-03-06T14:24:19+00:00","dateModified":"2026-07-27T18:03:52+00:00","description":"Services de moulage par injection sur mesure, avec une \u00e9valuation technique experte et un accompagnement en conception d\u00e9taill\u00e9.","breadcrumb":{"@id":"https:\/\/xometry.eu\/fr\/moulage-par-injection\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xometry.eu\/fr\/moulage-par-injection\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/xometry.eu\/fr\/moulage-par-injection\/#primaryimage","url":"https:\/\/xometry.eu\/wp-content\/uploads\/2026\/07\/FR-Injection-moulding.jpg","contentUrl":"https:\/\/xometry.eu\/wp-content\/uploads\/2026\/07\/FR-Injection-moulding.jpg","width":2400,"height":1260},{"@type":"BreadcrumbList","@id":"https:\/\/xometry.eu\/fr\/moulage-par-injection\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/xometry.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Injection plastique"}]},{"@type":"WebSite","@id":"https:\/\/xometry.eu\/fr\/#website","url":"https:\/\/xometry.eu\/fr\/","name":"Xometry Europe","description":"","publisher":{"@id":"https:\/\/xometry.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xometry.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/xometry.eu\/fr\/wp-json\/wp\/v2\/pages\/155638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xometry.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xometry.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xometry.eu\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/xometry.eu\/fr\/wp-json\/wp\/v2\/comments?post=155638"}],"version-history":[{"count":1,"href":"https:\/\/xometry.eu\/fr\/wp-json\/wp\/v2\/pages\/155638\/revisions"}],"predecessor-version":[{"id":184038,"href":"https:\/\/xometry.eu\/fr\/wp-json\/wp\/v2\/pages\/155638\/revisions\/184038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xometry.eu\/fr\/wp-json\/wp\/v2\/media\/183521"}],"wp:attachment":[{"href":"https:\/\/xometry.eu\/fr\/wp-json\/wp\/v2\/media?parent=155638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}